{"id":9807,"date":"2022-06-09T17:28:39","date_gmt":"2022-06-09T15:28:39","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9807"},"modified":"2022-06-06T17:30:56","modified_gmt":"2022-06-06T15:30:56","slug":"prelievo-anticipato-dalla-cassa-pensione-2-pilastro","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/prelievo-anticipato-dalla-cassa-pensione-2-pilastro\/","title":{"rendered":"Prelievo anticipato dalla cassa pensione (2\u00b0 pilastro)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">In linea di principio, il 2\u00b0\npilastro, ossia il fondo pensione, serve a provvedere alla vecchiaia. In\ndeterminate circostanze, tuttavia, \u00e8 possibile ritirare gli averi del fondo\npensione prima del raggiungimento dell&#8217;et\u00e0 pensionabile ordinaria. In questo\ncontesto, l&#8217;acquisto di un&#8217;abitazione propria (acquisto di un immobile ad uso\nabitativo), l&#8217;abbandono definitivo della Svizzera (emigrazione) e l&#8217;avvio di\nun&#8217;attivit\u00e0 lavorativa autonoma sono motivi che rendono possibile il prelievo\nanticipato degli averi della cassa pensione.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"6720\" height=\"4480\" data-attachment-id=\"9808\" data-permalink=\"https:\/\/blog.startups.ch\/it\/prelievo-anticipato-dalla-cassa-pensione-2-pilastro\/pexels-karolina-grabowska-4968362\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?fit=6720%2C4480&amp;ssl=1\" data-orig-size=\"6720,4480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pexels-karolina-grabowska-4968362\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?fit=1200%2C800&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?fit=1200%2C800&amp;ssl=1\" alt=\"Prelievo anticipato dalla cassa pensione (2\u00b0 pilastro)\" class=\"wp-image-9808\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?w=6720&amp;ssl=1 6720w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/06\/pexels-karolina-grabowska-4968362.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ritiro dal 2\u00b0 pilastro a causa di un&#8217;attivit\u00e0 autonoma<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gli averi del 2\u00b0 pilastro possono essere ritirati da persone che non hanno\nl&#8217;obbligo di aderire alla previdenza professionale. Da un lato, ci\u00f2 riguarda i\ntitolari di una ditta individuale e i soci accomandatari.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Iscrizione nel registro di commercio<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il primo passo \u00e8 l\u2019iscrizione della societ\u00e0 nel registro di commercio.\nSebbene la registrazione sia obbligatoria solo per le imprese individuali con\nun fatturato annuo pari o superiore a 100.000 franchi svizzeri, essa \u00e8\nconsigliata in ogni caso in relazione al percepimento delle prestazioni della\ncassa pensione. Da un lato, l&#8217;iscrizione nel registro pu\u00f2 accelerare il\nriconoscimento da parte del fondo di compensazione, e, dall&#8217;altro, l&#8217;effetto di\ntrasparenza dell&#8217;iscrizione nel registro di commercio pu\u00f2 lasciare\nun&#8217;impressione di professionalit\u00e0 ai partner contrattuali e ai clienti.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Registrazione presso la cassa di compensazione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il secondo passo consiste nel registrarsi presso la cassa di compensazione\nper ottenere il riconoscimento di lavoratore autonomo. \u00c8 importante che la\ndocumentazione per la cassa di compensazione sia completa. Oltre al modulo di\nregistrazione compilato, la cassa di compensazione deve ricevere un estratto\ndel registro di commercio imprese e almeno tre fatture inviate a tre clienti\ndiversi. A seconda dell&#8217;attivit\u00e0, possono essere richiesti ulteriori documenti\ndi supporto.&nbsp; \u00c8 quindi importante notare\nche gli investimenti iniziali per l&#8217;avvio dell&#8217;attivit\u00e0 non possono essere\nfinanziati dai fondi pensione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Richiedere il prelievo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In un&#8217;ultima fase, \u00e8 necessario richiedere il prelievo dei fondi della\ncassa pensione all&#8217;istituto di previdenza competente (cassa pensione) e\npresentare le conferme delle prime due fasi (estratto del registro di commercio\ne conferma della cassa di compensazione). A seconda del fondo pensione, possono\nessere aggiunti ulteriori requisiti (ad esempio, un piano aziendale).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da un punto di vista temporale, va notato che il ritiro anticipato del\ncapitale deve essere effettuato entro un anno dall&#8217;inizio dell&#8217;attivit\u00e0 di\nlavoro autonomo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nessun ritiro del 2\u00b0 pilastro con SA\/Sagl<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">D&#8217;altra parte, non \u00e8 possibile ritirare il patrimonio del fondo pensione\nquando si fonda una Sagl o una SA. Il motivo \u00e8 che il fondatore di una societ\u00e0\na responsabilit\u00e0 limitata (Sagl o SA) non pu\u00f2 essere considerato un lavoratore\nautonomo ai sensi della legge sulle assicurazioni sociali. \u00c8 piuttosto\nconsiderato un dipendente della propria azienda ed \u00e8 quindi soggetto\nall&#8217;assicurazione pensionistica professionale obbligatoria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conclusione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Per poter percepire anticipatamente le prestazioni della cassa pensione, \u00e8\nnecessario essere riconosciuti come lavoratori autonomi dalla cassa di\ncompensazione cantonale competente. Pu\u00f2 trattarsi del titolare di una ditta\nindividuale o di un socio accomandatario. A tal fine \u00e8 necessaria una prova da\nparte della cassa di compensazione e, idealmente, un&#8217;iscrizione nel registro di\ncommercio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Mompreneur: <a href=\"http:\/\/www.mom-preneur.ch\">www.mom-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Dadpreneur: <a href=\"http:\/\/www.dad-preneur.ch\">www.dad-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Seniorpreneur: <a href=\"http:\/\/www.senior-preneur.ch\">www.senior-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Youngpreneur: <a href=\"http:\/\/www.young-preneur.ch\">www.young-preneur.ch<\/a> <\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fprelievo-anticipato-dalla-cassa-pensione-2-pilastro%2F';\n  addthis_title  = 'Prelievo+anticipato+dalla+cassa+pensione+%282%C2%B0+pilastro%29';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>In linea di principio, il 2\u00b0 pilastro, ossia il fondo pensione, serve a provvedere alla vecchiaia. In determinate circostanze, tuttavia, \u00e8 possibile ritirare gli averi del fondo pensione prima del raggiungimento dell&#8217;et\u00e0 pensionabile ordinaria. In questo contesto, l&#8217;acquisto di un&#8217;abitazione propria (acquisto di un immobile ad uso abitativo), l&#8217;abbandono definitivo della Svizzera (emigrazione) e l&#8217;avvio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1647],"tags":[415],"class_list":["post-9807","post","type-post","status-publish","format-standard","hentry","category-diritto-societario","tag-cassa-pensioni"],"jetpack_publicize_connections":[],"views":1254,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2yb","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9807"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9807\/revisions"}],"predecessor-version":[{"id":9809,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9807\/revisions\/9809"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}