{"id":9778,"date":"2022-04-28T09:53:54","date_gmt":"2022-04-28T07:53:54","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9778"},"modified":"2022-04-26T10:01:51","modified_gmt":"2022-04-26T08:01:51","slug":"aida","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/aida\/","title":{"rendered":"AIDA: le quattro condizioni per una pubblicit\u00e0 efficace"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">AIDA \u00e8 l\u2019acronimo per Attention, Interest, Desire e Action, ossia un\nmodello di marketing che indica le quattro condizioni fondamentali affinch\u00e9 una\npubblicit\u00e0 sia davvero efficace. In particolare,&nbsp;<strong>A<\/strong><strong>IDA<\/strong> indica le fasi attraverso cui il consumatore passa\ndalla conoscenza del brand allo svolgimento di un\u2019azione quale l\u2019acquisto di un\nprodotto o la richiesta di informazioni. Scopriamo insieme quali.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"4288\" height=\"2848\" data-attachment-id=\"9779\" data-permalink=\"https:\/\/blog.startups.ch\/it\/aida\/pexels-jose-francisco-fernandez-saura-802024\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?fit=4288%2C2848&amp;ssl=1\" data-orig-size=\"4288,2848\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pexels-jose-francisco-fernandez-saura-802024\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?fit=1200%2C797&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?fit=1200%2C797&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?fit=1200%2C797&amp;ssl=1\" alt=\"AIDA: le quattro condizioni per una pubblicit\u00e0 efficace\" class=\"wp-image-9779\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?w=4288&amp;ssl=1 4288w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?resize=1200%2C797&amp;ssl=1 1200w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/04\/pexels-jose-francisco-fernandez-saura-802024.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">A: Attention<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una pubblicit\u00e0\ndeve per prima cosa attirare l\u2019attenzione di un potenziale consumatore, una\nmissione non del tutto scontata: infatti, ogni giorno, una persona viene letteralmente\nbombardata da migliaia di input e informazioni, che per la maggior parte del\ntempo ignora. Occorre quindi essere davvero molto creativi, utilizzando un\nmessaggio chiaro e comprensivo, per riuscire a distinguersi dalla massa ed\nessere quindi percepiti dal consumatore. In questo senso, la teoria identifica\npi\u00f9 misure possibili: comunicare in modo emotivo, fornire informazioni nuove, provocare\no utilizzare riferimenti sessuali, fare leva su elementi grafici accattivanti, utilizzare\nelementi audio con volume diverso rispetto ai programmi trasmessi, stimoli\nolfattivi oppure ricorrere a elementi che riportino il cliente alla sua\ninfanzia o facendo leva sull\u2019effetto nostalgia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I: Interest<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo aver\nattirato l\u2019attenzione del consumatore, lo step successivo \u00e8 quello di\nmanifestare in lui un interesse attivo nel prodotto. Per fare ci\u00f2, occorre riuscire a farsi leggere, farsi\nguardare e riguardare. In questo caso, attraverso la ricerca di informazioni i\nconsumatori vengono a conoscenza delle qualit\u00e0 e delle caratteristiche del\nprodotto e maturano un atteggiamento favorevole nei confronti del prodotto\nmedesimo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">D: Desire<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nella terza\nfase del modello AIDA, il consumatore esprime una preferenza e dimostra una\nconcreta intenzione di acquistare il prodotto. Il ruolo della pubblicit\u00e0 in\nquesta fase \u00e8 quello di accentuare i pregi del proprio prodotto rispetto a\nquelli dei prodotti simili della concorrenza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A: Action<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Per essere\ndavvero efficace, lo scopo ultimo di una pubblicit\u00e0 \u00e8 quella di condurre il\nconsumatore ad una azione, ossia concretizzare l\u2019acquisto del prodotto o\nservizio. Il messaggio pubblicitario deve infatti indurre a fare qualcosa, a\ncomprare, ossia deve contenere una call to action. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I limiti del modello<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Essendo un modello introdotto e sviluppato agli inizi del secolo scorso, l\u2019AIDA presenta dei limiti. In particolare, il modello non tiene conto di tutti gli aspetti legati alla gestione della reputazione di un marchio, come ad esempio il grado di soddisfazione del pubblico rispetto ai prodotti\/servizi, Consigli e recensioni degli utenti, fedelt\u00e0 al brand. Nonostante ci\u00f2, vista la sua facilit\u00e0 e la rapida applicabilit\u00e0, il modello AIDA rimane oggi uno dei pi\u00f9 usati quando si deve valutare l\u2019efficacia di una pubblicit\u00e0 nel suo complesso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Mompreneur: <a href=\"http:\/\/www.mom-preneur.ch\">www.mom-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Dadpreneur: <a href=\"http:\/\/www.dad-preneur.ch\">www.dad-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Seniorpreneur: <a href=\"http:\/\/www.senior-preneur.ch\">www.senior-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Youngpreneur: <a href=\"http:\/\/www.young-preneur.ch\">www.young-preneur.ch<\/a> <\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Faida%2F';\n  addthis_title  = 'AIDA%3A+le+quattro+condizioni+per+una+pubblicit%C3%A0+efficace';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>AIDA \u00e8 l\u2019acronimo per Attention, Interest, Desire e Action, ossia un modello di marketing che indica le quattro condizioni fondamentali affinch\u00e9 una pubblicit\u00e0 sia davvero efficace. In particolare,&nbsp;AIDA indica le fasi attraverso cui il consumatore passa dalla conoscenza del brand allo svolgimento di un\u2019azione quale l\u2019acquisto di un prodotto o la richiesta di informazioni. Scopriamo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1577],"tags":[1687,1688],"class_list":["post-9778","post","type-post","status-publish","format-standard","hentry","category-marketing","tag-aida","tag-comunicazione"],"jetpack_publicize_connections":[],"views":775,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s7ydF5-aida","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9778"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9778\/revisions"}],"predecessor-version":[{"id":9781,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9778\/revisions\/9781"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}