{"id":9634,"date":"2022-03-05T14:04:53","date_gmt":"2022-03-05T13:04:53","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9634"},"modified":"2022-03-05T14:05:59","modified_gmt":"2022-03-05T13:05:59","slug":"rapporto-sulle-costituzioni-febbraio-2022-cifre-ancora-molto-forti","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/rapporto-sulle-costituzioni-febbraio-2022-cifre-ancora-molto-forti\/","title":{"rendered":"Rapporto sulle costituzioni febbraio 2022: cifre ancora molto forti"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nel febbraio 2022, 4.222 aziende sono state fondate in Svizzera. Anche se questo rappresenta un calo del -3,74% rispetto a febbraio 2021, il numero di nuove costituzioni \u00e8 aumentato del +10,76% rispetto a gennaio 2022.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" data-attachment-id=\"9635\" data-permalink=\"https:\/\/blog.startups.ch\/it\/rapporto-sulle-costituzioni-febbraio-2022-cifre-ancora-molto-forti\/gb_it-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/03\/GB_IT-1.png?fit=940%2C788&amp;ssl=1\" data-orig-size=\"940,788\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GB_IT (1)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/03\/GB_IT-1.png?fit=940%2C788&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/03\/GB_IT-1.png?fit=940%2C788&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2022\/03\/GB_IT-1.png?resize=940%2C788&#038;ssl=1\" alt=\"Rapporto sulle costituzioni febbraio 2022\" class=\"wp-image-9635\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ottimo inizio per il 2022<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con un totale di 4&#8217;222 nuove imprese in tutta la Svizzera,\nfebbraio 2022 \u00e8 il secondo febbraio con il numero di costituzioni pi\u00f9 alto da\nquando STARTUPS.CH pubblica rapporti mensili. Il precedente record di 4.386 nuove\nformazioni era stato stabilito nel febbraio 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nonostante un calo del -3,74% rispetto a febbraio 2021, \u00e8\nstata registrata una crescita del +10,76% rispetto al mese precedente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solo la Svizzera nordoccidentale ha registrato un calo rispetto al mese precedente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Svizzera nordoccidentale \u00e8 l&#8217;unica regione che ha\nregistrato una diminuzione (-5,64%) delle formazioni di imprese rispetto al\ngennaio 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con 108 nuove imprese fondate sia in gennaio che in\nfebbraio, Basilea Campagna \u00e8 l&#8217;unico cantone della regione della Svizzera\nnord-occidentale a non essere in rosso. D&#8217;altra parte, i cantoni di Berna (-1,76%),\nArgovia (-9,38%), Soletta (-4,63%) e Basilea Citt\u00e0 (-15,6%) hanno registrato\ncifre di costituzione in calo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situazione \u00e8 molto diversa nelle altre regioni svizzere.\nIl Ticino \u00e8 la regione con l&#8217;aumento pi\u00f9 forte (+29,29%) rispetto al gennaio\n2022, seguito dalla Svizzera occidentale con +20,3% di fondazioni di imprese in\npi\u00f9. La Svizzera centrale e orientale sono entrambe al terzo posto (+15,5%).\nZurigo occupa il quarto posto con +7,89% di formazioni di imprese in pi\u00f9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Risultati misti rispetto all&#8217;anno precedente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Rispetto al febbraio 2022, la met\u00e0 delle regioni svizzere ha\nvisto un calo delle costituzioni. La regione della Svizzera nord-occidentale \u00e8\nstata di nuovo la pi\u00f9 colpita (-18,46%). Nella Svizzera occidentale, il numero\ndi nuove imprese \u00e8 sceso del -4,56%. Il Ticino ha registrato un piccolissimo\ncalo del -0,55%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Svizzera orientale \u00e8 la regione svizzera che ha\nregistrato l&#8217;aumento pi\u00f9 forte rispetto al febbraio 2021. Nella Svizzera\ncentrale, il numero di nuove imprese \u00e8 aumentato del +3,95% e nella regione di\nZurigo del +1,73%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Mompreneur: <a href=\"http:\/\/www.mom-preneur.ch\">www.mom-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Dadpreneur: <a href=\"http:\/\/www.dad-preneur.ch\">www.dad-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Seniorpreneur: <a href=\"http:\/\/www.senior-preneur.ch\">www.senior-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Youngpreneur: <a href=\"http:\/\/www.young-preneur.ch\">www.young-preneur.ch<\/a> <\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/blog\/category\/costituzione\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Altri rapporti sulle costituzioni<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Frapporto-sulle-costituzioni-febbraio-2022-cifre-ancora-molto-forti%2F';\n  addthis_title  = 'Rapporto+sulle+costituzioni+febbraio+2022%3A+cifre+ancora+molto+forti';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nel febbraio 2022, 4.222 aziende sono state fondate in Svizzera. Anche se questo rappresenta un calo del -3,74% rispetto a febbraio 2021, il numero di nuove costituzioni \u00e8 aumentato del +10,76% rispetto a gennaio 2022. Ottimo inizio per il 2022 Con un totale di 4&#8217;222 nuove imprese in tutta la Svizzera, febbraio 2022 \u00e8 il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24],"tags":[1335],"class_list":["post-9634","post","type-post","status-publish","format-standard","hentry","category-costituzione","tag-rapporto-sulle-costituzioni"],"jetpack_publicize_connections":[],"views":699,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2vo","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9634"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9634\/revisions"}],"predecessor-version":[{"id":9636,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9634\/revisions\/9636"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}