{"id":9526,"date":"2021-11-01T11:30:54","date_gmt":"2021-11-01T10:30:54","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9526"},"modified":"2021-11-01T11:58:03","modified_gmt":"2021-11-01T10:58:03","slug":"rapporto-sulle-costituzioni-ottobre-2021-le-cifre-di-costituzioni-rimangono-ad-un-livello-stabile","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/rapporto-sulle-costituzioni-ottobre-2021-le-cifre-di-costituzioni-rimangono-ad-un-livello-stabile\/","title":{"rendered":"Rapporto sulle costituzioni ottobre 2021: le cifre di costituzione rimangono ad un livello stabile"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nell&#8217;ottobre 2021, 3694 aziende sono\nstate fondate in Svizzera. Mentre il numero di costituzioni \u00e8 aumentato\ndell&#8217;1,74% rispetto a settembre 2021, sono diminuite del 6,62% rispetto a\nottobre 2020.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" data-attachment-id=\"9527\" data-permalink=\"https:\/\/blog.startups.ch\/it\/rapporto-sulle-costituzioni-ottobre-2021-le-cifre-di-costituzioni-rimangono-ad-un-livello-stabile\/it-okt21-die-entwicklung-im-zeitlichen-verlauf-handelsregistereintragungen\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/11\/IT-Okt21-Die-Entwicklung-im-zeitlichen-Verlauf-Handelsregistereintragungen.png?fit=940%2C788&amp;ssl=1\" data-orig-size=\"940,788\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IT &amp;#8211; Okt21 &amp;#8211; Die Entwicklung im zeitlichen Verlauf &amp;#8211; Handelsregistereintragungen\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/11\/IT-Okt21-Die-Entwicklung-im-zeitlichen-Verlauf-Handelsregistereintragungen.png?fit=940%2C788&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/11\/IT-Okt21-Die-Entwicklung-im-zeitlichen-Verlauf-Handelsregistereintragungen.png?fit=940%2C788&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/11\/IT-Okt21-Die-Entwicklung-im-zeitlichen-Verlauf-Handelsregistereintragungen.png?resize=940%2C788&#038;ssl=1\" alt=\"Rapporto sulle costituzioni ottobre 2021\" class=\"wp-image-9527\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Quasi nessun cambiamento nelle cifre di costituzione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un totale di 3694\naziende sono state fondate in Svizzera nell&#8217;ottobre 2021. Rispetto a settembre\n2021, sono state registrate 63 costituzioni in pi\u00f9 (+1,74%). Al contrario, il\nnumero di nuove aziende \u00e8 sceso di 262 (-6,62%) rispetto a ottobre 2020. La\nsituazione \u00e8 simile nelle tre regioni linguistiche. Mentre il numero di nuove\naziende nella Svizzera tedesca (+46 costituzioni o +1,93%) e in Ticino (+25 costituzioni\no +16,03) \u00e8 aumentato rispetto al mese precedente, le costituzioni nella\nSvizzera francese sono leggermente diminuite (-8 o -0,73%). Rispetto all&#8217;anno\nprecedente, il numero di costituzioni \u00e8 diminuito nella Svizzera tedesca (-188 costituzioni\no -7,18%), nella Svizzera francese (-64 costituzioni o -5,57%) e anche in\nTicino (-10 costituzioni o -5,24%).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Appenzello Esterno registra il maggior aumento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sebbene nell&#8217;ottobre\n2021 sia stato fondato un numero di imprese complessivamente simile a quello\ndel settembre 2021, le cifre di fondazione nei singoli cantoni sono cambiate\nrispetto al mese precedente. Tra i cantoni con il maggior numero di costituzioni,\ni cantoni Argovia (+4 costituzioni o +1,69%), Ginevra (+32 costituzioni o\n+10,77%), San Gallo (+24 costituzioni o 12,12%), Ticino (+25 costituzioni o\n+16,03%), Zugo (+51 costituzioni o +27,42%) e Zurigo (+25 costituzioni o\n+4,07%) hanno registrato un aumento. Al contrario, il numero di nuove aziende \u00e8\ndiminuito nei cantoni di Berna (-6 costituzioni o -2,07%), Lucerna (-30 costituzioni\no -16,13%) e Vaud (-40 costituzioni o -10,47%). Il pi\u00f9 grande aumento relativo\n\u00e8 nel cantone di Appenzello Esterno (+7 costituzioni o -38,89%).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Obvaldo con la maggiore diminuzione rispetto all&#8217;anno precedente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La maggior parte dei\ncantoni non ha raggiunto le cifre di costituzioni dell&#8217;ottobre 2020. Per\nesempio, il numero di nuove aziende \u00e8 diminuito nei cantoni di Argovia (-3 costituzioni\no -1,23%), Berna (-25 costituzioni o -8,09%), Ginevra (-29 costituzioni o\n-8,10%), Lucerna (-20 costituzioni o -11,36%), Ticino (-10 costituzioni o\n-5,24%), Vaud (-64 costituzioni o -15,76%) e Zurigo (-51 costituzioni o\n-7,39%). Tra i cantoni con una forte attivit\u00e0 imprenditoriale, solo i cantoni\ndi San Gallo (+26 costituzioni o +13,27%) e Zugo (+25 costituzioni o +11,79%) hanno\nfatto registrare un aumento. Il pi\u00f9 grande aumento relativo \u00e8 nel cantone di\nUri (+6 costituzioni o +85,71%). Al contrario, Obvaldo \u00e8 il cantone\nmaggiormente interessato dalla diminuzione relativamente pi\u00f9 forte (-11 costituzioni\no -64,71%).<\/p>\n\n\n\n<table class=\"wp-block-table\"><tbody><tr><td>\n  &nbsp;\n  <\/td><td>\n  <strong>Variazione\n  rispetto al mese precedente (assoluta)<\/strong>\n  <\/td><td>\n  <strong>Variazione\n  rispetto al mese dell&#8217;anno precedente<\/strong>\n  <\/td><td>\n  <strong>Variazione\n  rispetto al mese precedente (relativa)<\/strong>\n  <\/td><td>\n  <strong>Variazione\n  rispetto al mese dell&#8217;anno precedente (relativa)<\/strong>\n  <\/td><\/tr><tr><td>\n  AG\n  <\/td><td>\n  4\n  <\/td><td>\n  -3\n  <\/td><td>\n  1.69%\n  <\/td><td>\n  -1.23%\n  <\/td><\/tr><tr><td>\n  AI\n  <\/td><td>\n  3\n  <\/td><td>\n  -3\n  <\/td><td>\n  33.33%\n  <\/td><td>\n  -20.00%\n  <\/td><\/tr><tr><td>\n  AR\n  <\/td><td>\n  7\n  <\/td><td>\n  -4\n  <\/td><td>\n  38.889%\n  <\/td><td>\n  -13.79%\n  <\/td><\/tr><tr><td>\n  BE\n  <\/td><td>\n  -6\n  <\/td><td>\n  -25\n  <\/td><td>\n  -2.07%\n  <\/td><td>\n  -8.09%\n  <\/td><\/tr><tr><td>\n  BL\n  <\/td><td>\n  -9\n  <\/td><td>\n  -34\n  <\/td><td>\n  -9.18%\n  <\/td><td>\n  -27.64%\n  <\/td><\/tr><tr><td>\n  BS\n  <\/td><td>\n  10\n  <\/td><td>\n  4\n  <\/td><td>\n  10.53%\n  <\/td><td>\n  3.96%\n  <\/td><\/tr><tr><td>\n  FR\n  <\/td><td>\n  -15\n  <\/td><td>\n  -12\n  <\/td><td>\n  -10.64%\n  <\/td><td>\n  -8.70%\n  <\/td><\/tr><tr><td>\n  GE\n  <\/td><td>\n  32\n  <\/td><td>\n  -29\n  <\/td><td>\n  10.77%\n  <\/td><td>\n  -8.10%\n  <\/td><\/tr><tr><td>\n  GL\n  <\/td><td>\n  -7\n  <\/td><td>\n  -3\n  <\/td><td>\n  -38.89%\n  <\/td><td>\n  -21.43%\n  <\/td><\/tr><tr><td>\n  GR\n  <\/td><td>\n  10\n  <\/td><td>\n  -19\n  <\/td><td>\n  16.39%\n  <\/td><td>\n  -21.11%\n  <\/td><\/tr><tr><td>\n  JU\n  <\/td><td>\n  0\n  <\/td><td>\n  5\n  <\/td><td>\n  0.00%\n  <\/td><td>\n  17.86%\n  <\/td><\/tr><tr><td>\n  LU\n  <\/td><td>\n  -30\n  <\/td><td>\n  -20\n  <\/td><td>\n  -16.13%\n  <\/td><td>\n  -11.36%\n  <\/td><\/tr><tr><td>\n  NE\n  <\/td><td>\n  5\n  <\/td><td>\n  13\n  <\/td><td>\n  8.47%\n  <\/td><td>\n  25.49%\n  <\/td><\/tr><tr><td>\n  NW\n  <\/td><td>\n  -4\n  <\/td><td>\n  -17\n  <\/td><td>\n  -21.053%\n  <\/td><td>\n  -53.13%\n  <\/td><\/tr><tr><td>\n  OW\n  <\/td><td>\n  -11\n  <\/td><td>\n  -11\n  <\/td><td>\n  -64.71%\n  <\/td><td>\n  -64.71%\n  <\/td><\/tr><tr><td>\n  SG\n  <\/td><td>\n  24\n  <\/td><td>\n  26\n  <\/td><td>\n  12.12%\n  <\/td><td>\n  13.27%\n  <\/td><\/tr><tr><td>\n  SH\n  <\/td><td>\n  -11\n  <\/td><td>\n  -4\n  <\/td><td>\n  -34.38%\n  <\/td><td>\n  -16.00%\n  <\/td><\/tr><tr><td>\n  SO\n  <\/td><td>\n  13\n  <\/td><td>\n  1\n  <\/td><td>\n  15.12%\n  <\/td><td>\n  1.02%\n  <\/td><\/tr><tr><td>\n  SZ\n  <\/td><td>\n  -20\n  <\/td><td>\n  -38\n  <\/td><td>\n  -18.18%\n  <\/td><td>\n  -29.69%\n  <\/td><\/tr><tr><td>\n  TG\n  <\/td><td>\n  -5\n  <\/td><td>\n  -18\n  <\/td><td>\n  -5.10%\n  <\/td><td>\n  -16.22%\n  <\/td><\/tr><tr><td>\n  TI\n  <\/td><td>\n  25\n  <\/td><td>\n  -10\n  <\/td><td>\n  16.03%\n  <\/td><td>\n  -5.24%\n  <\/td><\/tr><tr><td>\n  UR\n  <\/td><td>\n  2\n  <\/td><td>\n  6\n  <\/td><td>\n  18.18%\n  <\/td><td>\n  85.71%\n  <\/td><\/tr><tr><td>\n  VD\n  <\/td><td>\n  -40\n  <\/td><td>\n  -64\n  <\/td><td>\n  -10.47%\n  <\/td><td>\n  -15.76%\n  <\/td><\/tr><tr><td>\n  VS\n  <\/td><td>\n  10\n  <\/td><td>\n  23\n  <\/td><td>\n  5.56%\n  <\/td><td>\n  13.77%\n  <\/td><\/tr><tr><td>\n  ZG\n  <\/td><td>\n  51\n  <\/td><td>\n  25\n  <\/td><td>\n  27.42%\n  <\/td><td>\n  11.79%\n  <\/td><\/tr><tr><td>\n  ZH\n  <\/td><td>\n  25\n  <\/td><td>\n  -51\n  <\/td><td>\n  4.07%\n  <\/td><td>\n  -7.39%\n  <\/td><\/tr><tr><td>\n  <strong>CH<\/strong>\n  <\/td><td>\n  <strong>63<\/strong>\n  <\/td><td>\n  <strong>-262<\/strong>\n  <\/td><td>\n  <strong>1.74%<\/strong>\n  <\/td><td>\n  <strong>-6.62%<\/strong>\n  <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea\ninnovativa che vorreste implementare? Gli esperti di STARTUPS.CH saranno lieti\ndi accompagnarvi verso l\u2019indipendenza professionale!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nMompreneur: <a href=\"http:\/\/www.mom-preneur.ch\">www.mom-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nDadpreneur: <a href=\"http:\/\/www.dad-preneur.ch\">www.dad-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nSeniorpreneur: <a href=\"http:\/\/www.senior-preneur.ch\">www.senior-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nYoungpreneur: <a href=\"http:\/\/www.young-preneur.ch\">www.young-preneur.ch<\/a> <\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/blog\/category\/costituzione\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Altri rapporti sulle costituzioni<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Frapporto-sulle-costituzioni-ottobre-2021-le-cifre-di-costituzioni-rimangono-ad-un-livello-stabile%2F';\n  addthis_title  = 'Rapporto+sulle+costituzioni+ottobre+2021%3A+le+cifre+di+costituzione+rimangono+ad+un+livello+stabile';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;ottobre 2021, 3694 aziende sono state fondate in Svizzera. Mentre il numero di costituzioni \u00e8 aumentato dell&#8217;1,74% rispetto a settembre 2021, sono diminuite del 6,62% rispetto a ottobre 2020. Quasi nessun cambiamento nelle cifre di costituzione Un totale di 3694 aziende sono state fondate in Svizzera nell&#8217;ottobre 2021. Rispetto a settembre 2021, sono state registrate [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24],"tags":[198],"class_list":["post-9526","post","type-post","status-publish","format-standard","hentry","category-costituzione","tag-rapporto-dimpiego"],"jetpack_publicize_connections":[],"views":736,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2tE","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9526"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9526\/revisions"}],"predecessor-version":[{"id":9529,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9526\/revisions\/9529"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}