{"id":9366,"date":"2021-06-10T09:14:22","date_gmt":"2021-06-10T07:14:22","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9366"},"modified":"2021-06-07T12:16:32","modified_gmt":"2021-06-07T10:16:32","slug":"il-futuro-del-lavoro-intervista-con-raphael-jaeger-di-deskbird","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/il-futuro-del-lavoro-intervista-con-raphael-jaeger-di-deskbird\/","title":{"rendered":"Il futuro del lavoro: intervista con Raphael Jaeger di deskbird"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La\nstartup svizzera deskbird ha sviluppato un&#8217;app che permette a chiunque di\nprenotare uno spazio di lavoro in uno spazio di coworking in modo facile e\nveloce. STARTUPS.CH ha parlato con Raphael Jaeger, avvocato e presidente del\nconsiglio di amministrazione di deskbird, delle sfide della fondazione di una\nstartup e del futuro dei modelli di lavoro ibridi. <\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"642\" height=\"358\" data-attachment-id=\"9367\" data-permalink=\"https:\/\/blog.startups.ch\/it\/il-futuro-del-lavoro-intervista-con-raphael-jaeger-di-deskbird\/desj\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/06\/desj.png?fit=642%2C358&amp;ssl=1\" data-orig-size=\"642,358\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"desj\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/06\/desj.png?fit=642%2C358&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/06\/desj.png?fit=642%2C358&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/06\/desj.png?resize=642%2C358&#038;ssl=1\" alt=\"deskbird\" class=\"wp-image-9367\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La startup deskbird AG, con sede a San Gallo, \u00e8\nstata fondata nell&#8217;agosto 2020 e poco dopo ha lanciato l&#8217;app mobile deskbird,\nche permette agli utenti di prenotare spazi di lavoro in oltre 300 spazi di\ncoworking europei. Nel frattempo, l&#8217;azienda ha ampliato la sua offerta con una\nsoluzione software che permette alle aziende di sfruttare tutto il potenziale\ndegli uffici ibridi. I dipendenti dei clienti aziendali hanno la possibilit\u00e0 di\npianificare i loro giorni di home office, riservare uno spazio di lavoro in\nufficio e fare rete con i colleghi con pochi clic.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Startup con grandi ambizioni<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La visione della giovane azienda \u00e8 quella di\ncontribuire a plasmare il nuovo mondo del lavoro e diventare la piattaforma\nleader per gli spazi di lavoro flessibili in Europa entro il 2025. STARTUPS.CH\nha parlato con Raphael Jaeger, avvocato e presidente del consiglio di\namministrazione di deskbird, del mondo delle startup e del futuro degli spazi\ndi lavoro flessibili.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">STARTUP.CH: Come funziona il modello di business di deskbird?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Raphael Jaeger: A deskbird, offriamo soluzioni\ndi spazio di lavoro flessibile a clienti privati e aiutiamo a trovare lavoro. A\nquesto scopo, abbiamo lanciato un&#8217;applicazione che pu\u00f2 essere scaricata\ngratuitamente da App e Playstore. Gli utenti possono usare l&#8217;applicazione per\nconfrontare comodamente gli spazi di coworking nella loro zona e prenotare il\nloro spazio di lavoro perfetto. Per ogni prenotazione, deskbird riceve una\ncommissione. Recentemente abbiamo anche iniziato a offrire ai clienti aziendali\nla possibilit\u00e0 di creare posti di lavoro ibridi per i loro dipendenti. I\ndipendenti possono vedere quando i colleghi vanno in ufficio e pianificare la\nloro settimana di conseguenza. A seconda della domanda, \u00e8 possibile prenotare\npostazioni di lavoro cos\u00ec come sale riunioni e zone di incontro in ufficio o in\nuno spazio di coworking tramite l&#8217;app. Per questo servizio, deskbird fa pagare\nai clienti aziendali una piccola somma per dipendente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Da dove \u00e8 nata l&#8217;idea di deskbird?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">I due fondatori, Ivan Cossu (CEO) e Jonas Hess\n(CPO), hanno avuto l&#8217;idea di deskbird quando erano alla ricerca di uno spazio\ndi lavoro per un progetto. Mentre setacciavano internet per trovare un posto\nadatto, hanno notato quanto tempo richieda la ricerca di spazi di lavoro e il\nconfronto delle offerte. Hanno pensato che dovrebbe essere pi\u00f9 facile e hanno\nsviluppato l&#8217;applicazione deskbird. L&#8217;idea dell&#8217;opzione di prenotazione degli\nspazi di lavoro negli uffici aziendali \u00e8 nata da quasi un centinaio di\nconversazioni con le aziende. Si \u00e8 scoperto che soprattutto le grandi aziende\nhanno bisogno di una soluzione di gestione intelligente del posto di lavoro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come sar\u00e0 il futuro degli spazi di coworking?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tobi Lutke, CEO di Shopify, lo ha riassunto\nmolto bene: &#8220;La centralit\u00e0 dell&#8217;ufficio \u00e8 finita&#8221;. Soprattutto per le\ngrandi aziende, sta avvenendo un cambiamento. Noi di deskbird ci aspettiamo che\nil numero di uffici tradizionali diminuisca di almeno il 30% nei prossimi anni.\nChi vuole lavorare a un progetto da solo pu\u00f2 farlo a casa o in uno spazio di\ncoworking. Ci aspettiamo quindi che in futuro i dipendenti non si recheranno\npi\u00f9 ogni mattina alla loro scrivania, ma che gli uffici saranno sempre pi\u00f9\nutilizzati come zone di incontro. Questo creer\u00e0 una dinamica di lavoro\ncompletamente nuova. I modelli ibridi sono gi\u00e0 una realt\u00e0 oggi, soprattutto\nnelle aziende in rapida crescita. Altre aziende passeranno alla gestione\nflessibile del posto di lavoro nel prossimo futuro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come ha vissuto la crisi legata al coronavirus?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La startup deskbird \u00e8 stata fondata nell&#8217;agosto\n2020 e quindi nel mezzo della crisi legata al coronavirus. Io stesso sono stato\ncoinvolto fin dall&#8217;inizio come investitore principale e voce di supporto. La\nfondazione ai tempi della pandemia era abbastanza speciale. Invece di una sala\nriunioni, la fondazione ha avuto luogo nel St.Leonhard P\u00e4rklein a San Gallo.\nUna grande sfida, che abbiamo superato con successo, \u00e8 stata la ricerca di\ninvestitori senza la possibilit\u00e0 di incontri fisici. In generale, per\u00f2, la\ncrisi ha messo le ali ai modelli di lavoro ibridi e quindi anche al modello di\nbusiness di deskbird. Ci aspettiamo che gli spazi di lavoro flessibili siano\nmolto richiesti, soprattutto dopo la crisi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come sar\u00e0 il futuro di deskbird?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nel prossimo futuro, vogliamo certamente\nsviluppare ed espandere ulteriormente la nostra offerta. Attualmente siamo gi\u00e0\nin trattative con una vasta gamma di potenziali clienti. Un&#8217;offensiva di\nvendita \u00e8 anche prevista per l&#8217;estate. Poich\u00e9 molti spazi di lavoro sono stati\nchiusi a causa delle misure legate al coronavirus, abbiamo deliberatamente\ntrattenuto la pubblicit\u00e0 finora. Questo \u00e8 ora destinato a cambiare. Non solo il\npotenziale di crescita e di sviluppo del mercato, ma anche le nostre ambizioni\nsono grandi. Il nostro obiettivo dichiarato \u00e8 quello di diventare la principale\npiattaforma di lavoro in Europa. Per essere in grado di soddisfare le enormi\nesigenze dei clienti e per crescere ulteriormente, stiamo anche pianificando un\naumento di capitale per l&#8217;autunno di quest&#8217;anno. Attualmente stiamo cercando\ninvestitori per questo scopo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quali consigli ha per i fondatori di aziende?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Fate attenzione quando scegliete i partner!\nConviene scegliere con cura i propri partner commerciali. Raccomando ai\nfondatori di scegliere come partner qualcuno che completi le loro competenze e\ncolmi i loro deficit. \u00c8 importante per il successo che il team fondatore\nincluda gi\u00e0 persone che conoscono il business cos\u00ec come quelle che possono\nreferenziare investitori e clienti. Per le startup \u00e8 sicuramente vantaggioso\nportare a bordo qualcuno con esperienza e buoni contatti che ha anche\nfamiliarit\u00e0 con le sfide dei mercati in rapida crescita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Mompreneur: <a href=\"http:\/\/www.mom-preneur.ch\">www.mom-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Dadpreneur: <a href=\"http:\/\/www.dad-preneur.ch\">www.dad-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Seniorpreneur: <a href=\"http:\/\/www.senior-preneur.ch\">www.senior-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Youngpreneur: <a href=\"http:\/\/www.young-preneur.ch\">www.young-preneur.ch<\/a> <\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fil-futuro-del-lavoro-intervista-con-raphael-jaeger-di-deskbird%2F';\n  addthis_title  = 'Il+futuro+del+lavoro%3A+intervista+con+Raphael+Jaeger+di+deskbird';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La startup svizzera deskbird ha sviluppato un&#8217;app che permette a chiunque di prenotare uno spazio di lavoro in uno spazio di coworking in modo facile e veloce. STARTUPS.CH ha parlato con Raphael Jaeger, avvocato e presidente del consiglio di amministrazione di deskbird, delle sfide della fondazione di una startup e del futuro dei modelli di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1550],"tags":[1661,1656],"class_list":["post-9366","post","type-post","status-publish","format-standard","hentry","category-scenario-startup","tag-deskbird","tag-scenario-startup"],"jetpack_publicize_connections":[],"views":1020,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2r4","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9366"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9366\/revisions"}],"predecessor-version":[{"id":9368,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9366\/revisions\/9368"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}