{"id":9272,"date":"2021-04-12T09:11:15","date_gmt":"2021-04-12T07:11:15","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9272"},"modified":"2021-04-12T12:06:52","modified_gmt":"2021-04-12T10:06:52","slug":"perche-i-fondatori-di-successo-non-sono-sempre-buoni-manager","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/perche-i-fondatori-di-successo-non-sono-sempre-buoni-manager\/","title":{"rendered":"Perch\u00e9 i fondatori di successo non sono sempre buoni manager"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">I fondatori di successo si\ndistinguono dalla folla degli imprenditori per il loro spirito innovativo e la\nloro capacit\u00e0 di mettere in pratica nuove idee. Soprattutto quando il business\n\u00e8 gi\u00e0 in funzione da qualche anno e si parla per la prima volta di una entrata\nin borsa, tuttavia, diventa spesso chiaro che i fondatori di successo non sono\nsempre buoni manager.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"6000\" height=\"4000\" data-attachment-id=\"9273\" data-permalink=\"https:\/\/blog.startups.ch\/it\/perche-i-fondatori-di-successo-non-sono-sempre-buoni-manager\/pexels-sora-shimazaki-5668765\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?fit=6000%2C4000&amp;ssl=1\" data-orig-size=\"6000,4000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pexels-sora-shimazaki-5668765\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?fit=1200%2C800&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?fit=1200%2C800&amp;ssl=1\" alt=\"\" class=\"wp-image-9273\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?w=6000&amp;ssl=1 6000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/04\/pexels-sora-shimazaki-5668765.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Negli ultimi anni le nuove aziende sono spuntate come funghi. Soprattutto\nnel settore tecnologico, \u00e8 scoppiata la febbre delle startup. Tuttavia, una\nvolta che il business \u00e8 stato impostato e le prime vendite cominciano ad\narrivare, spesso diventa chiaro che non tutti i fondatori sono anche dei buoni\nmanager. Dopo tutto, le startup di solito devono essere gestite in modo diverso\ndalle aziende consolidate. Questa semplice intuizione ha implicazioni di vasta\nportata per i fondatori.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Diverse competenze di fondatori e manager<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mentre i fondatori costruiscono un&#8217;azienda da zero, i manager hanno il\ncompito di mantenere un&#8217;azienda esistente e aiutarla a crescere. Questi diversi\ncompiti richiedono competenze diverse da parte delle persone incaricate. Nelle\nprime fasi, un&#8217;idea di business deve essere messa in pratica sviluppando un\nprodotto e attirando dipendenti, fornitori e clienti. Oltre allo spirito\ninnovativo, ai fondatori d&#8217;azienda sono richieste anche capacit\u00e0 di\nnegoziazione e potere di persuasione. Una volta che un&#8217;azienda \u00e8 riuscita ad\naffermarsi sul mercato, il passo successivo \u00e8 quello di perfezionare lo status\nquo. Invece di prototipi, si devono progettare strategie e invece di prodotti,\nsi devono sviluppare piani di espansione. A differenza della fase di avvio,\ndove i risultati possono spesso essere visti dopo pochi giorni, spesso ci\nvogliono mesi o addirittura anni perch\u00e9 i cambiamenti diventino visibili nelle\nimprese consolidate. I manager devono quindi essere particolarmente pazienti.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cercare supporto in tempo utile<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cosa significano questi risultati per i fondatori di aziende? Siccome sono\nrichieste competenze e qualit\u00e0 diverse nelle diverse fasi dell&#8217;impresa, i\nfondatori dovrebbero considerare per tempo se vogliono assumere loro stessi le\nattivit\u00e0 di un manager o se preferiscono lasciarle a uno specialista.\nSoprattutto quando le decisioni non devono pi\u00f9 essere prese liberamente ma\ndevono essere coordinate con gli azionisti, \u00e8 arrivato il momento per molti\nfondatori di cercare il supporto di un manager. Ci sono alcune cose che gli\nimprenditori dovrebbero tenere a mente quando lo fanno. In primo luogo, \u00e8\nimportante che i fondatori abbiano gi\u00e0 un&#8217;idea di come loro e la loro azienda\nvogliono andare avanti. Vogliono rimanere in affari a lungo termine ed\nesternalizzare solo le attivit\u00e0 di gestione, o vogliono vendere l&#8217;azienda lungo\nla strada? A seconda della risposta a questa domanda, sono necessarie diverse\nstrategie di gestione. In secondo luogo, \u00e8 importante scegliere un manager che\nabbia familiarit\u00e0 con il settore in questione e che si adatti al team\nesistente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, spetta ai fondatori decidere se vogliono gestirlo da soli o\nassumere una terza parte per farlo. Anche se molti fondatori preferiscono\ninnovare e lasciare il calcolo dei numeri finanziari ad altri, ci sono anche\nmanager fondatori di successo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Mompreneur: <a href=\"http:\/\/www.mom-preneur.ch\">www.mom-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Dadpreneur: <a href=\"http:\/\/www.dad-preneur.ch\">www.dad-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Seniorpreneur: <a href=\"http:\/\/www.senior-preneur.ch\">www.senior-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Youngpreneur: <a href=\"http:\/\/www.young-preneur.ch\">www.young-preneur.ch<\/a> <\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fperche-i-fondatori-di-successo-non-sono-sempre-buoni-manager%2F';\n  addthis_title  = 'Perch%C3%A9+i+fondatori+di+successo+non+sono+sempre+buoni+manager';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>I fondatori di successo si distinguono dalla folla degli imprenditori per il loro spirito innovativo e la loro capacit\u00e0 di mettere in pratica nuove idee. Soprattutto quando il business \u00e8 gi\u00e0 in funzione da qualche anno e si parla per la prima volta di una entrata in borsa, tuttavia, diventa spesso chiaro che i fondatori [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[905,1588],"class_list":["post-9272","post","type-post","status-publish","format-standard","hentry","category-curiosita","tag-fondatore","tag-manager"],"jetpack_publicize_connections":[],"views":907,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2py","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9272"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9272\/revisions"}],"predecessor-version":[{"id":9274,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9272\/revisions\/9274"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}