{"id":9242,"date":"2021-03-15T08:32:33","date_gmt":"2021-03-15T07:32:33","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9242"},"modified":"2021-03-09T18:34:21","modified_gmt":"2021-03-09T17:34:21","slug":"lotta-alla-pirateria-online-da-parte-degli-hosting-provider","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/lotta-alla-pirateria-online-da-parte-degli-hosting-provider\/","title":{"rendered":"Lotta alla pirateria online da parte degli hosting provider"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Quando\nle persone caricano video e film illegalmente sulle piattaforme di streaming,\nnon solo violano i diritti dei creatori culturali, ma li danneggiano anche\nfinanziariamente. Rendendo responsabili gli hosting provider, l&#8217;obiettivo \u00e8\nquello di combattere la pirateria online e proteggere meglio i creatori.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" data-attachment-id=\"9243\" data-permalink=\"https:\/\/blog.startups.ch\/it\/lotta-alla-pirateria-online-da-parte-degli-hosting-provider\/programming-593312_1920\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/03\/programming-593312_1920.jpg?fit=1920%2C1280&amp;ssl=1\" data-orig-size=\"1920,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"programming-593312_1920\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/03\/programming-593312_1920.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/03\/programming-593312_1920.jpg?fit=1200%2C800&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/03\/programming-593312_1920.jpg?fit=1200%2C800&amp;ssl=1\" alt=\"\" class=\"wp-image-9243\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/03\/programming-593312_1920.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/03\/programming-593312_1920.jpg?resize=1200%2C800&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Quando piattaforme di streaming come kinox.to o Putlocker mettono a\ndisposizione del pubblico film e serie senza il consenso degli autori, violano\ni diritti dei creatori. Il problema qui \u00e8 che di solito non sono gli stessi\noperatori delle piattaforme a caricare le opere in violazione, ma terze parti. Ritendendo\ncomunque responsabili gli operatori delle piattaforme, la pirateria online potr\u00e0\nessere combattuta in modo pi\u00f9 efficace. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Codice di condotta di hosting<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;autoregolamentazione \u00e8 di grande importanza nella lotta contro la\nviolazione del copyright da parte dei servizi di streaming. Nella lotta contro\nla pirateria su Internet, i fornitori di hosting hanno unito le loro forze per\nprevenire i comportamenti illegali. In Svizzera, il Code of Conduct Hosting\n(CCH) \u00e8 stato emesso nel 2013 dall&#8217;Associazione svizzera per la tecnologia\ndell&#8217;informazione, della comunicazione e dell&#8217;organizzazione (swico) a questo\nscopo. Gli hosting provider svizzeri possono impegnarsi volontariamente a\nrispettare il CCH. Gli strumenti pi\u00f9 importanti previsti dal CCH sono\n&#8220;Notice and Notice&#8221; e &#8220;Notice and Take-Down&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Notice and Notice<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Secondo il sistema di notice and notice, qualcuno, di solito l&#8217;autore\nviolato, notifica ai fornitori di hosting l&#8217;uso illecito di un&#8217;opera. I\nfornitori della piattaforma, a loro volta, segnalano l&#8217;infrazione alla persona\nche ha caricato l&#8217;opera e le chiedono di rimuoverla o di spiegarsi. Inoltre, i\ncaricatori sono informati che sono tenuti a risarcire i reclami basati sulla\nviolazione. Questo ha lo scopo di motivare i trasgressori del copyright a\ncancellare da soli le opere pubblicate illegalmente. Se gli uploader non si\nconformano alla richiesta, tuttavia, questo non ha conseguenze immediate per\nloro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Notice and Take-Down<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nel caso notice and take-down, i fornitori di hosting sono anche informati\ndella violazione del copyright in un primo passo. A differenza del notice and notice,\ntuttavia, gli operatori delle piattaforme possono bloccare autonomamente\nl&#8217;accesso all&#8217;opera pubblicata illegalmente, a patto che siano soddisfatte\nalcune condizioni. Il problema di questo sistema \u00e8 che nessuno impedisce agli\nuploader di ricaricare l&#8217;opera protetta e di commettere ulteriori violazioni\ndel copyright. Ogni volta che un&#8217;opera viene ricaricata, il proprietario del\ncopyright interessato deve segnalarla di nuovo agli operatori della\npiattaforma. Questo pu\u00f2 essere estremamente costoso e dispendioso in termini di\ntempo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Notice and Stay-Down<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il metodo pi\u00f9 efficace per combattere la pirateria online \u00e8 il metodo\nnotice and stay-down previsto dall&#8217;art. 39d LDA. In base all&#8217;avviso e alla\nsospensione, i fornitori di hosting sono tenuti a prendere tutte le misure\neconomicamente e tecnicamente ragionevoli per prevenire la violazione del\ncopyright. Tuttavia, questo si applica solo se un&#8217;opera \u00e8 gi\u00e0 stata messa a\ndisposizione tramite il servizio di hosting, gli operatori sono stati messi al\ncorrente della violazione e il servizio di hosting in questione crea un rischio\nparticolare di tali violazioni. L&#8217;avviso e la sospensione sono destinati a\ndistruggere i modelli di business dei siti di hosting che sono principalmente\nfocalizzati sulla violazione del copyright.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Mompreneur: www.mom-preneur.ch<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Dadpreneur: www.dad-preneur.ch<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Seniorpreneur:\nwww.senior-preneur.ch<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Youngpreneur: www.young-preneur.ch<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Flotta-alla-pirateria-online-da-parte-degli-hosting-provider%2F';\n  addthis_title  = 'Lotta+alla+pirateria+online+da+parte+degli+hosting+provider';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Quando le persone caricano video e film illegalmente sulle piattaforme di streaming, non solo violano i diritti dei creatori culturali, ma li danneggiano anche finanziariamente. Rendendo responsabili gli hosting provider, l&#8217;obiettivo \u00e8 quello di combattere la pirateria online e proteggere meglio i creatori. Quando piattaforme di streaming come kinox.to o Putlocker mettono a disposizione del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[1640,1641],"class_list":["post-9242","post","type-post","status-publish","format-standard","hentry","category-curiosita","tag-copyright","tag-diritti-dautore"],"jetpack_publicize_connections":[],"views":903,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2p4","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9242"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9242\/revisions"}],"predecessor-version":[{"id":9244,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9242\/revisions\/9244"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}