{"id":9223,"date":"2021-03-01T09:41:35","date_gmt":"2021-03-01T08:41:35","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9223"},"modified":"2021-02-24T09:43:00","modified_gmt":"2021-02-24T08:43:00","slug":"21-milioni-di-franchi-svizzeri-per-la-startup-svizzera-mirai-foods","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/21-milioni-di-franchi-svizzeri-per-la-startup-svizzera-mirai-foods\/","title":{"rendered":"2,1 milioni di franchi svizzeri per la startup svizzera Mirai Foods"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La startup svizzera di clean\nmeat Mirai Foods ha ricevuto un finanziamento di 2,1 milioni di franchi\nsvizzeri per sviluppare carne senza OGM. <\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"642\" height=\"421\" data-attachment-id=\"9224\" data-permalink=\"https:\/\/blog.startups.ch\/it\/21-milioni-di-franchi-svizzeri-per-la-startup-svizzera-mirai-foods\/dsfdfg\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/02\/dsfdfg.png?fit=642%2C421&amp;ssl=1\" data-orig-size=\"642,421\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"dsfdfg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/02\/dsfdfg.png?fit=642%2C421&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/02\/dsfdfg.png?fit=642%2C421&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2021\/02\/dsfdfg.png?resize=642%2C421&#038;ssl=1\" alt=\"\" class=\"wp-image-9224\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">La startup di carne pulita Mirai Foods<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La startup\nsvizzera di clean meat Mirai Foods \u00e8 stata fondata a W\u00e4denswil nel 2019 e mira\na produrre e distribuire carne coltivata. La clean meat o carne coltivata \u00e8 la\ncarne che viene coltivata specificamente da cellule staminali. L&#8217;obiettivo\ndell&#8217;azienda \u00e8 quello di diventare leader nei prodotti di carne coltivata entro\nil 2030 e di ridurre la produzione di carne e la sua impronta ambientale\nattraverso i suoi prodotti. A differenza di altre aziende in questo campo,\nMirai Foods utilizza carne e cellule di grasso naturali e non utilizza\nl&#8217;ingegneria genetica nella produzione dei prodotti. Finora, Mirai Foods si \u00e8\nconcentrata sulla produzione di carne bovina. A lungo termine, tuttavia,\nprevede di offrire ai clienti una vasta gamma di prodotti di carne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2,1 milioni di franchi di finanziamento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Anche se la\nstartup Mirai Foods ha solo un anno di vita, si \u00e8 gi\u00e0 assicurata 2,1 milioni di\nfranchi svizzeri in un round di finanziamento iniziale. Tra gli investitori c&#8217;\u00e8\nl&#8217;azienda di alimenti e bevande Paulig Group, la quale, grazie all\u2019esperienza\nnel settore alimentare, pu\u00f2 assistere la giovane startup con lo sviluppo del\nprodotto. Tra gli investitori pure il gruppo tecnologico Team Europe, la cui\nmissione \u00e8 quella di creare un futuro pi\u00f9 pulito. In totale, sette investitori\nhanno partecipato al primo round di finanziamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte:\nhttps:\/\/www.miraifoods.com\/media<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea\ninnovativa che vorreste implementare? Gli esperti di STARTUPS.CH saranno lieti\ndi accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nMompreneur: www.mom-preneur.ch<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nDadpreneur: www.dad-preneur.ch<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nSeniorpreneur: www.senior-preneur.ch<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come\nYoungpreneur: www.young-preneur.ch<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2F21-milioni-di-franchi-svizzeri-per-la-startup-svizzera-mirai-foods%2F';\n  addthis_title  = '2%2C1+milioni+di+franchi+svizzeri+per+la+startup+svizzera+Mirai+Foods';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La startup svizzera di clean meat Mirai Foods ha ricevuto un finanziamento di 2,1 milioni di franchi svizzeri per sviluppare carne senza OGM. La startup di carne pulita Mirai Foods La startup svizzera di clean meat Mirai Foods \u00e8 stata fondata a W\u00e4denswil nel 2019 e mira a produrre e distribuire carne coltivata. La clean [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1550],"tags":[1639],"class_list":["post-9223","post","type-post","status-publish","format-standard","hentry","category-scenario-startup","tag-clean-meat"],"jetpack_publicize_connections":[],"views":975,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2oL","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9223"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9223\/revisions"}],"predecessor-version":[{"id":9225,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9223\/revisions\/9225"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}