{"id":9082,"date":"2020-11-16T07:20:45","date_gmt":"2020-11-16T06:20:45","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9082"},"modified":"2020-11-10T10:24:22","modified_gmt":"2020-11-10T09:24:22","slug":"ecco-come-la-pandemia-promuove-linnovazione","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/ecco-come-la-pandemia-promuove-linnovazione\/","title":{"rendered":"Ecco come la pandemia promuove l&#8217;innovazione"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La crisi del coronavirus significa\nmolta incertezza per le aziende. Ci sono abbastanza clienti in arrivo? C&#8217;\u00e8\nabbastanza liquidit\u00e0\nper sopravvivere nonostante la riduzione del fatturato? La crisi pu\u00f2 essere\nsuperata? Tuttavia, la pandemia porta anche sviluppi positivi, soprattutto nel\nsettore dell&#8217;innovazione e delle\nstart-up.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"6000\" height=\"4000\" data-attachment-id=\"9083\" data-permalink=\"https:\/\/blog.startups.ch\/it\/ecco-come-la-pandemia-promuove-linnovazione\/pexels-fotografierende-1314410\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?fit=6000%2C4000&amp;ssl=1\" data-orig-size=\"6000,4000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pexels-fotografierende-1314410\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?fit=1200%2C800&amp;ssl=1\" src=\"https:\/\/i2.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?fit=1200%2C800&amp;ssl=1\" alt=\"\" class=\"wp-image-9083\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?w=6000&amp;ssl=1 6000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/11\/pexels-fotografierende-1314410.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Uno sguardo al <a href=\"https:\/\/blog.startups.ch\/it\/rapporto-delle-costituzioni-ottobre-2020-le-serie-di-record-rimangono-ininterrotte\/\">numero di costituzioni<\/a> mostra che la scena delle start-up e dell&#8217;innovazione sta emergendo con forza dalla crisi del coronavirus. Mai prima d&#8217;ora sono state fondate cos\u00ec tante aziende come negli ultimi quattro mesi: molte persone sembrano aver sfruttato la situazione particolare per realizzare il sogno di aprire la propria azienda. Le start-up nel settore dell&#8217;innovazione hanno avuto un impulso sotto molti aspetti.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Flessibilit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;introduzione dell&#8217;home office a livello nazionale ha\ncambiato la comprensione dell&#8217;orario e del luogo di lavoro. Il risultato \u00e8 una\nmaggiore flessibilit\u00e0, il mondo del lavoro sta cambiando. \u00c8 probabile che in\nfuturo ci si aspetti un aumento del numero di persone impiegate all&#8217;estero e\nuna maggiore flessibilit\u00e0 in termini di modelli a tempo parziale. Grazie alla\nmutata esperienza lavorativa, si sono affermate anche nuove start-up.\nSoprattutto nel settore delle Food-Tech-Startup, sono successe molte cose: sia che si tratti solo della consegna a domicilio di generi\nalimentari o che un cuoco\nvi prepari la cena direttamente a casa, le start-up alimentari sono pi\u00f9\nche mai in piena espansione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cooperazione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Anche la cooperazione ha subito un cambiamento. Mentre in\nprecedenza le riunioni e le discussioni della durata di ore erano la norma in\nufficio, ora la collaborazione avviene sempre pi\u00f9 spesso tramite piattaforme\nonline. Le reti virtuali e le applicazioni di pianificazione aiutano a\nmantenere una visione d&#8217;insieme e ad aumentare la produttivit\u00e0.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sostenibilit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Inquinamento atmosferico a livelli bassi come mai prima d&#8217;ora, delfini nei canali di\nVenezia &#8211; almeno il clima ha beneficiato della crisi e dell&#8217;isolamento. Ma la\npandemia ha anche aumentato la consapevolezza generale sui temi dell&#8217;ambiente e\ndella sostenibilit\u00e0. I processi logistici e gli usi dei prodotti sono in fase\ndi ridefinizione e le start-up nel settore della sostenibilit\u00e0 hanno ricevuto\nun impulso inaspettato. Un&#8217;economia pi\u00f9 sostenibile deve essere creata attraverso\nstart-up innovative nell&#8217;economia circolare, un sistema rigenerativo con\nl&#8217;obiettivo di ridurre al minimo il consumo di risorse ed energia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea\ninnovativa che vorreste implementare? Gli esperti di STARTUPS.CH saranno lieti\ndi accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fecco-come-la-pandemia-promuove-linnovazione%2F';\n  addthis_title  = 'Ecco+come+la+pandemia+promuove+l%26%238217%3Binnovazione';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La crisi del coronavirus significa molta incertezza per le aziende. Ci sono abbastanza clienti in arrivo? C&#8217;\u00e8 abbastanza liquidit\u00e0 per sopravvivere nonostante la riduzione del fatturato? La crisi pu\u00f2 essere superata? Tuttavia, la pandemia porta anche sviluppi positivi, soprattutto nel settore dell&#8217;innovazione e delle start-up. Uno sguardo al numero di costituzioni mostra che la scena [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1550],"tags":[1595,759],"class_list":["post-9082","post","type-post","status-publish","format-standard","hentry","category-scenario-startup","tag-coronavirus","tag-innovazione"],"jetpack_publicize_connections":[],"views":910,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2mu","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9082"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9082\/revisions"}],"predecessor-version":[{"id":9084,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9082\/revisions\/9084"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}