{"id":9057,"date":"2020-10-29T13:59:26","date_gmt":"2020-10-29T12:59:26","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9057"},"modified":"2020-10-27T14:03:34","modified_gmt":"2020-10-27T13:03:34","slug":"creative-commons","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/creative-commons\/","title":{"rendered":"Creative Commons"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Creative Commons \u00e8 un&#8217;organizzazione no-profit fondata negli Stati Uniti nel 2001. Pubblicando contratti di licenza standard, Creative Commons consente agli autori di concedere facilmente al pubblico i diritti d&#8217;uso delle loro opere.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"708\" data-attachment-id=\"9059\" data-permalink=\"https:\/\/blog.startups.ch\/it\/creative-commons\/creative-commons-783531_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/creative-commons-783531_1280.png?fit=1280%2C708&amp;ssl=1\" data-orig-size=\"1280,708\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"creative-commons-783531_1280\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/creative-commons-783531_1280.png?fit=1200%2C664&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/creative-commons-783531_1280.png?fit=1200%2C664&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/creative-commons-783531_1280.png?fit=1200%2C664&amp;ssl=1\" alt=\"\" class=\"wp-image-9059\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/creative-commons-783531_1280.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/creative-commons-783531_1280.png?resize=1200%2C664&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tramite Creative Commons, gli autori,\novvero i produttori di foto, video, musica, opere d&#8217;arte e altro ancora,\npossono creare licenze con pochi clic, permettendo al pubblico di utilizzare le loro opere. Il\nconcetto di Creative Commons si basa su un sistema modulare ed \u00e8 indicato agli\nutenti da segni e abbreviazioni. A seconda di quali simboli o abbreviazioni\nsono visibili su un&#8217;opera, i potenziali utenti capiranno immediatamente come\nun&#8217;opera pu\u00f2 essere utilizzata. Si distingue tra i seguenti quattro componenti\ndi licenza:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Created by\n(BY)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;abbreviazione &#8220;BY&#8221; e\nil simbolo di una persona stanno per il componente di licenza &#8220;created by&#8221;. Tutte le\nlicenze Creative Commons contengono questo simbolo, che vuole raffigurare l&#8217;autore. Indica che\nl&#8217;autore deve essere nominato come creatore quando la sua opera viene\nutilizzata da terzi. Tuttavia, non \u00e8 specificato come deve apparire questa\ndesignazione dell&#8217;autore. In determinate circostanze \u00e8 sufficiente un link\nall&#8217;opera originale, ma per\nsicurezza si raccomanda di citare sempre il nome completo dell&#8217;autore quando\nsi utilizza un&#8217;opera di terzi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Non Commercial (NC)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se un&#8217;opera \u00e8 contrassegnata con\nun segno del dollaro barrato o con l&#8217;abbreviazione &#8220;NC&#8221;, ci\u00f2\nsignifica che \u00e8 vietato l&#8217;ulteriore utilizzo dell\u2019opera per scopi commerciali. In\nquesto caso, l&#8217;autore concede al pubblico il diritto di utilizzare la sua\nopera, ma non pu\u00f2 ricavarne denaro. Se si desidera utilizzare un&#8217;opera per\nscopi commerciali, \u00e8 necessario il permesso speciale dell&#8217;autore. Quest&#8217;ultimo,\na sua volta, in questi casi, richiede\nsolitamente il pagamento di una piccola somma di denaro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">No\nDerivative (ND)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;abbreviazione &#8220;ND&#8221; e\nil segno uguale significano che un&#8217;opera non pu\u00f2 essere modificata. Di\nconseguenza, l&#8217;ulteriore utilizzo \u00e8 consentito solo in forma identica. La\nmodifica di un&#8217;opera, invece, richiede il permesso speciale dell&#8217;autore.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Share\nAlike (SA)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se un&#8217;opera reca il simbolo del\nriciclaggio o l&#8217;abbreviazione &#8220;SA&#8221;, gli utenti vengono informati che\ndevono utilizzare la stessa licenza per l&#8217;utilizzo dell&#8217;opera. Ci\u00f2 significa\nche per le opere riutilizzate valgono le stesse identiche restrizioni\ndell&#8217;originale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sistema modulare<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A seconda della misura in cui un\nautore desidera limitare l&#8217;uso della sua opera, pu\u00f2 limitare l&#8217;uso della sua\nopera all&#8217;attribuzione dell&#8217;autore (BY) o combinare diversi degli elementi discussi in precedenza. Questo sistema facilita la concessione di licenze per le\nopere e allo stesso tempo fornisce al pubblico l&#8217;accesso alle stesse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Fonte: Creative Commons &#8220;Perch\u00e9 il CC \u00e8 importante&#8221;, scaricato da: <\/em><a href=\"http:\/\/www.creativecommons.ch\/wie-funktionierts\/\"><em>http:\/\/www.creativecommons.ch\/wie-funktionierts\/<\/em><\/a><em> il 13.10.2020<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fcreative-commons%2F';\n  addthis_title  = 'Creative+Commons';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Creative Commons \u00e8 un&#8217;organizzazione no-profit fondata negli Stati Uniti nel 2001. Pubblicando contratti di licenza standard, Creative Commons consente agli autori di concedere facilmente al pubblico i diritti d&#8217;uso delle loro opere. Tramite Creative Commons, gli autori, ovvero i produttori di foto, video, musica, opere d&#8217;arte e altro ancora, possono creare licenze con pochi clic, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[1616],"class_list":["post-9057","post","type-post","status-publish","format-standard","hentry","category-curiosita","tag-creative-commons"],"jetpack_publicize_connections":[],"views":988,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2m5","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9057"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9057\/revisions"}],"predecessor-version":[{"id":9060,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9057\/revisions\/9060"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}