{"id":9033,"date":"2020-10-08T06:39:59","date_gmt":"2020-10-08T04:39:59","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=9033"},"modified":"2020-10-06T16:47:30","modified_gmt":"2020-10-06T14:47:30","slug":"queste-sono-le-migliori-startup-svizzere","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/queste-sono-le-migliori-startup-svizzere\/","title":{"rendered":"Queste sono le migliori startup svizzere"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ogni\nanno lo Swiss Startup Award premia le 100 migliori startup della Svizzera.\nQuest&#8217;anno il podio \u00e8 stato conquistato dalle tre startup Cutiss (1\u00b0 posto),\nWingtra (2\u00b0 posto) e Piavita (3\u00b0 posto). Per saperne di pi\u00f9 su queste aziende\ninnovative, leggete l&#8217;articolo.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"7680\" height=\"5120\" data-attachment-id=\"9034\" data-permalink=\"https:\/\/blog.startups.ch\/it\/queste-sono-le-migliori-startup-svizzere\/pexels-andrea-piacquadio-3865569\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?fit=7680%2C5120&amp;ssl=1\" data-orig-size=\"7680,5120\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pexels-andrea-piacquadio-3865569\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?fit=1200%2C800&amp;ssl=1\" src=\"https:\/\/i2.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?fit=1200%2C800&amp;ssl=1\" alt=\"\" class=\"wp-image-9034\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?w=7680&amp;ssl=1 7680w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/10\/pexels-andrea-piacquadio-3865569.jpg?w=3000&amp;ssl=1 3000w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Anche quest&#8217;anno le 100 migliori startup sono state scelte al TOP 100 Swiss Startup Award. Per la prima volta l&#8217;evento del 2020 \u00e8 stato trasmesso anche online. La cerimonia annuale di premiazione riunisce le startup pi\u00f9 innovative della Svizzera, gli investitori e i manager internazionali. Le migliori start-up di quest&#8217;anno sono Cutiss, Wingtra e Piavita.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cutiss<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La start-up di scienze della vita\nCutiss produce innesti di pelle umana personalizzati per il trattamento di\ngravi ustioni o scottature. La start-up zurighese \u00e8 stata fondata dalla Dr.\nDaniela Marino e dalla Dr. Fabienne Hartmann-Fritsch. Nel 2019, l&#8217;azienda si\nera gi\u00e0 classificata al 6\u00b0 posto: in una procedura speciale, le cellule\ntissutali vengono rimosse dalla persona colpita, moltiplicate e viene prodotto\nun trapianto di pelle (denovoSkin\u2122). Ci si aspetta che l\u2019operazione lasci solo\ncicatrici minime dopo il trapianto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Wingtra<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La startup Wingtra, anch&#8217;essa con\nsede a Zurigo, produce droni per il rilevamento di superfici. Gi\u00e0 nel 2019\nWingtra si era aggiudicata il 4\u00b0 posto nella Top 100. L&#8217;azienda \u00e8 stata fondata\nda Maximilian Boosfeld, Basil Weibel ed Elias Kleinmann. Il drone WintraOne\ndecolla e atterra in verticale (VTOL), che gli permette di muoversi come un\nelicottero. Per le attivit\u00e0 di rilievo, il drone ruota di 90\u00b0 e si sposta in\nposizione orizzontale. Questa tecnica non solo permette di rilevare grandi aree\nin tempo reale, ma riduce anche il rischio di danni durante l&#8217;atterraggio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Piavita<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Piavita, un&#8217;azienda che vuole\nrivoluzionare la medicina veterinaria, \u00e8 al terzo posto. Mentre nel 2019 la start-up\nsi trovava ancora all&#8217;8\u00b0 posto, quest&#8217;anno ha ottenuto il podio. La dottoressa\nDorina Thiess e Sascha B\u00fchrle, fondatrici di Piavita, e il loro team hanno\nsviluppato una piattaforma per il monitoraggio dei cavalli malati o in fase di\nrecupero. In un approccio rivoluzionario, i moderni sensori, Big Data e IA sono\ncombinati per fornire un trattamento e una cura completi. Un sensore misura\ncontinuamente i segni vitali del cavallo e li invia a un telefono cellulare o ad\nun laptop. In questo modo ci si pu\u00f2 assicurare che l&#8217;animale stia bene in ogni\nmomento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: https:\/\/www.top100startups.swiss\/;\nhttps:\/\/www.organisator.ch\/die-100-besten-startups-der-schweiz-2020\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fqueste-sono-le-migliori-startup-svizzere%2F';\n  addthis_title  = 'Queste+sono+le+migliori+startup+svizzere';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ogni anno lo Swiss Startup Award premia le 100 migliori startup della Svizzera. Quest&#8217;anno il podio \u00e8 stato conquistato dalle tre startup Cutiss (1\u00b0 posto), Wingtra (2\u00b0 posto) e Piavita (3\u00b0 posto). Per saperne di pi\u00f9 su queste aziende innovative, leggete l&#8217;articolo. Anche quest&#8217;anno le 100 migliori startup sono state scelte al TOP 100 Swiss [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1550],"tags":[1126,739],"class_list":["post-9033","post","type-post","status-publish","format-standard","hentry","category-scenario-startup","tag-premi-startup-svizzera","tag-startup"],"jetpack_publicize_connections":[],"views":1138,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2lH","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=9033"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9033\/revisions"}],"predecessor-version":[{"id":9035,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/9033\/revisions\/9035"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=9033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=9033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=9033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}