{"id":8820,"date":"2020-02-04T15:43:48","date_gmt":"2020-02-04T14:43:48","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=8820"},"modified":"2020-03-20T12:08:01","modified_gmt":"2020-03-20T11:08:01","slug":"conversione-delle-azioni-nominative-in-azioni-al-portatore-parte-2","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/conversione-delle-azioni-nominative-in-azioni-al-portatore-parte-2\/","title":{"rendered":"Conversione delle azioni nominative in azioni al portatore (Parte 2)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Definizione legale dell&#8217;avente diritto economico nelle societ\u00e0 in qualit\u00e0 di azionista.<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1999\" height=\"1334\" data-attachment-id=\"8821\" data-permalink=\"https:\/\/blog.startups.ch\/it\/conversione-delle-azioni-nominative-in-azioni-al-portatore-parte-2\/u%cc%88ber-startups-ch_\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/02\/U\u0308ber-STARTUPS.CH_.jpg?fit=1999%2C1334&amp;ssl=1\" data-orig-size=\"1999,1334\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"U\u0308ber-STARTUPS.CH_\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/02\/U\u0308ber-STARTUPS.CH_.jpg?fit=1200%2C801&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/02\/U\u0308ber-STARTUPS.CH_.jpg?fit=1200%2C801&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/02\/U\u0308ber-STARTUPS.CH_.jpg?resize=1999%2C1334&#038;ssl=1\" alt=\"\" class=\"wp-image-8821\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/02\/U\u0308ber-STARTUPS.CH_.jpg?w=1999&amp;ssl=1 1999w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2020\/02\/U\u0308ber-STARTUPS.CH_.jpg?resize=1200%2C801&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La nuova legge specifica chi \u00e8 considerato l&#8217;avente diritto economico se\nl&#8217;azionista \u00e8 una azienda o una societ\u00e0 quotata in borsa. Analogamente all&#8217;art.\n963 cpv. 2 CO, una persona giuridica controlla un\u2019altra impresa se:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>dispone direttamente o indirettamente della maggioranza dei voti\nnell\u2019organo supremo;<\/li><li>ha direttamente o indirettamente il\ndiritto di nominare o di revocare la maggioranza dei membri dell\u2019organo\nsuperiore di direzione o di amministrazione; o<\/li><li>pu\u00f2 esercitare un\u2019influenza\ndominante in virt\u00f9 dello statuto, dell\u2019atto di fondazione, di un contratto o di\nstrumenti analoghi.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">In mancanza di tale persona, l&#8217;obbligo di segnalazione viene adempiuto\nsegnalandolo alla societ\u00e0. Se la persona che soddisfa i requisiti di cui sopra\n\u00e8 un&#8217;altra societ\u00e0 quotata in borsa, questo fatto deve essere segnalato, cos\u00ec\ncome il nome e la sede legale di questa societ\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le notifiche relative a modifiche del nome, del cognome o dell&#8217;indirizzo\ndell&#8217;avente diritto economico devono ora essere inviate alla societ\u00e0 entro tre\nmesi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cambiamenti nel\ndiritto penale<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Anche il codice penale sar\u00e0 completato dalle nuove disposizioni. La\nviolazione intenzionale dell&#8217;obbligo di comunicazione degli aventi diritto\neconomico, nonch\u00e9 la violazione intenzionale dell&#8217;obbligo di tenere un registro\ne un elenco delle azioni o dei registri delle azioni, sono ora punibili con una\nmulta fino a CHF 10&#8217;000.-. La societ\u00e0 \u00e8 minacciata da un processo anche in caso\ndi carenze organizzative, per cui il tribunale pu\u00f2 anche ordinare lo\nscioglimento e la liquidazione della societ\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volete convertire le\nvostre azioni nominative? I nostri esperti sono a vostra disposizione. <a href=\"https:\/\/www.startups.ch\/it\/servizi\/modifiche-nel-registro-di-commercio\">Qui<\/a> potete ordinare la\nconversione direttamente online. Oppure siete invitati a <a href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\">prendere un appuntament<\/a>o per una\nconsulenza tramite STARTUPS.CH.<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/modifiche-nel-registro-di-commercio\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Convertire le azioni <\/a><a class=\"postButton\" href=\"https:\/\/blog.startups.ch\/it\/conversione-delle-azioni-nominative-in-azioni-al-portatore\/\" rel=\"noopener noreferrer\">\u00bb Torna alla parte 1<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fconversione-delle-azioni-nominative-in-azioni-al-portatore-parte-2%2F';\n  addthis_title  = 'Conversione+delle+azioni+nominative+in+azioni+al+portatore+%28Parte+2%29';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Definizione legale dell&#8217;avente diritto economico nelle societ\u00e0 in qualit\u00e0 di azionista. La nuova legge specifica chi \u00e8 considerato l&#8217;avente diritto economico se l&#8217;azionista \u00e8 una azienda o una societ\u00e0 quotata in borsa. Analogamente all&#8217;art. 963 cpv. 2 CO, una persona giuridica controlla un\u2019altra impresa se: dispone direttamente o indirettamente della maggioranza dei voti nell\u2019organo supremo; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[5],"tags":[293,292,13],"class_list":["post-8820","post","type-post","status-publish","format-standard","hentry","category-sa","tag-azioni-al-portatore","tag-azioni-nominative","tag-azionista"],"jetpack_publicize_connections":[],"views":1455,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2ig","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=8820"}],"version-history":[{"count":3,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8820\/revisions"}],"predecessor-version":[{"id":8854,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8820\/revisions\/8854"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=8820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=8820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=8820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}