{"id":8487,"date":"2019-09-06T13:00:24","date_gmt":"2019-09-06T11:00:24","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=8487"},"modified":"2019-09-06T08:00:30","modified_gmt":"2019-09-06T06:00:30","slug":"kill-your-business-diventare-piu-forti-riconoscendo-le-proprie-debolezze","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/kill-your-business-diventare-piu-forti-riconoscendo-le-proprie-debolezze\/","title":{"rendered":"Kill your Business: diventare pi\u00f9 forti riconoscendo le proprie debolezze"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Con il metodo &#8220;Kill\nyour Business&#8221; i giovani imprenditori riconoscono i punti deboli della\npropria organizzazione mettendosi nei panni della concorrenza. Il metodo ha\norigine nel &#8220;Red Teaming&#8221;, che viene utilizzato nel settore militare\nper identificare le proprie lacune di sicurezza. Da alcuni anni, tuttavia, sono\nstati utilizzati con successo anche dalle aziende.<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" data-attachment-id=\"8488\" data-permalink=\"https:\/\/blog.startups.ch\/it\/kill-your-business-diventare-piu-forti-riconoscendo-le-proprie-debolezze\/board-game-businessman-challenge-1040157\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/09\/board-game-businessman-challenge-1040157.jpg?fit=2000%2C1333&amp;ssl=1\" data-orig-size=\"2000,1333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"board-game-businessman-challenge-1040157\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/09\/board-game-businessman-challenge-1040157.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/09\/board-game-businessman-challenge-1040157.jpg?fit=1200%2C800&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/09\/board-game-businessman-challenge-1040157.jpg?resize=2000%2C1333&#038;ssl=1\" alt=\"\" class=\"wp-image-8488\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/09\/board-game-businessman-challenge-1040157.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/09\/board-game-businessman-challenge-1040157.jpg?resize=1200%2C800&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">I giovani\nimprenditori sono euforici e vogliono avviare le loro startup, penetrando in\nnuovi mercati e sviluppando nuove aree di business. Tuttavia, i giovani\nimprenditori spesso si sopravvalutano e in molti casi le cose non vanno come\nprevisto, portando al fallimento della startup.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un nuovo metodo chiamato &#8220;Kill your Business&#8221; pu\u00f2 ora aiutare le startup a identificare i loro punti deboli. Durante un workshop, i dipendenti della startup creano un concorrente fittizio migliore della propria azienda e che sia potenzialmente in grado di distruggerla, da cui il nome &#8220;Kill your Business&#8221;. Mettendosi nella posizione del loro pi\u00f9 grande concorrente e cercando di silurare la propria startup, riconoscono dove si trovano i punti deboli e gli angoli ciechi pi\u00f9 grandi (le cosiddette incognite). In seguito \u00e8 necessario eliminare i punti deboli individuati nella propria startup per essere maggiormente preparati in futuro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Metodo derivato dal mondo\nmilitare<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il metodo\n&#8220;Kill your Business&#8221; deriva dal settore militare, dove \u00e8 conosciuto\ncome &#8220;Red Team&#8221;. Ci si mette nella posizione del proprio avversario\nper scoprire le proprie falle di sicurezza prima che lo facciano terze parti.\nDa alcuni anni, anche le aziende private negli Stati Uniti utilizzano le\ncosiddette Red Teams per eliminare le loro debolezze e prevenire i fallimenti.\nIl fatto che il metodo possa essere di grande utilit\u00e0 \u00e8 dimostrato da aziende\nun tempo molto importanti, come Kodak o Blockbuster, che hanno mantenuto troppo\na lungo i loro vecchi modelli di business.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Fonte: Neue Z\u00fcrcher Zeitung<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di STARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\" https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fkill-your-business-diventare-piu-forti-riconoscendo-le-proprie-debolezze%2F';\n  addthis_title  = 'Kill+your+Business%3A+diventare+pi%C3%B9+forti+riconoscendo+le+proprie+debolezze';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Con il metodo &#8220;Kill your Business&#8221; i giovani imprenditori riconoscono i punti deboli della propria organizzazione mettendosi nei panni della concorrenza. Il metodo ha origine nel &#8220;Red Teaming&#8221;, che viene utilizzato nel settore militare per identificare le proprie lacune di sicurezza. Da alcuni anni, tuttavia, sono stati utilizzati con successo anche dalle aziende. I giovani [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[648,200,1294],"class_list":["post-8487","post","type-post","status-publish","format-standard","hentry","category-curiosita","tag-azienda","tag-concorrenza","tag-nuovo-metodo"],"jetpack_publicize_connections":[],"views":2255,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2cT","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=8487"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8487\/revisions"}],"predecessor-version":[{"id":8490,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8487\/revisions\/8490"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=8487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=8487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=8487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}