{"id":8329,"date":"2019-07-10T11:59:17","date_gmt":"2019-07-10T09:59:17","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=8329"},"modified":"2019-09-04T11:10:19","modified_gmt":"2019-09-04T09:10:19","slug":"10-tendenze-in-ambito-user-experience-da-conoscere-nel-2019-parte-2","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/10-tendenze-in-ambito-user-experience-da-conoscere-nel-2019-parte-2\/","title":{"rendered":"10 tendenze in ambito \u201cUser Experience\u201d da conoscere nel 2019 \u2013 Parte 2"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La user experience \u00e8 un elemento\nfondamentale da prendere in considerazione nella progettazione di applicazioni,\nsiti web e software. Da essa pu\u00f2 dipendere il successo o il fallimento di\nun\u2019azienda. In questa seconda parte della nostra mini-serie vi mostriamo le restanti\n5 tendenze del 2019 in ambito user experience.<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1154\" height=\"770\" data-attachment-id=\"8330\" data-permalink=\"https:\/\/blog.startups.ch\/it\/10-tendenze-in-ambito-user-experience-da-conoscere-nel-2019-parte-2\/fidel-fernando-715382-unsplash\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/07\/fidel-fernando-715382-unsplash.jpg?fit=1154%2C770&amp;ssl=1\" data-orig-size=\"1154,770\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fidel-fernando-715382-unsplash\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/07\/fidel-fernando-715382-unsplash.jpg?fit=1154%2C770&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2019\/07\/fidel-fernando-715382-unsplash.jpg?fit=1154%2C770&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2019\/07\/fidel-fernando-715382-unsplash.jpg?resize=1154%2C770&#038;ssl=1\" alt=\"\" class=\"wp-image-8330\" data-recalc-dims=\"1\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">6.&nbsp;&nbsp;&nbsp;&nbsp;\nContenuti video<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">I dati mobili sono sempre meno un problema e la\ncompressione delle dimensioni dei file sta diventando sempre pi\u00f9 veloce, per\ncui i video potrebbero diventare la fonte principale di contenuti di consumo. I\nvideo non sono niente di nuovo, naturalmente, i social media divulgano brevi\nvideo e bastano pochi secondi per guadagnare o perdere l&#8217;attenzione\ndell&#8217;utente. E&#8217; anche molto difficile far passare un messaggio in un breve\nperiodo di tempo utilizzando parole precise e convincenti. Ecco perch\u00e9 sempre\npi\u00f9 aziende stanno creando brevi video sulle loro applicazioni e siti web per\nfornire pi\u00f9 informazioni in meno tempo, mantenendo viva l&#8217;attenzione\ndell&#8217;utente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7.&nbsp;&nbsp;&nbsp;&nbsp;\nAutenticazione biometrica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le minacce online sono aumentate e le aziende e i\nclienti sono pi\u00f9 che mai preoccupati per la loro sicurezza. L&#8217;autenticazione\nbiometrica pu\u00f2 essere la risposta a questo problema. Questa tecnologia aumenta\nla sicurezza scansionando i dati biometrici dell&#8217;utente, come un&#8217;impronta\ndigitale, per confermare la sua identit\u00e0 prima di consentire l&#8217;accesso a\ninformazioni sensibili. Questo pu\u00f2 essere molto utile per quanto riguarda le\napplicazioni bancarie o nella fattispecie prima che un utente effettui un\nacquisto nel negozio Google Play o App Store. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">8.&nbsp;&nbsp;&nbsp;&nbsp;\nNavigazione ottimizzata<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quando si tratta di caricare una pagina web, si hanno\ncirca tre secondi prima che l&#8217;utente lasci il sito. Questo significa due cose:\nla pagina web deve essere ottimizzata con file compressi per un caricamento pi\u00f9\nveloce possibile e la navigazione deve essere chiara e semplice. La\nconfigurazione grafica permette di aggiungere una quantit\u00e0 incredibile di\ndettagli ed effetti, ma bisogna evitare di cadere nella trappola di rendere la\npagina troppo ingombrante e rallentare quindi la navigazione. Tre secondi non \u00e8\nmolto tempo e le aziende devono sfruttare al meglio questi pochi attimi con una\nnavigazione chiara e un caricamento pi\u00f9 veloce.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">9.&nbsp;&nbsp;&nbsp;&nbsp;\nTelefoni pieghevoli<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Samsung e Huawei hanno gi\u00e0 iniziato a far parlare di\ns\u00e8 con i loro prototipi di smartphone pieghevoli. Cosa c&#8217;\u00e8 di cos\u00ec bello in un\ntelefono pieghevole? Beh, un dispositivo pieghevole occupa meno spazio ed \u00e8 pi\u00f9\nleggero, ma uno dei maggiori vantaggi \u00e8 che il materiale utilizzato per uno\nschermo pieghevole \u00e8 pi\u00f9 forte e pi\u00f9 resistente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">10.&nbsp; Il contenuto sar\u00e0 sempre il re<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni azienda deve avere un contenuto di alta qualit\u00e0, compresa una storia avvincente sul perch\u00e9 l&#8217;utente dovrebbe acquistare il suo prodotto. Un modo per farlo \u00e8 usare il comportamento e le preferenze degli utenti per sapere dove concentrarsi e su chi scommettere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di STARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\" https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2F10-tendenze-in-ambito-user-experience-da-conoscere-nel-2019-parte-2%2F';\n  addthis_title  = '10+tendenze+in+ambito+%E2%80%9CUser+Experience%E2%80%9D+da+conoscere+nel+2019+%E2%80%93+Parte+2';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La user experience \u00e8 un elemento fondamentale da prendere in considerazione nella progettazione di applicazioni, siti web e software. Da essa pu\u00f2 dipendere il successo o il fallimento di un\u2019azienda. In questa seconda parte della nostra mini-serie vi mostriamo le restanti 5 tendenze del 2019 in ambito user experience. 6.&nbsp;&nbsp;&nbsp;&nbsp; Contenuti video I dati mobili [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[704,672,739,890,1101,1569],"class_list":["post-8329","post","type-post","status-publish","format-standard","hentry","category-curiosita","tag-nuove-aziende","tag-software","tag-startup","tag-trend","tag-trend-tecnologici","tag-user-experience"],"jetpack_publicize_connections":[],"views":1213,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2al","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=8329"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8329\/revisions"}],"predecessor-version":[{"id":8481,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/8329\/revisions\/8481"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=8329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=8329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=8329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}