{"id":796,"date":"2010-10-21T08:00:36","date_gmt":"2010-10-21T06:00:36","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=796"},"modified":"2014-03-24T14:44:08","modified_gmt":"2014-03-24T13:44:08","slug":"iva-detrazione-della-ritenuta-dacconto","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/iva-detrazione-della-ritenuta-dacconto\/","title":{"rendered":"Detrazione dell&#8217;IVA a credito"},"content":{"rendered":"<p><em>Aggiornato il 3 gennaio 2013<\/em><\/p>\n<h4 style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">Spesso l&#8217;acquirente indipendente si lamenta dell&#8217;imposta sul valore aggiunto, non tanto perch\u00e9 questa gli\/le grava fortemente, ma piuttosto a causa del dispendio amministrativo. Soprattutto molto giovani imprenditori(-trici) fanno fatica a capire come funzioni esattamente la detrazione della ritenuta d&#8217;acconto. Eppure l&#8217;IVA a credito, una volta capita, non rappresenta pi\u00f9 un problema.<\/h4>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">Per facilitare la comprensione sulla detrazione della ritenuta d&#8217;acconto, ecco un esempio:<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">Beat vende nel suo negozio articoli sportivi. Egli riceve dai suoi fornitori articoli sportivi per il valore di CHF 540.\u2013 IVA inclusa. Gli articoli sportivi li vende come commerciante al minuto ai suoi clienti \u00a0per CHF 1614.\u2013 IVA inclusa. Questi due prezzi si compongono nella maniera seguente:<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">&#8211; CHF 540: CHF 500 (materiale) + 40 (IVA 8.0%) [acquisto]<br \/>\n&#8211; CHF 1620: CHF 1500 (materiale) + 120 (IVA 8.0%) [vendita]<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">Fondamentalmente l&#8217;IVA non grava sul fatturato di Beat, poich\u00e9 l&#8217;IVA \u00e8 un&#8217;imposta sul consumo e viene scaricata sui consumatori finali (cfr. <a href=\"http:\/\/blog.startups.ch\/it\/2010\/10\/14\/assoggettamento-allimposta-sul-valore-aggiunto\/\" target=\"_blank\">articolo corrispondente<\/a>). Inoltre Beat deve per\u00f2 far valere la detrazione dell&#8217;IVA a credito.<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">Questa funziona come segue:<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">1. Beat compra le merce dal fornitore e paga CHF 40 IVA.<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">2. Beat vende la merce. Nel prezzo di vendita sono contenuti CHF 120 IVA.<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">3. Beat dovrebbe pagare CHF 120 all&#8217;AFC (amministrazione federale delle contribuzioni).<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">4. Poich\u00e9 Beat dovette gi\u00e0 pagare CHF 40 per la stessa merce, pu\u00f2 detrarre questo importo come\u00a0<strong>IVA a credito<\/strong>.<\/p>\n<p style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 10px; margin-left: 0px; font-size: 12px; color: #595959; font-family: Arial, Helvetica, Verdana; line-height: 15px; display: block; padding: 0px;\">5. Risultato: Beat deve pagare CHF 80 all&#8217;AFC (CHF 120\u00a0<strong>meno CHF 40<\/strong> = CHF 80).<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fiva-detrazione-della-ritenuta-dacconto%2F';\n  addthis_title  = 'Detrazione+dell%26%238217%3BIVA+a+credito';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aggiornato il 3 gennaio 2013 Spesso l&#8217;acquirente indipendente si lamenta dell&#8217;imposta sul valore aggiunto, non tanto perch\u00e9 questa gli\/le grava fortemente, ma piuttosto a causa del dispendio amministrativo. Soprattutto molto giovani imprenditori(-trici) fanno fatica a capire come funzioni esattamente la detrazione della ritenuta d&#8217;acconto. Eppure l&#8217;IVA a credito, una volta capita, non rappresenta pi\u00f9 un [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[8],"tags":[326,327,336,333,318,39,334,335],"class_list":["post-796","post","type-post","status-publish","format-standard","hentry","category-imposte-e-assicurazioni-sociali","tag-afc","tag-amministrazione-federale-delle-contribuzioni","tag-detrazione-iva","tag-imposta-precedente","tag-imposta-sul-valore-aggiunto","tag-iva","tag-iva-a-credito","tag-ritenuta-dacconto"],"jetpack_publicize_connections":[],"views":2442,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-cQ","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=796"}],"version-history":[{"count":21,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/796\/revisions"}],"predecessor-version":[{"id":3827,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/796\/revisions\/3827"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}