{"id":7898,"date":"2018-12-26T13:00:06","date_gmt":"2018-12-26T12:00:06","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=7898"},"modified":"2019-09-24T18:54:07","modified_gmt":"2019-09-24T16:54:07","slug":"sempre-meno-aziende-svizzere-investono-nella-ricerca-sviluppo-rs","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/sempre-meno-aziende-svizzere-investono-nella-ricerca-sviluppo-rs\/","title":{"rendered":"Sempre meno aziende svizzere investono nella ricerca e sviluppo (R&#038;S)"},"content":{"rendered":"<h2>Le aziende svizzere si concentrano sempre pi\u00f9 sul miglioramento dei prodotti invece di investire nella ricerca e sviluppo (R&amp;S) di nuovi prodotti innovativi. La quota delle imprese svizzere che investono in R&amp;S \u00e8 scesa dal 25% nel 2000 all&#8217;attuale 13,3%. Lo dimostra uno studio condotto dal Centro di ricerca congiunturale (KOF) del Politecnico di Zurigo (ETH).<\/h2>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7899\" data-permalink=\"https:\/\/blog.startups.ch\/it\/sempre-meno-aziende-svizzere-investono-nella-ricerca-sviluppo-rs\/hans-reniers-746177-unsplash\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/12\/hans-reniers-746177-unsplash.jpg?fit=1154%2C770&amp;ssl=1\" data-orig-size=\"1154,770\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"hans-reniers-746177-unsplash\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/12\/hans-reniers-746177-unsplash.jpg?fit=1154%2C770&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/12\/hans-reniers-746177-unsplash.jpg?fit=1154%2C770&amp;ssl=1\" class=\"size-full wp-image-7899 aligncenter\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2018\/12\/hans-reniers-746177-unsplash.jpg?resize=1154%2C770&#038;ssl=1\" alt=\"\" width=\"1154\" height=\"770\" data-recalc-dims=\"1\" \/><\/p>\n<h3>Il totale degli investimenti \u00e8 aumentato, tuttavia \u00e8 concentrato in poche aziende<\/h3>\n<p>Secondo l&#8217;indagine sull&#8217;innovazione del 2016 condotta dal Centro di ricerca congiunturale del Politecnico di Zurigo, gli investimenti complessivi delle imprese svizzere nell&#8217;ambito della ricerca e sviluppo (R&amp;S) sono aumentati rispetto agli anni precedenti. D&#8217;altro canto, il numero di imprese che investono in R&amp;S \u00e8 diminuito. All&#8217;inizio del millennio, un&#8217;azienda svizzera su quattro era ancora impegnata nella ricerca e sviluppo; oggi \u00e8 solamente all&#8217;incirca una su otto. Al contrario, l&#8217;attenzione si concentra sempre pi\u00f9 sul miglioramento dei prodotti. I fattori che determinano questa diminuzione sono la mancanza di capitale proprio, il lungo periodo di ammortamento dei costi di innovazione, un elevato rischio di mercato e il pericolo che i nuovi prodotti vengano copiati. In particolare le PMI hanno problemi di finanziamento. Infatti, un fattore importante di questo declino \u00e8 l&#8217;elevato costo della R&amp;S in Svizzera, motivo per cui il numero di imprese che svolgono attivit\u00e0 di R&amp;S a livello nazionale \u00e8 diminuito maggiormente. Per contro, il numero di imprese svizzere attive nella R&amp;S all&#8217;estero \u00e8 rimasto stabile.<\/p>\n<h3>A seconda delle dimensioni dell\u2019azienda questo trend incide diversamente<\/h3>\n<p>La dimensione dell&#8217;azienda gioca un ruolo importante nel livello di investimento in R&amp;S: rispetto all&#8217;inizio del millennio, le grandi aziende hanno nuovamente aumentato i loro investimenti nel settore della R&amp;S a partire dal 2009. D&#8217;altro canto, dal 2000 le PMI spendono sempre meno per la ricerca e lo sviluppo. Fortunatamente, la collaborazione tra le societ\u00e0 di ricerca \u00e8 praticamente raddoppiata. Inoltre \u00e8 particolarmente aumentata la cooperazione con i partner all&#8217;estero.<\/p>\n<p>L&#8217;indagine sull&#8217;innovazione del Centro di ricerca congiunturale del Politecnico federale di Zurigo ha esaminato tramite un questionario in forma scritta le attivit\u00e0 innovative dell&#8217;economia svizzera nel periodo 2014-16. L&#8217;indagine ha riguardato circa 5600 imprese private con pi\u00f9 di cinque dipendenti nel settore industriale, nell&#8217;edilizia e nel settore dei servizi.<\/p>\n<p><em>Fonte: \u00abInnovation in der Schweizer Privatwirtschaft. Ergebnisse der Innovationserhebung 2016\u00bb der Konjunkturforschungsstelle der ETH Z\u00fcrich<\/em><\/p>\n<p>Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di STARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fsempre-meno-aziende-svizzere-investono-nella-ricerca-sviluppo-rs%2F';\n  addthis_title  = 'Sempre+meno+aziende+svizzere+investono+nella+ricerca+e+sviluppo+%28R%26%23038%3BS%29';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le aziende svizzere si concentrano sempre pi\u00f9 sul miglioramento dei prodotti invece di investire nella ricerca e sviluppo (R&amp;S) di nuovi prodotti innovativi. La quota delle imprese svizzere che investono in R&amp;S \u00e8 scesa dal 25% nel 2000 all&#8217;attuale 13,3%. Lo dimostra uno studio condotto dal Centro di ricerca congiunturale (KOF) del Politecnico di Zurigo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[791,1512,47,746],"class_list":["post-7898","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-business-model","tag-ricerca-e-sviluppo","tag-startups-ch","tag-svizzera"],"jetpack_publicize_connections":[],"views":1450,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-23o","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=7898"}],"version-history":[{"count":3,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7898\/revisions"}],"predecessor-version":[{"id":8576,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7898\/revisions\/8576"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=7898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=7898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=7898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}