{"id":7810,"date":"2018-11-16T13:00:41","date_gmt":"2018-11-16T12:00:41","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=7810"},"modified":"2019-09-24T19:10:16","modified_gmt":"2019-09-24T17:10:16","slug":"lezioni-leadership-dalla-spedizione-shackleton-parte-2","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/lezioni-leadership-dalla-spedizione-shackleton-parte-2\/","title":{"rendered":"Lezioni di leadership dalla spedizione di Shackleton \u2013 Parte 2"},"content":{"rendered":"<h2>La spedizione di Shackleton, avvenuta fra il 1914 e il 1916, \u00e8 un&#8217;avvincente storia di leadership che dimostra l\u2019importanza di un leader nel mantenere unito un gruppo al fine di superare le debolezze, la paura e la negativit\u00e0, spingendolo a compiere l\u2019impossibile. Scopri la seconda parte della trilogia dedicata a Ernest Shackleton.<\/h2>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7821\" data-permalink=\"https:\/\/blog.startups.ch\/it\/lezioni-leadership-dalla-spedizione-shackleton-parte-2\/pirates-587988_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/11\/pirates-587988_1280.jpg?fit=1200%2C799&amp;ssl=1\" data-orig-size=\"1200,799\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pirates-587988_1280\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/11\/pirates-587988_1280.jpg?fit=1200%2C799&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/11\/pirates-587988_1280.jpg?fit=1200%2C799&amp;ssl=1\" class=\"size-medium wp-image-7821 aligncenter\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2018\/11\/pirates-587988_1280-1200x799.jpg?resize=1200%2C799&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"799\" data-recalc-dims=\"1\" \/><\/p>\n<p><strong>La sopravvivenza<\/strong><\/p>\n<p>L&#8217;Endurance era immobilizzata, tenuta in ostaggio dai banchi di ghiaccio. Shackleton si rese conto che i suoi uomini avrebbero dovuto aspettare la fine dell&#8217;inverno negli angusti anfratti della nave fino al disgelo estivo. Shackleton temeva i potenziali effetti della pigrizia, della noia e della dissidenza tra i suoi uomini pi\u00f9 di quanto non temesse il ghiaccio e il freddo. Richiese che ogni uomo continuasse il pi\u00f9 possibile a mantenere i suoi doveri quotidiani. I marinai pulivano i ponti, gli scienziati raccoglievano campioni dal ghiaccio e altri, quando la carne fresca scarseggiava, erano assegnati alla caccia alle foche e ai pinguini. Mantenne anche una rigorosa routine per i pasti e insistette che gli uomini socializzassero dopo cena per tonificare il morale in declino.<\/p>\n<p>Attraverso la routine, l&#8217;ordine e l&#8217;interazione, Shackleton gest\u00ec la paura collettiva che minacciava di prendere piede quando il viaggio non and\u00f2 come previsto.\u00a0 Sapeva che in questo ambiente, senza punti di riferimento e supporti tradizionali, i suoi pi\u00f9 grandi nemici erano alti livelli di ansia e disimpegno, cos\u00ec come un progressivo pessimismo.<\/p>\n<p>I giorni diventarono settimane, le settimane mesi, e il ghiaccio tratteneva ancora la nave. Nel giugno 1915, il rigido inverno dell&#8217;emisfero australe stava indebolendo i legnami della nave che si stavano deteriorando a causa della pressione creata dal ghiaccio, e in ottobre l&#8217;acqua inizi\u00f2 a riversarsi nella Endurance. Shackleton ordin\u00f2 all&#8217;equipaggio di abbandonare la nave che stava affondando e di accamparsi su una banchisa di ghiaccio nelle vicinanze. La mattina dopo, annunci\u00f2 un nuovo obiettivo: &#8220;Nave e rifornimenti sono andati &#8211; quindi ora torneremo a casa&#8221;. Il giorno dopo, nell&#8217;intimit\u00e0 del suo diario, fu pi\u00f9 sincero riguardo alla sfida che lo attendeva e scrisse \u201cprego Dio, che io possa riuscire a riportare la truppa alla civilt\u00e0\u201d.<\/p>\n<p><strong>Una nuova missione<\/strong><\/p>\n<p>Dopo che la Endurance affond\u00f2, lasciando gli uomini bloccati sul ghiaccio con tre piccole scialuppe di salvataggio, alcune tende e pochi rifornimenti, Shackleton si rese conto che egli stesso doveva incarnare la nuova missione di sopravvivenza &#8211; non solo in quello che diceva e faceva, ma anche nel suo supporto fisico.<\/p>\n<p>Sapeva che ogni giorno la sua presenza aveva un enorme impatto sulla mente degli uomini. Gestiva la sua intelligenza emotiva per mantenere alto il suo coraggio e la sua fiducia; e anche quando questi venivano a meno, non lo faceva mai notare ai suoi uomini.<\/p>\n<p>Ci\u00f2 dimostra che, come leader, \u00e8 importante avere una fede assoluta nella propria missione, in s\u00e9 stessi e nelle proprie capacit\u00e0. La parte pi\u00f9 difficile della leadership non \u00e8 solo alimentare la propria squadra con idee e motivazioni, ma anche s\u00e9 stessi; e di fronte a enormi ostacoli, Shackleton trov\u00f2 un modo per farlo.<\/p>\n<p>Altrettanto importante, Shackleton ha mantenuto l&#8217;attenzione dei suoi uomini sul futuro. La nave era sparita; i piani precedenti erano irrilevanti. Ora il suo obiettivo era quello di portare il team a casa in sicurezza, e ha improvvisato, adattato e usato ogni risorsa a portata di mano per raggiungerlo.<\/p>\n<p>Quando alcuni uomini hanno espresso scetticismo sui suoi piani, ha agito rapidamente per contenere la loro opposizione e la loro negativit\u00e0, cercando di conquistarli e di tenerli sotto stretta sorveglianza. Ha assegnato i potenziali piantagrane alla sua tenda, dimostrando il valore del detto: &#8220;Tieni i tuoi amici vicino e i tuoi nemici ancora di pi\u00f9&#8221;.<\/p>\n<p><strong>Nel prossimo ed ultimo articolo di questa trilogia scoprirete il finale della storia. \u201cStay tuned!\u201d<\/strong><\/p>\n<p>Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di STARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Flezioni-leadership-dalla-spedizione-shackleton-parte-2%2F';\n  addthis_title  = 'Lezioni+di+leadership+dalla+spedizione+di+Shackleton+%E2%80%93+Parte+2';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La spedizione di Shackleton, avvenuta fra il 1914 e il 1916, \u00e8 un&#8217;avvincente storia di leadership che dimostra l\u2019importanza di un leader nel mantenere unito un gruppo al fine di superare le debolezze, la paura e la negativit\u00e0, spingendolo a compiere l\u2019impossibile. Scopri la seconda parte della trilogia dedicata a Ernest Shackleton.<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[187,1426,47],"class_list":["post-7810","post","type-post","status-publish","format-standard","hentry","category-curiosita","tag-imprenditore","tag-leadership","tag-startups-ch"],"jetpack_publicize_connections":[],"views":1807,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-21Y","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=7810"}],"version-history":[{"count":4,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7810\/revisions"}],"predecessor-version":[{"id":8589,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7810\/revisions\/8589"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=7810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=7810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=7810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}