{"id":7704,"date":"2018-10-05T13:00:14","date_gmt":"2018-10-05T11:00:14","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=7704"},"modified":"2019-09-24T19:22:25","modified_gmt":"2019-09-24T17:22:25","slug":"motivi-della-risoluzione-del-contratto-di-lavoro-cosa-considerare","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/motivi-della-risoluzione-del-contratto-di-lavoro-cosa-considerare\/","title":{"rendered":"Motivi della risoluzione del contratto di lavoro: cosa considerare?"},"content":{"rendered":"<h2><span lang=\"IT-CH\">Il contratto di lavoro pu\u00f2 essere disdetto in cinque modi diversi. Di norma, il rapporto di lavoro viene interrotto dal licenziamento. Il fallimento del datore di lavoro, ad esempio, non \u00e8 motivo di risoluzione del contratto di lavoro.<\/span><\/h2>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2018\/09\/iStock_93222739_XXLARGE.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7705\" data-permalink=\"https:\/\/blog.startups.ch\/it\/motivi-della-risoluzione-del-contratto-di-lavoro-cosa-considerare\/problems-at-the-office\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/09\/iStock_93222739_XXLARGE.jpg?fit=1154%2C770&amp;ssl=1\" data-orig-size=\"1154,770\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Getty Images\\\/iStockphoto&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;business colleagues working together and analyzing financial figures on a digital tablet, it seems it is a bad day for work&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;South_agency&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Problems at the office&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Problems at the office\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;business colleagues working together and analyzing financial figures on a digital tablet, it seems it is a bad day for work&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/09\/iStock_93222739_XXLARGE.jpg?fit=1154%2C770&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/09\/iStock_93222739_XXLARGE.jpg?fit=1154%2C770&amp;ssl=1\" class=\"wp-image-7705 size-full\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2018\/09\/iStock_93222739_XXLARGE.jpg?resize=1154%2C770&#038;ssl=1\" alt=\"\" width=\"1154\" height=\"770\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><strong>Motivi di risoluzione del contratto di lavoro<\/strong><\/p>\n<p>Il contratto di lavoro pu\u00f2 essere rescisso in cinque modi diversi. Di norma, il rapporto di lavoro viene interrotto con disdetta ordinaria o straordinaria. \u00c8 anche possibile sciogliere l&#8217;accordo mediante un accordo di risoluzione, ma entrambe le parti devono dare il loro consenso. Il rapporto scade anche al termine di un periodo concordato (nel caso di contratti a tempo determinato), al momento del pensionamento o del decesso del dipendente.<\/p>\n<p><strong>La disdetta \u00e8 la norma <\/strong><\/p>\n<p>La risoluzione ordinaria \u00e8 possibile in qualsiasi momento da entrambe le parti. Al ricevimento della lettera di disdetta inizia a decorrere il termine di preavviso concordato contrattualmente. Il rapporto di lavoro scade anche allo scadere del termine di preavviso. Su richiesta di una delle parti, il recesso ordinario deve essere giustificato (cfr. post sul blog).<\/p>\n<p>Il licenziamento straordinario &#8211; noto anche come licenziamento senza preavviso &#8211; \u00e8 meno frequente ed \u00e8 possibile solo per motivi importanti. Un motivo importante esiste se non ci si pu\u00f2 pi\u00f9 ragionevolmente aspettare che un partito possa continuare il rapporto di lavoro in buona fede.<\/p>\n<p><strong>Casi particolari senza risoluzione<\/strong><\/p>\n<p>Non vi sono motivi di risoluzione del contratto di lavoro in caso di decesso del datore di lavoro, fallimento del datore di lavoro, trasferimento dell&#8217;azienda, impossibilit\u00e0 di lavoro o invalidit\u00e0 del dipendente.<\/p>\n<p>In caso di decesso del datore di lavoro, il rapporto di lavoro viene trasferito agli eredi (art. 338a CO). Si applicano le stesse regole valide per la successione aziendale ai sensi dell&#8217;art. 333 OR. Il dipendente pu\u00f2 tuttavia rifiutare il trasferimento e il contratto di lavoro viene rescisso nei termini di legge (art. 333 cpv. 2 CO).<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fmotivi-della-risoluzione-del-contratto-di-lavoro-cosa-considerare%2F';\n  addthis_title  = 'Motivi+della+risoluzione+del+contratto+di+lavoro%3A+cosa+considerare%3F';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il contratto di lavoro pu\u00f2 essere disdetto in cinque modi diversi. Di norma, il rapporto di lavoro viene interrotto dal licenziamento. Il fallimento del datore di lavoro, ad esempio, non \u00e8 motivo di risoluzione del contratto di lavoro.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[3],"tags":[199,947,739,47,746],"class_list":["post-7704","post","type-post","status-publish","format-standard","hentry","category-domande-generali","tag-contratto-di-lavoro","tag-diritto-del-lavoro","tag-startup","tag-startups-ch","tag-svizzera"],"jetpack_publicize_connections":[],"views":2405,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-20g","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=7704"}],"version-history":[{"count":3,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7704\/revisions"}],"predecessor-version":[{"id":8601,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7704\/revisions\/8601"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=7704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=7704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=7704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}