{"id":7530,"date":"2018-06-06T12:00:14","date_gmt":"2018-06-06T10:00:14","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=7530"},"modified":"2018-05-15T20:31:48","modified_gmt":"2018-05-15T18:31:48","slug":"3-fonti-ispirazione-business","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/3-fonti-ispirazione-business\/","title":{"rendered":"3 fonti di ispirazione per il tuo nuovo business"},"content":{"rendered":"<h2>Gli imprenditori sono persone che osano sognare e inventare idee che possono essere tradotte in un business di successo. Alcuni ci vanno cauti, altri invece ci si buttano a capofitto. Non importa quanto grande o piccola, tuttavia, ogni azienda inizia con un piano &#8211; una visione o un concetto che qualcuno ha deciso che vale la pena provare. Prendiamo ad esempio i seguenti tre imprenditori: l&#8217;ispirazione pu\u00f2 provenire da molti luoghi e questi tre imprenditori hanno trovato il loro in modi unici.<\/h2>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7531\" data-permalink=\"https:\/\/blog.startups.ch\/it\/3-fonti-ispirazione-business\/ispirazione\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/05\/ispirazione.jpg?fit=1200%2C800&amp;ssl=1\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ispirazione\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/05\/ispirazione.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2018\/05\/ispirazione.jpg?fit=1200%2C800&amp;ssl=1\" class=\"alignnone wp-image-7531\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2018\/05\/ispirazione-1200x800.jpg?resize=982%2C655&#038;ssl=1\" alt=\"\" width=\"982\" height=\"655\" data-recalc-dims=\"1\" \/><\/p>\n<p><strong>Bisogno personale<\/strong><br \/>\nMolte persone iniziano la propria attivit\u00e0 intorno a un prodotto o servizio di cui hanno bisogno, ma che non sono riusciti a trovarli sul mercato. \u00c8 successo a Carlton e Hazel Solle, che hanno costruito un fiorente business con un accessorio inaspettato, il Bioscarf. Questo accessorio \u00e8 realizzato con materiali sostenibili e protegge chi lo indossa da inquinamento, germi, pollini e persino fumo di sigaretta.<br \/>\nL&#8217;ispirazione per il Bioscarf arriv\u00f2 quando Carlton viaggi\u00f2 in Cina e si ammal\u00f2 gravemente respirando l&#8217;aria inquinata. I medici gli dissero che, per rimanere in buona salute, aveva bisogno di indossare una di quelle orribili maschere di filtraggio bianche che i cittadini locali indossano regolarmente.<br \/>\nQuando \u00e8 tornato a casa, ha condiviso la sua storia con Hazel, che le ha ricordato la sua infanzia vivendo in una piccola fattoria in Costa Rica dove non c&#8217;era acqua e pochissimi comfort. I suoi giocattoli preferiti erano due bambole fatte a mano. Con solo pochi pezzi di stoffa con cui lavorare, aveva fatto delle sciarpe per coprire gli abiti logori delle bambole.<br \/>\n&#8220;Quando tornai e cominciammo a parlare della mia malattia e della maschera, pens\u00f2 a quelle bambole e alle sciarpe che era solita fare; \u00e8 stato allora che le \u00e8 venuta l&#8217;idea di mettere insieme le due cose&#8221;, ha detto Carlton. Il risultato \u00e8 stato il Bioscarf, che ha realizzato la maggior parte delle maschere di filtrazione pi\u00f9 diffuse sul mercato oggi, con un&#8217;efficienza di filtrazione media del 99,75%. Queste sciarpe sono ora vendute in tutto il mondo.<\/p>\n<p><strong>Radici familiari<\/strong><br \/>\nGli imprenditori usano spesso le loro conoscenze o esperienze come pietre miliari per il successo. Per Matt Ampolsky, crescere nell&#8217;attivit\u00e0 concertistica della sua famiglia gli ha dato la visione interna completa del processo, il risultato? una startup di grande successo, Confirmed 360, un servizio di intrattenimento e concierge.<br \/>\nCome spiega Ampolsky, &#8220;Ho avuto la fortuna di partecipare ai backstage dei concerti e degli eventi live. Mi sono reso conto sin da subito dell&#8217;impatto di queste esperienze di vita e ho visualizzato la mia missione; offrire queste esperienze indimenticabili agli altri &#8220;.<br \/>\nHa aperto il suo primo ufficio mentre era ancora all&#8217;universit\u00e0 e ha lanciato il suo sito web nel 2015. La societ\u00e0 \u00e8 specializzata nella realizzazione di esperienze irripetibili: dal suo lancio, Confirmed 360 ha organizzato esperienze curate con alcune delle celebrit\u00e0 pi\u00f9 famose di oggi, tra cui Taylor Swift, Ed Sheeran, U2 e Bruce Springsteen, e i grandi dello sport Cristiano Ronaldo e Rafael Nadal. Ha anche consegnato pacchetti VIP personalizzati per il Super Bowl e i principali premi di Hollywood.<br \/>\nMentre Ampolsky ha detto di aver raggiunto ci\u00f2 che si \u00e8 proposto di fare, si rende conto dell&#8217;importanza di offrire ci\u00f2 che promette. &#8220;Continuando a far crescere il business a livello internazionale, rimango fedele alla nostra missione: consegnare ci\u00f2 che non \u00e8 possibile recapitare&#8221;, ha affermato.<\/p>\n<p><strong>Una vecchia idea, rianimata<\/strong><br \/>\nA volte non hai bisogno di una nuova idea. Si pu\u00f2 semplicemente far rivivere una vecchia idea che qualcun altro ha avuto, ma mai sviluppata. Walter Klemp, fondatore \/ CEO di Moleculin, \u00e8 stato introdotto un decennio fa a un promettente trattamento per il cancro che era stato abbandonato quando lo sviluppatore originale aveva finito i soldi. L&#8217;azienda farmaceutica originaria stava sviluppando l&#8217;annamycina, un farmaco che uccide selettivamente i tumori altamente resistenti, in particolare ai pazienti affetti da AML (leucemia mieloide acuta). La societ\u00e0 ha dovuto abbandonare la ricerca a causa di carenze di finanziamenti prima che il farmaco potesse essere completamente testato. Il farmaco fu quindi scartato e lasciato per morto, anche se i primi test avevano mostrato risultati promettenti.<br \/>\nKlemp \u00e8 stato contattato per questo trattamento potenzialmente salvavita dal team originale e coinvolto nello sviluppo del farmaco. Ha speso i suoi soldi per far ripartire i test che erano stati fatti un decennio prima e ha concluso che quei primi risultati valevano per riprovarci. Si \u00e8 offerto di riattivare la squadra e finanziare la ricerca. Klemp credeva cos\u00ec tanto nella scienza da convincere gli investitori a partecipare a ulteriori ricerche, compresa la ripetizione di tutti i test precedenti.<br \/>\nMoleculin \u00e8 stata approvata dalla FDA a settembre 2017. Ha ottenuto il via libera per iniziare i test e ha iniziato tali studi per portare sul mercato l&#8217;Annamycina, offrendo un rimedio contro il cancro potenzialmente storico che finora ha mostrato risulta essere promettente.<\/p>\n<p>Non c&#8217;\u00e8 un modo per trovare l&#8217;idea perfetta che ti metter\u00e0 sulla via dell&#8217;imprenditorialit\u00e0. Puoi scoprire opportunit\u00e0 esaminando le tue esigenze e portando la tua esperienza personale al tavolo, oppure puoi far rivivere una vecchia idea. Tuttavia, quando arriva un\u2019opportunit\u00e0, osa.<\/p>\n<p>Hai un\u2019idea innovativa che vorresti implementare? Gli esperti di STARTUPS.CH saranno lieti di accompagnarti verso l\u2019indipendenza professionale!<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/startups.it\/it\/prepararsi\/colloquiopersonale\/\" target=\"_blank\" rel=\"noopener\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/secure.startups.it\/it\/default\/index\/index\" target=\"_blank\" rel=\"noopener\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2F3-fonti-ispirazione-business%2F';\n  addthis_title  = '3+fonti+di+ispirazione+per+il+tuo+nuovo+business';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Gli imprenditori sono persone che osano sognare e inventare idee che possono essere tradotte in un business di successo. Alcuni ci vanno cauti, altri invece ci si buttano a capofitto. Non importa quanto grande o piccola, tuttavia, ogni azienda inizia con un piano &#8211; una visione o un concetto che qualcuno ha deciso che vale [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691,3],"tags":[791,187,1483,704,604,748,745,899,572,739],"class_list":["post-7530","post","type-post","status-publish","format-standard","hentry","category-curiosita","category-domande-generali","tag-business-model","tag-imprenditore","tag-ispirazione","tag-nuove-aziende","tag-nuove-costituzioni","tag-nuove-imprese","tag-nuove-iscrizioni","tag-nuove-societa","tag-start-up","tag-startup"],"jetpack_publicize_connections":[],"views":1588,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-1Xs","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=7530"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7530\/revisions"}],"predecessor-version":[{"id":7532,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/7530\/revisions\/7532"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=7530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=7530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=7530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}