{"id":6811,"date":"2017-08-24T11:30:53","date_gmt":"2017-08-24T09:30:53","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=6811"},"modified":"2017-09-06T11:23:21","modified_gmt":"2017-09-06T09:23:21","slug":"personale-qualificato-scarseggia","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/personale-qualificato-scarseggia\/","title":{"rendered":"Se il personale qualificato scarseggia"},"content":{"rendered":"<h2><strong>Circa 90 000 PMI in Svizzera sono seriamente interessate dalla carenza di personale qualificato. Voi cosa fate per contrastarla?<\/strong><\/h2>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2017\/08\/1920x960.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6812\" data-permalink=\"https:\/\/blog.startups.ch\/it\/personale-qualificato-scarseggia\/1920x960\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/08\/1920x960.jpg?fit=1200%2C600&amp;ssl=1\" data-orig-size=\"1200,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1920&amp;#215;960\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/08\/1920x960.jpg?fit=1200%2C600&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/08\/1920x960.jpg?fit=1200%2C600&amp;ssl=1\" class=\"alignnone size-full wp-image-6812\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2017\/08\/1920x960.jpg?resize=1200%2C600&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"600\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p>La prosperit\u00e0 di un&#8217;impresa e la sua capacit\u00e0 di reagire rapidamente alle sfide ed essere innovativa dipendono in larga misura dalla qualit\u00e0 dei suoi collaboratori. Trovare personale specializzato adatto, per\u00f2, non \u00e8 sempre cos\u00ec facile. In base allo <a href=\"https:\/\/www.credit-suisse.com\/ch\/it\/unternehmen\/unternehmen-unternehmer\/aktuell\/wenn-fachkraefte-knapp-sind.html\" target=\"_blank\" rel=\"noopener\">studio Credit Suisse sulle PMI<\/a> di quest&#8217;anno, pi\u00f9 della met\u00e0 delle PMI svizzere che reclutano personale ha difficolt\u00e0 a trovare candidati adatti per i posti vacanti.<\/p>\n<p>Circa un quarto delle imprese intervistate \u00e8 seriamente colpito dalla carenza di personale specializzato; riportando il dato alla Svizzera si ottengono circa 90 000 PMI. Le imprese reagiscono in modo differente a questa sfida. Il reclutamento all&#8217;estero non \u00e8 affatto l&#8217;unica opzione, anche se per la ricerca del personale le aziende pi\u00f9 grandi e quelle situate nelle regioni frontaliere spesso allungano lo sguardo oltre confine per attingere a un serbatoio pi\u00f9 ampio di personale specializzato. Al primo posto tra le strategie volte ad assicurare il fabbisogno di personale qualificato ci sono la formazione e il perfezionamento dei propri collaboratori. Circa l&#8217;80% delle aziende sostiene interventi di formazione al proprio interno, pi\u00f9 della met\u00e0 si occupa di formare apprendisti. Ancora una volta spiccano la qualit\u00e0 del sistema educativo svizzero e la grande importanza attribuita alla formazione professionale duale. Tuttavia, ci sono anche voci critiche: circa un quarto delle aziende interpellate lamenta uno scarso orientamento del sistema educativo alle proprie esigenze. In futuro, un maggiore orientamento dei cicli di formazione al rapido mutare delle esigenze dell&#8217;economia assumer\u00e0 un&#8217;importanza crescente.<\/p>\n<p>Con la digitalizzazione e l&#8217;automazione, cambiano i profili di attivit\u00e0 e nascono nuove professioni. Oggi una PMI su quattro punta sulla digitalizzazione come mezzo per contrastare la carenza di personale qualificato, ma circa il 40% di esse si aspetta che questa evoluzione nei prossimi anni porter\u00e0 a un maggiore fabbisogno di forza lavoro con conoscenze tecniche specifiche.<\/p>\n<p>Un&#8217;altra sfida che le PMI svizzere devono affrontare \u00e8 l&#8217;invecchiamento demografico. Gi\u00e0 nei prossimi cinque-dieci anni la numerosa generazione del baby boom andr\u00e0 in pensione e le aziende, in futuro, dovranno confrontarsi (nel migliore dei casi) con la stagnazione e l&#8217;invecchiamento della forza lavoro. In un contesto di questo tipo, ad esempio, l&#8217;assunzione di lavoratori anziani oltre l&#8217;et\u00e0 di pensionamento \u00e8 evidentemente un&#8217;opzione praticabile, ma finora \u00e8 stata sfruttata solo da meno di un quarto delle PMI intervistate. Tuttavia, le esperienze di molte imprese che percorrono questa strada sono positive. Lo confermano anche i partecipanti alla nostra tavola rotonda, che arricchisce il nostro studio con opinioni ed esperienze provenienti dalla quotidianit\u00e0 delle aziende.<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/www.credit-suisse.com\/ch\/it\/unternehmen\/unternehmen-unternehmer\/aktuell\/wenn-fachkraefte-knapp-sind.html\" target=\"_blank\" rel=\"noopener\">\u00bb Credit Suisse \/ Imprenditore<\/a><a class=\"postButton\" href=\"https:\/\/secure.startups.it\/it\/default\/index\/index\" target=\"_blank\" rel=\"noopener\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fpersonale-qualificato-scarseggia%2F';\n  addthis_title  = 'Se+il+personale+qualificato+scarseggia';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Circa 90 000 PMI in Svizzera sono seriamente interessate dalla carenza di personale qualificato. Voi cosa fate per contrastarla?<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"class_list":["post-6811","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"views":1250,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-1LR","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=6811"}],"version-history":[{"count":3,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6811\/revisions"}],"predecessor-version":[{"id":6836,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6811\/revisions\/6836"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=6811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=6811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=6811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}