{"id":6495,"date":"2017-06-09T11:00:42","date_gmt":"2017-06-09T09:00:42","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=6495"},"modified":"2017-06-07T11:05:53","modified_gmt":"2017-06-07T09:05:53","slug":"hack-the-city-hackzurich-uniscono-le-forze-promuovere-gli-hackers-del-ticino","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/hack-the-city-hackzurich-uniscono-le-forze-promuovere-gli-hackers-del-ticino\/","title":{"rendered":"Hack the City e HackZurich uniscono le forze per promuovere gli hackers del Ticino"},"content":{"rendered":"<h2><strong>Hack the City (HTC), l\u2019hackathon del Ticino, \u00e8 stato ridisegnato. Un nuovo evento di due giorni con conferenze tecnologiche e tavole rotonde preceder\u00e0 il classico hackathon. Inoltre, Hack the City e HackZurich collaborano per unire maggiormente il Ticino e la citt\u00e0 di Zurigo.<\/strong><\/h2>\n<p><!--more--><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6497\" data-permalink=\"https:\/\/blog.startups.ch\/it\/hack-the-city-hackzurich-uniscono-le-forze-promuovere-gli-hackers-del-ticino\/htc17_featured-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/05\/htc17_featured-1.jpg?fit=1200%2C800&amp;ssl=1\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"htc17_featured-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/05\/htc17_featured-1.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/05\/htc17_featured-1.jpg?fit=1200%2C800&amp;ssl=1\" class=\"aligncenter wp-image-6497 size-large\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2017\/05\/htc17_featured-1-1200x800.jpg?resize=1200%2C800&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"800\" data-recalc-dims=\"1\" \/><\/p>\n<p><span style=\"color: #4d4c4d;\">Il team <a href=\"https:\/\/www.hackthecity.ch\/it\" target=\"_blank\" rel=\"noopener noreferrer\">HTC<\/a> ha lanciato una nuova edizione dell\u2019hackathon offrendo diversi highlights. A partire da quest&#8217;anno, HTC si terr\u00e0 soltanto in due giorni. Nel corso di 40 ore, i partecipanti &#8211; sviluppatori, progettisti, creatori e coloro che sono coinvolti nella tecnologia, nell&#8217;imprenditorialit\u00e0 e nell&#8217;innovazione &#8211; lavoreranno in team per sviluppare prototipi altamente innovativi per applicazioni web, mobile e desktop. L\u2019hackathon inizier\u00e0 sabato 2 settembre alle ore 8:00 e terminer\u00e0 domenica 3 settembre alle ore 17:00. I partecipanti avranno meno tempo di lavoro a disposizione rispetto alle edizioni precedenti. Le regole e i criteri di valutazione saranno adeguati di conseguenza. La registrazione per l&#8217;HTC 2017 \u00e8 aperta.<\/span><\/p>\n<h3><strong>Hack the City 2017: le novit\u00e0<\/strong><\/h3>\n<p><span style=\"color: #4d4c4d;\">Prima dell\u2019hackathon, il team HTC ha organizzato un evento di due giorni (gioved\u00ec 31 agosto e venerd\u00ec 1 settembre) dedicato a conferenze tecnologiche e a tavole rotonde. I relatori forniranno informazioni ed approfondimenti sugli eventi pi\u00f9 recenti che si sono svolti nell&#8217;industria digitale. I partecipanti di HTC avranno cos\u00ec la possibilit\u00e0 di essere ispirati e stimolati dagli ospiti e dagli oratori.<\/span><\/p>\n<p><span style=\"color: #4d4c4d;\">In aggiunta, HTC ha unito le forze con <a href=\"http:\/\/www.hackzurich.com\" target=\"_blank\" rel=\"noopener noreferrer\">HackZurich<\/a>, uno dei pi\u00f9 grandi hackathon d&#8217;Europa che raduna pi\u00f9 di 550 talenti tecnologici da oltre 50 paesi. L\u2019obiettivo di questa collaborazione \u00e8 di avvicinare ulteriormente il Ticino e la citt\u00e0 di Zurigo. Grazie a questa collaborazione, gli hackers della Svizzera italiana avranno ora l&#8217;opportunit\u00e0 di viaggiare a nord per partecipare al Digital festival in settembre. HackZurich premier\u00e0 il vincitore del premio HTC17 con una \u201cwild card\u201d per il Digital festival.<\/span><\/p>\n<p><span style=\"color: #4d4c4d;\">Questo sforzo congiunto consentir\u00e0 a HTC di collegare i suoi talenti con potenziali sostenitori, team e investitori.<\/span><\/p>\n<p><span style=\"color: #4d4c4d;\">&#8220;Questa collaborazione \u00e8 un primo passo per avvicinare ulteriormente due realt\u00e0 come il Ticino e Zurigo. Si tratta di una grande opportunit\u00e0 per gli sviluppatori della Svizzera italiana. In questa maniera potranno farsi notare e costruire una rete di contatti con i loro coetanei della Svizzera tedesca\u201d, afferma Ryan Vannin, Organizzatore e promotore di Hack the City.<\/span><\/p>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6278\" data-permalink=\"https:\/\/blog.startups.ch\/it\/linteresse-per-le-start-up-in-ticino-sta-aumentando\/schermata-2017-04-05-alle-16-59-53\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/04\/Schermata-2017-04-05-alle-16.59.53.png?fit=198%2C198&amp;ssl=1\" data-orig-size=\"198,198\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Schermata 2017-04-05 alle 16.59.53\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/04\/Schermata-2017-04-05-alle-16.59.53.png?fit=198%2C198&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/04\/Schermata-2017-04-05-alle-16.59.53.png?fit=198%2C198&amp;ssl=1\" class=\"size-full wp-image-6278 alignleft\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2017\/04\/Schermata-2017-04-05-alle-16.59.53.png?resize=198%2C198&#038;ssl=1\" alt=\"\" width=\"198\" height=\"198\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/04\/Schermata-2017-04-05-alle-16.59.53.png?w=198&amp;ssl=1 198w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/04\/Schermata-2017-04-05-alle-16.59.53.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" data-recalc-dims=\"1\" \/><\/p>\n<p>Startupticker \u00e8 la piattaforma online per giovani imprenditori, innovatori e Supporter. Il centro informazioni incrementa il grado di conoscenza delle Startup svizzere, promuove quelle gi\u00e0 in vita e porta la variopinta scena delle Startup svizzere alla luce della ribalta.<\/p>\n<p>Ogni giorno il portale delle notizie d\u00e0 voce ai successi delle giovani imprese, alle offerte di supporto, quali premi e programmi di incentivazione, nonch\u00e9 agli eventi e alle opportunit\u00e0 di formazione imminenti. Le news e gli eventi pi\u00f9 importanti della settimana vengono riepilogati il venerd\u00ec nella Newsletter settimanale.<\/p>\n<p><a href=\"http:\/\/www.startupticker.ch\/subscribe\" target=\"_blank\" rel=\"noopener noreferrer\">Abbonati ora<\/a>\u00a0alla Newsletter di Startupticket.ch!<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/startups.it\/it\/prepararsi\/colloquiopersonale\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/secure.startups.it\/it\/default\/index\/index\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fhack-the-city-hackzurich-uniscono-le-forze-promuovere-gli-hackers-del-ticino%2F';\n  addthis_title  = 'Hack+the+City+e+HackZurich+uniscono+le+forze+per+promuovere+gli+hackers+del+Ticino';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Hack the City (HTC), l\u2019hackathon del Ticino, \u00e8 stato ridisegnato. Un nuovo evento di due giorni con conferenze tecnologiche e tavole rotonde preceder\u00e0 il classico hackathon. Inoltre, Hack the City e HackZurich collaborano per unire maggiormente il Ticino e la citt\u00e0 di Zurigo.<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"Hack the City e HackZurich uniscono le forze per promuovere gli hackers del Ticino!","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691,3,722],"tags":[1265,1264,1263,1259,1261,1262,1266,1260,1267],"class_list":["post-6495","post","type-post","status-publish","format-standard","hentry","category-curiosita","category-domande-generali","category-eventi","tag-collaborazione-hack-the-city-con-hack-zurich","tag-edizione-2017-hack-the-city","tag-hack-the-city","tag-hack-the-city-2017","tag-hack-the-city-e-hackzurich","tag-hack-zurich","tag-premio-hack-the-city","tag-programma-hack-the-city","tag-startupticket"],"jetpack_publicize_connections":[],"views":2092,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-1GL","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=6495"}],"version-history":[{"count":9,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6495\/revisions"}],"predecessor-version":[{"id":6501,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6495\/revisions\/6501"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=6495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=6495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=6495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}