{"id":6149,"date":"2017-03-21T09:30:04","date_gmt":"2017-03-21T08:30:04","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=6149"},"modified":"2017-03-21T10:57:34","modified_gmt":"2017-03-21T09:57:34","slug":"8-tecnologie-che-cambieranno-il-nostro-futuro","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/8-tecnologie-che-cambieranno-il-nostro-futuro\/","title":{"rendered":"8 Tecnologie che cambieranno il nostro futuro"},"content":{"rendered":"<h2><strong>Nuove tecnologie mettono i dipendenti delle aziende svizzere di fronte a importanti sfide. Dall\u2019intelligenza artificiale passando dai droni e i robot fino alla stampa 3D. Le sfide legate al futuro sono molteplici e l\u2019essere umano dovr\u00e0 giocoforza adattarsi a questi cambiamenti.<\/strong><\/h2>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6150\" data-permalink=\"https:\/\/blog.startups.ch\/it\/8-tecnologie-che-cambieranno-il-nostro-futuro\/teens-629046_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/02\/teens-629046_1280.jpg?fit=1280%2C853&amp;ssl=1\" data-orig-size=\"1280,853\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"teens-629046_1280\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/02\/teens-629046_1280.jpg?fit=1200%2C800&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/02\/teens-629046_1280.jpg?fit=1200%2C800&amp;ssl=1\" class=\"aligncenter size-large wp-image-6150\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2017\/02\/teens-629046_1280-1200x800.jpg?resize=1200%2C800&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/02\/teens-629046_1280.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2017\/02\/teens-629046_1280.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/p>\n<p>La Posta sta testando dei robot e dei droni per la consegna dei pacchi, Amazon ha introdotto il \u201cDash Replenishment Button\u201d per velocizzare e rendere pi\u00f9 facile l\u2019ordinazione di materiale e nelle fabbriche cinesi i dipendenti sono sempre pi\u00f9 sostituiti da Robot. Questi eventi indicano che l\u2019evoluzione tecnologica sta cambiando e cambier\u00e0 molte industrie nei prossimi anni.<\/p>\n<p>Otto tecnologie specifiche avranno un grande effetto:<\/p>\n<p><strong>Intelligenza Artificiale<br \/>\n<\/strong>I computer potrebbero presto assumere i compiti che in precedenza erano in grado di fare solo le persone. Essi potrebbero quindi operare in settori come quello bancario e degli investimenti, nella diagnosi medica o nella logistica di grandi aziende.<\/p>\n<p><strong>Realt\u00e0 Aumentata<br \/>\n<\/strong>L\u2019esempio migliore per comprendere la tecnologia della realt\u00e0 aumentata \u00e8 \u201cPokemon Go\u201d. In questo caso i giocatori sono in grado di catturare personaggi virtuali e di fantasia che appaiono \u2013 grazie appunto alla tecnologia della realt\u00e0 aumentata \u2013 nella realt\u00e0. In sintesi il mondo digitale e virtuale si fonde con quello reale permettendo ai giocatori di muovendosi nella realt\u00e0 catturando personaggi del mondo virtuale.<\/p>\n<p><strong>Blockchain<br \/>\n<\/strong>La tecnologia del Blockchain viene utilizzata nella famosa criptovaluta del \u201cBitcoin\u201d. Attualmente la tecnologia \u00e8 ancora molto vaga e non \u00e8 ancora chiaro quali siano le soluzioni che possano prevalere nel futuro.<\/p>\n<p><strong>Droni<br \/>\n<\/strong>Amazon, Google e anche la Posta Svizzera stanno pensando di utilizzare droni a controllo remoto per la consegna dei pacchi. Secondo i piani della Posta entro massimo cinque anni dovremmo gi\u00e0 vedere i primi pacchi gialli volare al di sopra delle nostre teste.<\/p>\n<p><strong>Internet delle Cose<br \/>\n<\/strong>Il termine \u201cInternet delle cose\u201d si riferisce all\u2019estensione dell\u2019Internet al mondo degli oggetti e delle cose. Gli oggetti, i prodotti e i luoghi fisici assumono sempre di pi\u00f9 il ruolo di &#8220;dispositivo digitale intelligente&#8221;, i quali grazie all\u2019utilizzo di sensori e attuatori riescono a rendersi riconoscibili, ad acquisire intelligenza e comunicare tra loro. Un esempio potrebbe essere un frigorifero in grado di percepire l\u2019assenza di un prodotto e automaticamente ordinare lo stesso.<\/p>\n<p><strong>Robotica<br \/>\n<\/strong>In questo caso si possono identificare due tipi di robot: i robot software e i robot hardware. I primi sono essenzialmente un sinonimo della gi\u00e0 citata Intelligenza Artificiale. I secondi invece possono essere compresi come una macchina in grado di percepire una variet\u00e0 di compiti, come ad esempio nella produzione automobilistica e nelle professioni di cura.<\/p>\n<p><strong>Realt\u00e0 Virtuale<br \/>\n<\/strong>La realt\u00e0 virtuale \u00e8 la rappresentazione e la percezione della realt\u00e0 in tempo reale in un ambiente completamente virtuale generato da un computer. In confronto alla realt\u00e0 aumentata non c&#8217;\u00e8 alcuna promiscuit\u00e0 con il mondo reale e il tutto rimane quindi digitale.<\/p>\n<p><strong>Stampa 3D<br \/>\n<\/strong>La Stampa 3D consente di creare oggetti tridimensionali mediante produzione additiva partendo da un modello 3D digitale. Quest\u2019ultimo viene solitamente sviluppato grazie a software speciali e in seguito realizzato \u2013 strato dopo strato \u2013 tramite l\u2019utilizzo di stampanti speciali. In futuro, la tecnologia potrebbe essere utilizzata anche nella medicina, ad esempio per la creazione e la sostituzione di pelle a seguito di ustioni.<\/p>\n<p>Credits: <a href=\"http:\/\/m.20min.ch\/finance\/news\/story\/30887235\" target=\"_blank\">8 Technologien, die unsere Zukunft ver\u00e4ndern &#8211; 20 Minuten<\/a>.<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/startups.it\/it\/prepararsi\/colloquiopersonale\/\" target=\"_blank\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/secure.startups.it\/it\/default\/index\/index\" target=\"_blank\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2F8-tecnologie-che-cambieranno-il-nostro-futuro%2F';\n  addthis_title  = '8+Tecnologie+che+cambieranno+il+nostro+futuro';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuove tecnologie mettono i dipendenti delle aziende svizzere di fronte a importanti sfide. Dall\u2019intelligenza artificiale passando dai droni e i robot fino alla stampa 3D. Le sfide legate al futuro sono molteplici e l\u2019essere umano dovr\u00e0 giocoforza adattarsi a questi cambiamenti.<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"8 Tecnologie che cambieranno il nostro futuro!\r\n#tecnologie #futuro #lavoro","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691,3],"tags":[1095,1099,1098,1096,1097,1100,1101],"class_list":["post-6149","post","type-post","status-publish","format-standard","hentry","category-curiosita","category-domande-generali","tag-8-tecnologie","tag-nuove-tecnologie","tag-tecnologie-che-cambieranno-il-mondo","tag-tecnologie-del-futuro","tag-tecnologie-dirompenti","tag-trend-del-futuro","tag-trend-tecnologici"],"jetpack_publicize_connections":[],"views":1945,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-1Bb","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=6149"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6149\/revisions"}],"predecessor-version":[{"id":6221,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/6149\/revisions\/6221"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=6149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=6149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=6149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}