{"id":563,"date":"2010-07-26T08:00:25","date_gmt":"2010-07-26T06:00:25","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=563"},"modified":"2014-03-24T14:44:11","modified_gmt":"2014-03-24T13:44:11","slug":"protezione-della-proprieta-intellettuale-tutela-del-design","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/protezione-della-proprieta-intellettuale-tutela-del-design\/","title":{"rendered":"Protezione della propriet\u00e0 intellettuale. La tutela del design."},"content":{"rendered":"<h4>Se lei ha concepito un oggetto che risulta particolarmente adocchiabile, sinuoso nelle forme oppure originale, sussiste il pericolo che questo oggetto venga copiato dalla concorrenza. Per mezzo della tutela della propriet\u00e0 intellettuale ci si pu\u00f2 proteggere da tali copie. Sono da qualificare come <strong>design<\/strong> gli oggetti o le parti di oggetti che presentano una disposizione speciale di linee, colori, superfici, profili o materiali. Tra le altre cose vengono presi in considerazione i mobili.<\/h4>\n<p>\u00c9 per esempio possibile tutelare il design di una sedia dalla forma particolare. Premessa fondamentale \u00e8 che il design sia <strong>nuovo<\/strong> e disponga di <strong>caratteristiche ben determinate<\/strong>. L\u2019oggetto \u00e8 nuovo, quando il pubblico non \u00e8 gi\u00e0 a conoscenza di un oggetto identico. La particolarit\u00e0 \u00e8 data non appena l\u2019oggetto, frutto del dispendio intellettuale del designer, mostra una certa originalit\u00e0 e considerabilit\u00e0. Ovviamente il design non pu\u00f2 essere illegale. Per proteggere il design non \u00e8 necessario che lo si abbia progettato in prima persona. In ogni caso bisogna detenerne i diritti.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fprotezione-della-proprieta-intellettuale-tutela-del-design%2F';\n  addthis_title  = 'Protezione+della+propriet%C3%A0+intellettuale.+La+tutela+del+design.';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Se lei ha concepito un oggetto che risulta particolarmente adocchiabile, sinuoso nelle forme oppure originale, sussiste il pericolo che questo oggetto venga copiato dalla concorrenza. Per mezzo della tutela della propriet\u00e0 intellettuale ci si pu\u00f2 proteggere da tali copie. Sono da qualificare come design gli oggetti o le parti di oggetti che presentano una disposizione [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[238,194,239],"class_list":["post-563","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-design","tag-protezione-del-design","tag-protezione-della-proprieta-intellettuale"],"jetpack_publicize_connections":[],"views":1971,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-95","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=563"}],"version-history":[{"count":7,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/563\/revisions"}],"predecessor-version":[{"id":3854,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/563\/revisions\/3854"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}