{"id":5297,"date":"2016-07-08T09:15:53","date_gmt":"2016-07-08T07:15:53","guid":{"rendered":"https:\/\/www.startups.ch\/it\/blog\/?p=5297"},"modified":"2016-07-07T15:45:40","modified_gmt":"2016-07-07T13:45:40","slug":"finanziamento-startup-capitale-terzi","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/finanziamento-startup-capitale-terzi\/","title":{"rendered":"Finanziamento per startup: il capitale di terzi"},"content":{"rendered":"<h2>Le imprese hanno essenzialmente due fonti di finanziamento: il capitale proprio e il capitale di terzi. In quest\u2019ultima categoria rientrano i finanziamenti che istituti o societ\u00e0 di credito \u2013 spesso banche \u2013 concedono alle aziende.<\/h2>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2016\/07\/Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5298\" data-permalink=\"https:\/\/blog.startups.ch\/it\/finanziamento-startup-capitale-terzi\/businesses-that-can-benefit-from-partnering-with-a-customer-financing-enterprise\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/07\/Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise.jpg?fit=690%2C262&amp;ssl=1\" data-orig-size=\"690,262\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/07\/Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise.jpg?fit=300%2C114&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/07\/Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise.jpg?fit=690%2C262&amp;ssl=1\" class=\"size-full wp-image-5298 aligncenter\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/it\/blog\/wp-content\/uploads\/2016\/07\/Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise.jpg?resize=690%2C262&#038;ssl=1\" alt=\"Finanziamento per startup: il capitale di terzi\" width=\"690\" height=\"262\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/07\/Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise.jpg?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/07\/Businesses-That-Can-Benefit-From-Partnering-With-a-Customer-Financing-Enterprise.jpg?resize=300%2C114&amp;ssl=1 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<h3>Il capitale di terzi<\/h3>\n<p>I crediti concessi dagli istituti di credito rientrano sotto la categoria dei capitali ottenuti in prestito da terzi. I finanziamenti effettuati con <strong>capitale di terzi<\/strong> corrispondono essenzialmente ai debiti delle aziende verso banche, finanziatori o altri enti esterni. A seconda della durata il capitale di terzi pu\u00f2 essere suddiviso in 3 categorie: debiti a breve termine (&lt; 1 anno), a medio termine (1-5 anni) oppure a lungo termine (&gt; 5 anni). L\u2019ottenimento di un prestito da un istituto di credito dipende inoltre dalla tipologia del prodotto richiesto.<\/p>\n<h3>Vantaggi e Svantaggi<\/h3>\n<p>Tra i principali vantaggi del <strong>capitale di terzi<\/strong> vi \u00e8 l\u2019aspetto della \u201cnon-propriet\u00e0\u201d. I finanziamenti esterni, a differenza del capitale proprio, non hanno alcun diritto sulla propriet\u00e0 dell\u2019azienda. La relazione tra l\u2019istituto di credito e l\u2019azienda termina con la remunerazione del prestito. Inoltre, gli istituti di credito non hanno voce in capitolo nelle decisioni aziendali e gli interessi possono essere dedotti dalle tasse.\u00a0Al contrario, tra i principali svantaggi vi \u00e8 l\u2019obbligo di remunerazione \/ ammortizzazione del prestito entro un determinato periodo stabilito dal creditore (indipendentemente dal risultato economico della gestione). In condizioni difficili e negative, ci\u00f2 potrebbe causare problemi di liquidit\u00e0 per l\u2019azienda.<\/p>\n<h3>Documentazione<\/h3>\n<p>Prima di presentare una richiesta di credito \u00e8 fondamentale conoscere tutti i documenti necessari. Un Business Plan chiaro e convincente \u00e8 la base per l\u2019ottenimento di un finanziamento. Esso deve dimostrare la validit\u00e0 di un progetto \/ di un\u2019iniziativa imprenditoriale e fornire garanzie adeguate affinch\u00e9 l\u2019esposizione al rischio sia minima. Ogni istituto di credito richiede \u2013 oltre al Business Plan &#8211; documenti individuali e la mole degli stessi pu\u00f2 variare notevolmente. A tale proposito il consiglio \u00e8 di prestare attenzione alle procedure e alla documentazione specifica richiesta dall\u2019istituto cui si rivolge l\u2019azienda.<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/startups.it\/it\/prepararsi\/colloquiopersonale\/\" target=\"_blank\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/secure.startups.it\/it\/default\/index\/index\" target=\"_blank\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Ffinanziamento-startup-capitale-terzi%2F';\n  addthis_title  = 'Finanziamento+per+startup%3A+il+capitale+di+terzi';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le imprese hanno essenzialmente due fonti di finanziamento: il capitale proprio e il capitale di terzi. In quest\u2019ultima categoria rientrano i finanziamenti che istituti o societ\u00e0 di credito \u2013 spesso banche \u2013 concedono alle aziende.<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"Finanziamento per startup: il capitale di terzi\r\n#startup #finanziamento #credito","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[787,468,785,254,789,786,788,739],"class_list":["post-5297","post","type-post","status-publish","format-standard","hentry","category-curiosita","tag-banca","tag-capitale","tag-credito","tag-finanziamento","tag-istituto-di-credito","tag-prestito","tag-societa-di-credito","tag-startup"],"jetpack_publicize_connections":[],"views":1511,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-1nr","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/5297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=5297"}],"version-history":[{"count":5,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/5297\/revisions"}],"predecessor-version":[{"id":5300,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/5297\/revisions\/5300"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=5297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=5297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=5297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}