{"id":4830,"date":"2016-01-20T15:26:03","date_gmt":"2016-01-20T14:26:03","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=4830"},"modified":"2016-01-18T15:26:12","modified_gmt":"2016-01-18T14:26:12","slug":"studio-gen-2016-la-svizzera-tra-i-migliori-paesi-per-start-up","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/studio-gen-2016-la-svizzera-tra-i-migliori-paesi-per-start-up\/","title":{"rendered":"Studio GEN 2016\u2013 La Svizzera tra i migliori paesi per start-up"},"content":{"rendered":"<p><strong>Quale paese possiede il miglior ecosistema imprenditoriale? Un gruppo di ricercatori del Global Entrepreneurship and Development Institute (GEDI) di Washington ha deciso di cimentarsi per dare una risposta alla domanda. Secondo il Global Entrepreneurship Index (GEI) 2016 la Svizzera si piazza all\u2019ottavo posto.<\/strong><\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/u2.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4831\" data-permalink=\"https:\/\/blog.startups.ch\/it\/studio-gen-2016-la-svizzera-tra-i-migliori-paesi-per-start-up\/u2\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/u2.png?fit=561%2C361&amp;ssl=1\" data-orig-size=\"561,361\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"u2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/u2.png?fit=300%2C193&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/u2.png?fit=561%2C361&amp;ssl=1\" class=\"alignnone  wp-image-4831\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/u2.png?resize=577%2C371\" alt=\"u2\" width=\"577\" height=\"371\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/u2.png?w=561&amp;ssl=1 561w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/u2.png?resize=300%2C193&amp;ssl=1 300w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Si tratta del progetto di punta dell&#8217;Istituto. Il GEI offre uno sguardo dettagliato sullo stato di salute dei vari ecosistemi imprenditoriali nazionali. Il GEDI ha sviluppato una particolare metodologia di indicizzazione che collega le condizioni quadro dei vari paesi con le attitudini imprenditoriali, di capacit\u00e0 e di aspirazione a livello individuale. Il GEI misura la qualit\u00e0 e la portata del processo imprenditoriale di 132 paesi in tutto il mondo. Esso fornisce una cos\u00ec una comprensione sul livello qualitativo e quantitativo dell\u2019imprenditorialit\u00e0 in questi paesi.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>I risultati dell\u2019indice<\/strong><\/p>\n<p>In breve &#8211; al primo posto troviamo gli USA, con un distacco significativo dal secondo classificato, il Canada. Nel vecchio continente a farla da padrone troviamo la Danimarca seguita dalla Svezia, mentre in Sud America il miglior paese risulta essere il Cile. Secondo lo studio il mondo si troverebbe al 52% delle sue capacit\u00e0 imprenditoriali.<\/p>\n<p><strong>La Svizzera<\/strong><\/p>\n<p>La Svizzera si piazza all\u2019ottavo posto, davanti al Regno Unito e alla Francia. Ottimo risultato se si pensa al successo dell\u2019Hub londinese che cresce di anno in anno! I ricercatori hanno inoltre stilato i punti di forza e i punti deboli per ogni paese del ranking. Secondo lo studio in Svizzera ci sono molte start-up con prodotti innovativi e vi \u00e8 una forza lavoro molto qualificata. Tra i punti di forza sono menzionati anche la notevole capacit\u00e0 degli attori di farsi carico dei rischi legati alle attivit\u00e0 imprenditoriali ed una buona disponibilit\u00e0 di fondi privati. Tra i punti deboli invece troviamo per esempio la mancata capacit\u00e0 dei singoli nell\u2019identificare il potenziale della propria attivit\u00e0 o una mancanza di capacit\u00e0 imprenditoriale.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La mappa con il Ranking completo<\/strong><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/Untitled.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4832\" data-permalink=\"https:\/\/blog.startups.ch\/it\/studio-gen-2016-la-svizzera-tra-i-migliori-paesi-per-start-up\/untitled-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/Untitled.png?fit=605%2C612&amp;ssl=1\" data-orig-size=\"605,612\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Untitled\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/Untitled.png?fit=296%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/Untitled.png?fit=605%2C612&amp;ssl=1\" class=\"alignnone size-full wp-image-4832\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/Untitled.png?resize=605%2C612\" alt=\"Untitled\" width=\"605\" height=\"612\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/Untitled.png?w=605&amp;ssl=1 605w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2016\/01\/Untitled.png?resize=296%2C300&amp;ssl=1 296w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p>Source: GIN 2016<br \/>\n<a class=\"postButton\" href=\"http:\/\/thegedi.org\/2016-global-entrepreneurship-index\" target=\"_blank\">\u00bb GIN 2016<\/a><a class=\"postButton\" href=\"https:\/\/startups.ch\/it\/contatto-servizio\/contatti\" target=\"_blank\">\u00bb Contattaci e costituisci <\/a><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fstudio-gen-2016-la-svizzera-tra-i-migliori-paesi-per-start-up%2F';\n  addthis_title  = 'Studio+GEN+2016%E2%80%93+La+Svizzera+tra+i+migliori+paesi+per+start-up';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Quale paese possiede il miglior ecosistema imprenditoriale? Un gruppo di ricercatori del Global Entrepreneurship and Development Institute (GEDI) di Washington ha deciso di cimentarsi per dare una risposta alla domanda. Secondo il Global Entrepreneurship Index (GEI) 2016 la Svizzera si piazza all\u2019ottavo posto.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691],"tags":[],"class_list":["post-4830","post","type-post","status-publish","format-standard","hentry","category-curiosita"],"jetpack_publicize_connections":[],"views":1622,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-1fU","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=4830"}],"version-history":[{"count":4,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4830\/revisions"}],"predecessor-version":[{"id":4834,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4830\/revisions\/4834"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=4830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=4830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=4830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}