{"id":469,"date":"2010-07-02T11:00:36","date_gmt":"2010-07-02T09:00:36","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=469"},"modified":"2014-03-24T14:44:12","modified_gmt":"2014-03-24T13:44:12","slug":"risparmiare-sulle-imposte-al-momento-della-costituzione-della-ditta","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/risparmiare-sulle-imposte-al-momento-della-costituzione-della-ditta\/","title":{"rendered":"Risparmiare sulle imposte al momento della costituzione della propria azienda."},"content":{"rendered":"<h4>Al momento della costituzione di una ditta ci si pongono tante domande giuridiche ed economicoaziendali. All\u2019inizio gli aspetti fiscali vengono spesso tralasciati. Ad esercizio gi\u00e0 in corso protebbe essere in alcune circostanze troppo tardi per un\u2019ottimizzazione fiscale.<\/h4>\n<p>Ci si pongono domande in ambito tributario gi\u00e0 al momento della <strong>scelta della forma giuridica<\/strong> (ditta individuale, Sagl, SA o societ\u00e0 a nome collettivo), poich\u00e8 in Svizzera non esiste un&#8217;imposizione fiscale per l\u2019impresa che non tenga conto della forma giuridica. Gli utili realizzati dalle persone giuridiche (SA e Sagl) vengono privilegiati nei confronti degli utili realizzati dalle imprese di persone (ditta individuale e societ\u00e0 a nome collettivo).<\/p>\n<p>La forma giuridica determina, anche nella <strong>scelta della sede<\/strong>, il luogo d\u2019imposizione fiscale. Il reddito e gli utili vengono tassati a seconda della forma giuridica in luoghi differenti qualora il domicilio personale non si trovi nello stesso posto della sede d\u2019affari. L\u2019impresa che \u00e8 indipendente nella scelta della sede ha la possibilit\u00e0 di scegliere il cantone o il comune con l\u2019aliquota d\u2019imposta pi\u00f9 bassa. Alcuni cantoni concedono anche vantaggi fiscali per le nuove imprese che s\u2019insediano.<\/p>\n<p>Da considerare sono pure le imposte in riferimento alla previdenza professionale (2\u00b0 pilastro), ai contributi AVS, all\u2019imposta sul valore aggiunto (IVA) e all\u2019imposta anticipata.<\/p>\n<p>La soluzione fiscale ottimale dipende sempre dalla situazione concreta. \u00c8 consigliabile effettuare accurati chiarimenti che permettono\u00a0nel tempo\u00a0di risparmiare tanti soldi. Questo va incontro ai giovani imprenditori.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Frisparmiare-sulle-imposte-al-momento-della-costituzione-della-ditta%2F';\n  addthis_title  = 'Risparmiare+sulle+imposte+al+momento+della+costituzione+della+propria+azienda.';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Al momento della costituzione di una ditta ci si pongono tante domande giuridiche ed economicoaziendali. All\u2019inizio gli aspetti fiscali vengono spesso tralasciati. Ad esercizio gi\u00e0 in corso protebbe essere in alcune circostanze troppo tardi per un\u2019ottimizzazione fiscale. Ci si pongono domande in ambito tributario gi\u00e0 al momento della scelta della forma giuridica (ditta individuale, Sagl, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24,8],"tags":[90,217,733,216,40,91,215,39,89,731,730,78,734],"class_list":["post-469","post","type-post","status-publish","format-standard","hentry","category-costituzione","category-imposte-e-assicurazioni-sociali","tag-aliquota-dimposta","tag-avs","tag-costituzione","tag-ditta-inviduale","tag-imposte","tag-imposte-cantonali","tag-imposte-degli-utili","tag-iva","tag-persone-giuridiche","tag-sa","tag-sagl","tag-societa-di-persone","tag-societa-in-nome-collettivo"],"jetpack_publicize_connections":[],"views":2421,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-7z","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=469"}],"version-history":[{"count":16,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/469\/revisions"}],"predecessor-version":[{"id":3860,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/469\/revisions\/3860"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}