{"id":4513,"date":"2015-08-06T14:32:22","date_gmt":"2015-08-06T12:32:22","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=4513"},"modified":"2015-08-06T14:33:04","modified_gmt":"2015-08-06T12:33:04","slug":"gafi-nuovi-obblighi-legali-per-le-spa-le-srl-e-le-societa-cooperative-svizzere-a-partire-dal-1-luglio-2015","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/gafi-nuovi-obblighi-legali-per-le-spa-le-srl-e-le-societa-cooperative-svizzere-a-partire-dal-1-luglio-2015\/","title":{"rendered":"GAFI &#8211; nuovi obblighi legali per le Sa, le Sagl e le societ\u00e0 cooperative svizzere a partire dal 1\u00b0 luglio 2015"},"content":{"rendered":"<p><strong>Per contrastare il riciclaggio di denaro e il finanziamento del terrorismo nel 2012 le raccomandazioni del Groupe d\u2019action financi\u00e8re (Gruppo d\u2019Azione Finanziaria Internazionale) (GAFI) sono state sottoposte a revisione. Il Consiglio Nazionale e il Consiglio degli Stati hanno prontamente inserito tali raccomandazioni nella legislazione nazionale.<\/strong><\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/06\/Fotolia_Richter.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4417\" data-permalink=\"https:\/\/blog.startups.ch\/it\/scioglimento-e-chiusura-dellassociazione\/attachment\/4417\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/06\/Fotolia_Richter.jpg?fit=690%2C314&amp;ssl=1\" data-orig-size=\"690,314\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;women hand and Calculator isolated on white&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Africa Studio - Fotolia&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;???????????????????????????????????????????&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"???????????????????????????????????????????\" data-image-description=\"&lt;p&gt;women hand and Calculator isolated on white&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/06\/Fotolia_Richter.jpg?fit=300%2C136&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/06\/Fotolia_Richter.jpg?fit=690%2C314&amp;ssl=1\" class=\"alignnone size-full wp-image-4417\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/06\/Fotolia_Richter.jpg?resize=690%2C314\" alt=\"???????????????????????????????????????????\" width=\"690\" height=\"314\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/06\/Fotolia_Richter.jpg?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/06\/Fotolia_Richter.jpg?resize=300%2C136&amp;ssl=1 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p>La Legge federale per l\u2019attuazione delle raccomandazioni del Groupe d\u2019action financi\u00e8re, sottoposte a revisione nel 2012, entra in vigore parzialmente il 1\u00b0 luglio 2015 (legge GAFI). Le nuove disposizioni di legge\u00a0si applicano soltanto a societ\u00e0 svizzere private e ai loro azionisti. Pertanto le novazioni non riguardano le imprese quotate in Borsa.<\/p>\n<p><strong>Obbligo di dichiarazione per azioni al portatore<\/strong><\/p>\n<p>Di recente \u00e8 stato introdotto nell\u2019art. 697i del Diritto delle obbligazioni (OR) l\u2019obbligo di dichiarazione per le azioni al portatore. Chi acquista azioni al portatore non quotate in Borsa deve comunicare alla societ\u00e0 i propri dati personali entro un mese. Inoltre deve identificarsi presso la Societ\u00e0. Questo requisito si applica senza limitazioni, quindi dall\u2019acquisto anche di una azione al portatore.<\/p>\n<p>D\u2019ora in poi la societ\u00e0 deve tenere un elenco degli azionisti al portatore con i relativi dati personali. In caso di mancato adempimento dell\u2019obbligo di dichiarazione vengono sospesi i diritti sociali e patrimoniali. Inoltre la mancata dichiarazione ha anche ripercussioni penali. Pertanto viene punito con un\u2019ammenda chi intenzionalmente non adempie all\u2019obbligo di dichiarazione o non tiene correttamente il registro delle azioni. In virt\u00f9 di questi provvedimenti l\u2019azione al portatore diventa di fatto un\u2019azione nominativa.<\/p>\n<p>Anche chi possiede gi\u00e0 azioni al portatore deve adempiere all\u2019obbligo di dichiarazione. La scadenza prevista \u00e8 il 1\u00b0 gennaio 2016.<\/p>\n<p><strong>Obbligo di dichiarazione del beneficiario<\/strong><\/p>\n<p>Qualora una persona acquisisca il 25% o pi\u00f9 di azioni di una Spa svizzera privata, tale acquirente deve analogamente comunicare i dati personali del soggetto per il quale opera in ogni caso (beneficiario) (vale per azioni al portatore e per azioni nominative). La dichiarazione alla societ\u00e0 interessata deve avvenire entro un mese.<\/p>\n<p><strong>\u00a0Nuovo obbligo di residenza<\/strong><\/p>\n<p>Inoltre un membro del consiglio di amministrazione o un direttore deve essere residente in Svizzera. Questa persona deve avere accesso al registro delle azioni o all\u2019elenco delle azioni al portatore.<\/p>\n<p>Anche nel caso della Sagl \u00e8 stata introdotta la normative secondo cui il beneficiario di una quota maggiore del 25% delle quote sociali deve essere identificato. Analogamente la persona autorizzata a firmare deve essere amministratore o direttore.<\/p>\n<p>Per l\u2019adeguamento dello statuto si considera un termine transitorio di due anni.<\/p>\n<p><strong>Siamo a vostra disposizione per assolvere gli incarichi amministrativi relativi alle modifiche della legge. Per ulteriori informazioni chiamare il numero 0800 550 000<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fgafi-nuovi-obblighi-legali-per-le-spa-le-srl-e-le-societa-cooperative-svizzere-a-partire-dal-1-luglio-2015%2F';\n  addthis_title  = 'GAFI+%26%238211%3B+nuovi+obblighi+legali+per+le+Sa%2C+le+Sagl+e+le+societ%C3%A0+cooperative+svizzere+a+partire+dal+1%C2%B0+luglio+2015';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Per contrastare il riciclaggio di denaro e il finanziamento del terrorismo nel 2012 le raccomandazioni del Groupe d\u2019action financi\u00e8re (Gruppo d\u2019Azione Finanziaria Internazionale) (GAFI) sono state sottoposte a revisione. Il Consiglio Nazionale e il Consiglio degli Stati hanno prontamente inserito tali raccomandazioni nella legislazione nazionale.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691,3],"tags":[],"class_list":["post-4513","post","type-post","status-publish","format-standard","hentry","category-curiosita","category-domande-generali"],"jetpack_publicize_connections":[],"views":1696,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-1aN","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=4513"}],"version-history":[{"count":4,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4513\/revisions"}],"predecessor-version":[{"id":4517,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4513\/revisions\/4517"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=4513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=4513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=4513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}