{"id":4252,"date":"2015-02-03T15:14:15","date_gmt":"2015-02-03T14:14:15","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=4252"},"modified":"2015-02-03T15:17:29","modified_gmt":"2015-02-03T14:17:29","slug":"banca-cantonale-berna-bekb-detiene-prima-piattaforma-per-commercio-azioni-start-up-alto-rischio","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/banca-cantonale-berna-bekb-detiene-prima-piattaforma-per-commercio-azioni-start-up-alto-rischio\/","title":{"rendered":"La Banca Cantonale di Berna (BEKB) detiene la prima piattaforma per il commercio di azioni di start-up con alto rischio"},"content":{"rendered":"<p><strong>La BEKB ha ampliato il proprio segmento OTC-X con la sezione &#8220;Early Stage&#8221;, in modo da facilitare lo scambio ed il commercio di azioni appartenenti a start-up con alto rischio o di aziende in rapida crescita. Il giorno del 19 gennaio 2015, ovvero il giorno dell\u2019apertura della nuova sezione, sono state messe in circolazione le azioni di Nootrie SA, una start-up attiva nel settore della produzione di bevande.<\/strong><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/02\/security-risk-thumb.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4253\" data-permalink=\"https:\/\/blog.startups.ch\/it\/banca-cantonale-berna-bekb-detiene-prima-piattaforma-per-commercio-azioni-start-up-alto-rischio\/security-risk-thumb\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/02\/security-risk-thumb.jpg?fit=690%2C518&amp;ssl=1\" data-orig-size=\"690,518\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"security-risk-thumb\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/02\/security-risk-thumb.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/02\/security-risk-thumb.jpg?fit=690%2C518&amp;ssl=1\" class=\"alignnone size-full wp-image-4253\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/02\/security-risk-thumb.jpg?resize=690%2C518\" alt=\"security-risk-thumb\" width=\"690\" height=\"518\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/02\/security-risk-thumb.jpg?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2015\/02\/security-risk-thumb.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><strong>Piattaforma per il commercio delle azioni di start-up<\/strong><\/p>\n<p>Con la sua nuova offerta, la Banca Cantonale di Berna (BEKB) si orienta alle start-up e alle imprese in rapida crescita che hanno bisogno di finanziamenti durante la loro fase iniziale (&#8220;Early Stage&#8221;). Per quanto riguarda gli investitori, questa nuova offerta \u00e8 stata progettata per coloro che sono disposti a prendere in considerazione rischi elevati, ma che di conseguenza vogliono beneficiare di guadagni significativamente pi\u00f9 elevati alla media. Attualmente il mercato per il finanziamento di start-up si trova in una fase di forte crescita. Secondo un rapporto di Swiss VC, nel 2013, sono stati effettuati dei finanziamenti aziendali per un importo\u00a0di 120 milioni di franchi nella fase \u201ciniziale\u201d di diverse societ\u00e0. In precedenza, non esisteva un mercato secondario trasparente per azioni di societ\u00e0 in\u00a0fase iniziale.<\/p>\n<p>OTC \u00e8 l\u2019acronimo dei mercati &#8220;Over The Counter&#8221; e si riferisce alla negoziazione delle societ\u00e0 non quotate. Questi titoli vengono negoziati al di fuori di borse\u00a0da banche o istituzioni finanziarie e non sono soggetti ad alcuna specifica legge sulle borse. Attualmente, ci sono 175\u2019000 societ\u00e0 anonime in Svizzera, di cui solo 350 sono quotate nelle borse SIX e Berne eXchange BX. Circa 500 aziende non sono quotate in borsa, ma sono negoziate \u201cover the counter\u201d.<\/p>\n<p><strong>Nootrie SA \u00e8 la prima start-up<\/strong><\/p>\n<p>Le prime azioni nella nuova sezione &#8220;early-stage&#8221; appartengono a Nootrie SA, una start-up nel settore della produzione di bevande e di impianti per la produzione di bevande di ogni genere. Nootrie SA sta sviluppando una macchina che utilizza capsule per la preparazione di bevande che vengono commercializzate nel ramo Lifestyle e salute. L\u2019ingresso nel mercato e dunque il lancio del prodotto \u00e8 previsto per la met\u00e0 del 2015 \/ inizio 2016.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fbanca-cantonale-berna-bekb-detiene-prima-piattaforma-per-commercio-azioni-start-up-alto-rischio%2F';\n  addthis_title  = 'La+Banca+Cantonale+di+Berna+%28BEKB%29+detiene+la+prima+piattaforma+per+il+commercio+di+azioni+di+start-up+con+alto+rischio';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La BEKB ha ampliato il proprio segmento OTC-X con la sezione &#8220;Early Stage&#8221;, in modo da facilitare lo scambio ed il commercio di azioni appartenenti a start-up con alto rischio o di aziende in rapida crescita. Il giorno del 19 gennaio 2015, ovvero il giorno dell\u2019apertura della nuova sezione, sono state messe in circolazione le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691,5],"tags":[],"class_list":["post-4252","post","type-post","status-publish","format-standard","hentry","category-curiosita","category-sa"],"jetpack_publicize_connections":[],"views":1906,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-16A","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=4252"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4252\/revisions"}],"predecessor-version":[{"id":4255,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4252\/revisions\/4255"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=4252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=4252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=4252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}