{"id":4217,"date":"2014-11-13T14:30:44","date_gmt":"2014-11-13T13:30:44","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=4217"},"modified":"2014-11-13T14:30:57","modified_gmt":"2014-11-13T13:30:57","slug":"cose-business-model","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/cose-business-model\/","title":{"rendered":"Cos&#8217;\u00e8 un business model?"},"content":{"rendered":"<p><strong>Il business model (o modello di business) \u00e8 l&#8217;insieme delle soluzioni organizzative e strategiche con le quali l&#8217;impresa acquisisce un vantaggio competitivo. Secondo Alexander Osterwalder, ideatore del Business Model Canvas, il modello di business\u00a0descrive la logica con la quale un\u2019organizzazione crea, distribuisce e cattura valore.<\/strong><br \/>\n<!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Fotolia_60242457_S.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4055\" data-permalink=\"https:\/\/blog.startups.ch\/it\/come-sviluppare-concetto-marketing-efficace\/businessman-drawing-marketing-concepts\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Fotolia_60242457_S.jpg?fit=690%2C291&amp;ssl=1\" data-orig-size=\"690,291\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Melpomene - Fotolia&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Businessman drawing business marketing concepts with chalk&quot;,&quot;created_timestamp&quot;:&quot;1389298945&quot;,&quot;copyright&quot;:&quot;Melpomene - Fotolia&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Businessman drawing marketing concepts&quot;}\" data-image-title=\"\" data-image-description=\"&lt;p&gt;Businessman drawing business marketing concepts with chalk&lt;\/p&gt;\n\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Fotolia_60242457_S.jpg?fit=300%2C126&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Fotolia_60242457_S.jpg?fit=690%2C291&amp;ssl=1\" class=\"alignnone size-full wp-image-4055\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Fotolia_60242457_S.jpg?resize=690%2C291\" alt=\"Businessman drawing marketing concepts\" width=\"690\" height=\"291\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Fotolia_60242457_S.jpg?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Fotolia_60242457_S.jpg?resize=300%2C126&amp;ssl=1 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><strong>Business plan vs. business model<\/strong><\/p>\n<p>Il successo o l&#8217;insuccesso di un\u2019attivit\u00e0 imprenditoriale dipende dalla capacit\u00e0 dell&#8217;azienda di creare un valore aggiunto per i propri clienti. Secondo diversi esponenti del settore, la prima attivit\u00e0 da svolgere per creare una startup o ridisegnare il proprio business esistente deve essere la creazione del proprio modello di business in modo da stabilire con precisione cosa bisogna fare, come bisogna farlo e per quali precisi clienti l&#8217;azienda vuole creare valore. Spesso l&#8217;errore pi\u00f9 comune risulta essere quello di predisporre, come primo documento, il business plan aziendale. L&#8217;errore che alcuni non considerano\u00a0\u00e8 dovuto dal fatto, che il business plan indica\u00a0che cosa, quanto tempo e quanti soldi servono per mettere in pratica il business model. Per questo motivo il business plan \u00e8 un documento complesso, arricchito da molte pagine di analisi e previsioni, utilissimo per presentare agli stakeholders, agli investitori e per ottenere finanziamenti. Ma proprio per la\u00a0via della sua\u00a0complessit\u00e0 e la sua natura poco si presta alla sua funzione di pianificazione strategica. Utilizzando strumenti come ad esempio il business model canvas di Osterwalder si pu\u00f2 definire la pianificazione strategica e organizzativa in maniera semplice, veloce ed efficace. La redazione di un business plan deve avvenire una volta definito il proprio modello di business. Insomma, si potrebbe quasi dire che il business plan rappresenti pi\u00f9 una versione trascritta dello schematico business model canvas.<\/p>\n<p><strong>Le componenti del business model canvas<\/strong><\/p>\n<p>Il termine canvas riconduce ad una forma di \u201ctela\u201d su cui dipingere il proprio modello di business,\u00a0secondo uno schema standard. Attraverso l\u2019utilizzo di questo strumento si aumenta il livello di creativit\u00e0 durante la fase di sviluppo della logica del propria attivit\u00e0 imprenditoriale. Le parti del canvas sono le seguenti:<\/p>\n<ul>\n<li>Partner chiave<\/li>\n<li>Attivit\u00e0 chiave<\/li>\n<li>Risorse chiave<\/li>\n<li>Struttura dei costi<\/li>\n<li>Proposta di valore<\/li>\n<li>Relazioni con i clienti<\/li>\n<li>Canali<\/li>\n<li>Segmenti di clientela<\/li>\n<li>Flussi di entrate<\/li>\n<\/ul>\n<p>Grazie all&#8217;utilizzo del business model canvas, ogni elemento diventa fondamentale per il successo dell\u2019azienda, proprio perch\u00e9 \u00e8 pensata come un sistema immerso in un ecosistema pi\u00f9 grande: ogni elemento dipende dall&#8217;altro, lo rafforza e lo migliora. Potete trovare ulteriori informazioni in merito al business model canvas di Osterwalder al seguente <a href=\"http:\/\/businessmodelgeneration.com\">link<\/a>.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fcose-business-model%2F';\n  addthis_title  = 'Cos%26%238217%3B%C3%A8+un+business+model%3F';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il business model (o modello di business) \u00e8 l&#8217;insieme delle soluzioni organizzative e strategiche con le quali l&#8217;impresa acquisisce un vantaggio competitivo. Secondo Alexander Osterwalder, ideatore del Business Model Canvas, il modello di business\u00a0descrive la logica con la quale un\u2019organizzazione crea, distribuisce e cattura valore.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"class_list":["post-4217","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"views":2131,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-161","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=4217"}],"version-history":[{"count":3,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4217\/revisions"}],"predecessor-version":[{"id":4220,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4217\/revisions\/4220"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=4217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=4217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=4217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}