{"id":4069,"date":"2014-06-24T12:59:49","date_gmt":"2014-06-24T10:59:49","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=4069"},"modified":"2014-08-25T13:49:21","modified_gmt":"2014-08-25T11:49:21","slug":"intervista-marcel-dobler-co-fondatore-gruppo-galaxus","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/intervista-marcel-dobler-co-fondatore-gruppo-galaxus\/","title":{"rendered":"Intervista con Marcel Dobler, il  co-fondatore del gruppo Galaxus"},"content":{"rendered":"<p><strong>Marcel Dobler, nato nel 1980, \u00e8 il co-fondatore del gruppo Galaxus (Digitec, negozio online Galaxus). Insieme ai suoi partner Florian Teuteberg e Oliver Herren ha gestito l&#8217;azienda dal 2001 al 2014. Recentemente \u00e8 stato il presidente del consiglio d\u2019amministrazione del gruppo Galaxus ed il CFO, CIO e Co-CEO di Digitec. Nel 2012, il gruppo Galaxus \u00e8 stato venduto alla Migros. Nel 2014, Marcel Dobler ha venduto le sue quote in modo da ritirarsi a livello operativo e poter affrontare nuove sfide. Il gruppo Galaxus ha un fatturato che supera i 500 milioni, \u00e8 il leader di mercato ed impiega 450 dipendenti.<\/strong><br \/>\n<!--more--><\/p>\n<p><strong><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Marcel_Dobler.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4070\" data-permalink=\"https:\/\/blog.startups.ch\/it\/marcel_dobler\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Marcel_Dobler.png?fit=186%2C232&amp;ssl=1\" data-orig-size=\"186,232\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Marcel_Dobler\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Marcel_Dobler.png?fit=186%2C232&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Marcel_Dobler.png?fit=186%2C232&amp;ssl=1\" class=\"alignnone size-full wp-image-4070\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2014\/06\/Marcel_Dobler.png?resize=186%2C232\" alt=\"Marcel_Dobler\" width=\"186\" height=\"232\" data-recalc-dims=\"1\" \/><\/a><\/strong><\/p>\n<p><strong>Lei \u00e8 uno dei co-fondatori di Digitec<\/strong><strong>. Ci pu\u00f2 spiegare come \u00e8 stata la sua esperienza costituendo una societ\u00e0 con altri due soci?<\/strong><\/p>\n<p>Una partnership commerciale con diverse persone aventi gli stessi diritti equivale ad una grande opportunit\u00e0 che per\u00f2 nasconde anche un grande potenziale di conflitto. Una cultura orientata a risolvere i conflitti e che favoreggia la discussione tra le persone sta alla base del successo.<\/p>\n<p><strong>Quali sono stati gli ostacoli<\/strong><strong> maggiori nella fase iniziale di Digitec?<br \/>\n<\/strong><br \/>\nAll\u2019inizio della nostra attivit\u00e0 abbiamo dovuto superare diversi ostacoli per essere competitivi, soprattutto per quando riguarda la parte degli acquisti. Infatti, non \u00e8 che tutti i produttori e fornitori stessero aspettando il nostro ingresso nel mercato. Ancora oggi la componente politica tra i diversi livelli dei prezzi online e quelli offline \u00e8 un tema costante.<\/p>\n<p><strong>Secondo lei qual \u00e8 il segreto<\/strong><strong> di un giovane imprenditore?<\/strong><\/p>\n<p>Credo che l\u2019importante \u00e8 essere disposti ad effettuare cambiamenti continui ed a sviluppare nuove competenze. Il successo di Digitec \u00e8 il risultato di un lungo processo fatto di molti tentativi ed altrettanti fallimenti. Bisogna avere la voglia di migliorarsi in continuazione e di farlo meglio rispetto agli altri. Questo \u00e8 sempre stato molto importante per me.<\/p>\n<p><strong>Se avesse la possibilit\u00e0 di<\/strong><strong> dare solo un consiglio ad un giovane imprenditore, quale sarebbe?<\/strong><\/p>\n<p>Consentire ad estranei di dare la propria opinione in modo da sentire un parere esterno e soprattutto di saper mettere in discussione le proprie opinioni regolarmente.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fintervista-marcel-dobler-co-fondatore-gruppo-galaxus%2F';\n  addthis_title  = 'Intervista+con+Marcel+Dobler%2C+il++co-fondatore+del+gruppo+Galaxus';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Marcel Dobler, nato nel 1980, \u00e8 il co-fondatore del gruppo Galaxus (Digitec, negozio online Galaxus). Insieme ai suoi partner Florian Teuteberg e Oliver Herren ha gestito l&#8217;azienda dal 2001 al 2014. Recentemente \u00e8 stato il presidente del consiglio d\u2019amministrazione del gruppo Galaxus ed il CFO, CIO e Co-CEO di Digitec. Nel 2012, il gruppo Galaxus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691,721],"tags":[],"class_list":["post-4069","post","type-post","status-publish","format-standard","hentry","category-curiosita","category-interviste"],"jetpack_publicize_connections":[],"views":1747,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-13D","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=4069"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4069\/revisions"}],"predecessor-version":[{"id":4071,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/4069\/revisions\/4071"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=4069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=4069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=4069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}