{"id":3452,"date":"2013-12-23T15:43:28","date_gmt":"2013-12-23T14:43:28","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=3452"},"modified":"2014-03-24T14:43:47","modified_gmt":"2014-03-24T13:43:47","slug":"quali-sono-le-competenze-dellassemblea-generale","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/quali-sono-le-competenze-dellassemblea-generale\/","title":{"rendered":"Quali sono le competenze dell\u2019assemblea generale?"},"content":{"rendered":"<p><b>Le competenze dell\u2019assemblea generale sono regolate nell\u2019articolo 698 CO. L\u2019assemblea generale \u00e8 l\u2019organo supremo di una societ\u00e0 anonima.<!--more--><\/b><\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/12\/Fotolia_43009286_S.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3453\" data-permalink=\"https:\/\/blog.startups.ch\/it\/quali-sono-le-competenze-dellassemblea-generale\/fotolia_43009286_s\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/12\/Fotolia_43009286_S.png?fit=690%2C356&amp;ssl=1\" data-orig-size=\"690,356\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Fotolia_43009286_S\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/12\/Fotolia_43009286_S.png?fit=300%2C154&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/12\/Fotolia_43009286_S.png?fit=690%2C356&amp;ssl=1\" class=\"aligncenter size-full wp-image-3453\" alt=\"Fotolia_43009286_S\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/12\/Fotolia_43009286_S.png?resize=690%2C356\" width=\"690\" height=\"356\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/12\/Fotolia_43009286_S.png?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/12\/Fotolia_43009286_S.png?resize=300%2C154&amp;ssl=1 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><b>Le competenze dell\u2019assemblea generale<\/b><\/p>\n<p>L&#8217;assemblea generale (AG) detiene i poteri pi\u00f9 elementari di una societ\u00e0 anonima. Essa determina tra le altre cose, se adottare o modificare gli statuti, cos\u00ec come la nomina degli ulteriori organi. L\u2019AG detiene i seguenti compiti non trasferibili ed inalienabili:<\/p>\n<ul>\n<li>modifica degli statuti<\/li>\n<li>nomina il consiglio d&#8217;amministrazione e l&#8217;organo di revisione<\/li>\n<li>approva o respinge il rapporto annuale, cos\u00ec come il bilancio consolidato<\/li>\n<li>pu\u00f2 esonerare i membri del consiglio d\u2019amministrazione<\/li>\n<li>delibera sull&#8217;utilizzo dell&#8217;utile societario (soprattutto la definizione di dividendi e bonus)<\/li>\n<li>ulteriori competenze concesse all\u2019AG dalla legge o dagli statuti<\/li>\n<\/ul>\n<p><strong>Decisioni dell\u2019AG<\/strong><\/p>\n<p>Tra le decisioni esplicite per l\u2019assemblea generale vi sono per esempio, la riduzione o l\u2019aumento del capitale, le verifiche speciali, l&#8217;approvazione di un accordo di fusione o l&#8217;autorizzazione per l&#8217;ispezione da parte degli azionisti nella documentazione contabile dell\u2019azienda. Non \u00e8 consentito delegare tali compiti previsti dagli statuti o dalla legge al consiglio d\u2019amministrazione o ad un comitato di azionisti.<\/p>\n<p><b>L&#8217;AG non pu\u00f2 decidere tutto<\/b><\/p>\n<p>Tuttavia, va rigorosamente osservata la separazione dei poteri all&#8217;interno della societ\u00e0. Quindi l\u2019assemblea generale non pu\u00f2 decidere su questioni non trasferibili e irrevocabili che vengono assegnati al Consiglio di Amministrazione nell&#8217;articolo 716a CO.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fquali-sono-le-competenze-dellassemblea-generale%2F';\n  addthis_title  = 'Quali+sono+le+competenze+dell%E2%80%99assemblea+generale%3F';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le competenze dell\u2019assemblea generale sono regolate nell\u2019articolo 698 CO. L\u2019assemblea generale \u00e8 l\u2019organo supremo di una societ\u00e0 anonima.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"class_list":["post-3452","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"views":1860,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-TG","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=3452"}],"version-history":[{"count":5,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3452\/revisions"}],"predecessor-version":[{"id":3457,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3452\/revisions\/3457"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=3452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=3452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=3452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}