{"id":3256,"date":"2013-10-14T16:06:53","date_gmt":"2013-10-14T14:06:53","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=3256"},"modified":"2014-03-24T14:43:48","modified_gmt":"2014-03-24T13:43:48","slug":"gli-statuti-di-una-societa-anonima-sa","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/gli-statuti-di-una-societa-anonima-sa\/","title":{"rendered":"Gli statuti di una societ\u00e0 anonima (SA)"},"content":{"rendered":"<p><b>Gli statuti definiscono il funzionamento di una societ\u00e0. In seguito potrete conoscere quali sono i punti importanti da menzionare ed usare le informazioni come guida ed aiuto nella preparazione degli statuti per la vostra societ\u00e0 anonima.<\/b><\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/10\/Bild.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3258\" data-permalink=\"https:\/\/blog.startups.ch\/it\/gli-statuti-di-una-societa-anonima-sa\/bild\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/10\/Bild.png?fit=690%2C356&amp;ssl=1\" data-orig-size=\"690,356\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Bild\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/10\/Bild.png?fit=300%2C154&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/10\/Bild.png?fit=690%2C356&amp;ssl=1\" class=\"alignleft size-full wp-image-3258\" alt=\"Bild\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/10\/Bild.png?resize=690%2C356\" width=\"690\" height=\"356\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/10\/Bild.png?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/10\/Bild.png?resize=300%2C154&amp;ssl=1 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><b>Struttura degli statuti per una societ\u00e0 anonima (SA)<\/b><\/p>\n<p>In modo da poter valere giuridicamente, gli statuti devono essere autenticati da un&#8217;istituzione pubblica. Inoltre, ne \u00e8 richiesta l&#8217;iscrizione al registro di commercio nel rispettivo cantone. Nell\u2019articolo 626 del Codice delle obbligazioni, la legge regola il contenuto minimo previsto per gli statuti di una SA e definisce i punti che devono essere inclusi \u00a0nel caso si voglia usufruirne volontariamente o far diventare vincolanti (Art. 627 CO).<\/p>\n<p>La legge prevede che vengano fatti degli accenni inerenti la societ\u00e0 e la sede legale e riguardanti:<\/p>\n<ul>\n<li>lo scopo<\/li>\n<li>l\u2019ammontare del capitale sociale<\/li>\n<li>il valore nominale<\/li>\n<li>la tipologia delle azioni<\/li>\n<li>la convocazione dell\u2019assemblea generale<\/li>\n<li>i diritti di voto degli azionisti<\/li>\n<li>gli organi<\/li>\n<li>la revisione<\/li>\n<li>la forma\/struttura dell\u2019informazione emessa verso l\u2019esterno<\/li>\n<\/ul>\n<p>L&#8217;articolo 627 CO definisce ulteriori informazioni da inserire negli statuti. Per esempio fa riferimento alla modifica degli statuti nel caso divergessero dalla legge, ai limiti di trasferibilit\u00e0 di azioni nominative o alle limitazioni dei diritti di voto degli azionisti.<\/p>\n<p>Gli statuti di una societ\u00e0 anonima possono avere la seguente struttura:<\/p>\n<ol>\n<li><strong>Nome dell\u2019impresa, sede e durata<\/strong><\/li>\n<li><strong>Capitale<\/strong> (capitale sociale ed azioni, libro delle azioni, il trasferimento di azioni nominative)<\/li>\n<li><strong>Organizzazione della societ\u00e0<\/strong> (l&#8217;Assemblea Generale (poteri, convocazione, riunione di tuti gli azionisti, quorum, il diritto di voto ed il processo decisionale), il Consiglio di Amministrazione (elezione, ammissibilit\u00e0 e durata del mandato, poteri e doveri, riunioni consiliari, quorum e processo decisionale, delega), ufficio di revisione (scelta, ammissibilit\u00e0 e durata della carica ))<\/li>\n<li><strong>Contabilit\u00e0 e distribuzione del reddito<\/strong> (anno fiscale, distribuzione dell&#8217;utile)<\/li>\n<li><strong>Terminazione<\/strong> (scioglimento e liquidazione)<\/li>\n<li><strong>Notifiche<\/strong> (comunicazioni ed informazioni)<\/li>\n<\/ol>\n<p>Nell\u2019ambito degli investimenti materiali, delle acquisizioni di propriet\u00e0 e dei vantaggi speciali sono in vigore regolamentazioni speciali per quanto riguarda gli statuti. Nel caso di un investimento materiale gli statuti devono contenere il valore ed il nome del depositario (Art. 628 CO). Nel caso di un\u2019acquisizione di beni \u00e8 presente una regolamentazione simile. L\u2019art. 647 CO\u00a0 prevede che ogni modifica degli statuti necessita una certificazione da un&#8217;istituzione pubblica e che deve venir protocollata nel registro di commercio.<\/p>\n<p>Nel redigere i vostri statuti potete fare affidamento alle conoscenze e competenze degli esperti di STARTUPS.CH. Con un\u2019esperienza acquisita con la costituzione di oltre 6\u2019000 giovani imprese possiamo aiutarvi anche nei casi pi\u00f9 complessi.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fgli-statuti-di-una-societa-anonima-sa%2F';\n  addthis_title  = 'Gli+statuti+di+una+societ%C3%A0+anonima+%28SA%29';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Gli statuti definiscono il funzionamento di una societ\u00e0. In seguito potrete conoscere quali sono i punti importanti da menzionare ed usare le informazioni come guida ed aiuto nella preparazione degli statuti per la vostra societ\u00e0 anonima.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24,3,5,1],"tags":[],"class_list":["post-3256","post","type-post","status-publish","format-standard","hentry","category-costituzione","category-domande-generali","category-sa","category-uncategorized"],"jetpack_publicize_connections":[],"views":4940,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-Qw","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=3256"}],"version-history":[{"count":14,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3256\/revisions"}],"predecessor-version":[{"id":3646,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3256\/revisions\/3646"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=3256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=3256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=3256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}