{"id":316,"date":"2010-06-01T08:00:53","date_gmt":"2010-06-01T06:00:53","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=316"},"modified":"2014-03-24T14:44:13","modified_gmt":"2014-03-24T13:44:13","slug":"devo-stipulare-per-la-mia-impresa-unassicurazione-di-responsabilita-civile","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/devo-stipulare-per-la-mia-impresa-unassicurazione-di-responsabilita-civile\/","title":{"rendered":"Devo stipulare per la mia impresa un&#8217;assicurazione di responsabilit\u00e0 civile?"},"content":{"rendered":"<p><em>Aggiornato il 3 gennaio 2013<\/em><\/p>\n<h4>La stipulazione di un\u2019assicurazione di responsabilit\u00e0 civile per le imprese non \u00e8 obbligatoria, ma consigliabile. Essa persegue lo stesso scopo di un\u2019assicurazione di responsabilit\u00e0 civile: vengono coperti i danni causati a terzi dall\u2019imprenditore, da un suo rappresentante o da un suo dipendente.<\/h4>\n<p>Normalmente vengono inclusi i danni materiali o alle persone. I danni, che risultano da un non adempimento o non corretto adempimento del contratto da parte dell\u2019impresa, non sono assicurabili (cosiddetto rischio dell\u2019imprenditore). I rischi di responsabilit\u00e0 variano in maniera rilevante a dipendenza dell\u2019attivit\u00e0 dell\u2019impresa. In determinate circostanze sono immaginabili danni che potrebbero mettere a repentaglio l\u2019esistenza dell\u2019impresa. Per questo motivo si dovrebbe effettuare una precisa analisi dei rischi (cfr. <a href=\"http:\/\/blog.startups.ch\/it\/2010\/06\/01\/come-elaboro-un\u2019analisi-dei-rischi\/\" target=\"_blank\">blog<\/a>). Nel momento della costituzione della propria ditta attraverso <a href=\"http:\/\/www.startups.ch\/\">STARTUPS.CH<\/a> pu\u00f2 stipulare delle assicurazioni con il nostro partner AXA-Winterthur al fine di risparmiare sui costi di costituzione.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fdevo-stipulare-per-la-mia-impresa-unassicurazione-di-responsabilita-civile%2F';\n  addthis_title  = 'Devo+stipulare+per+la+mia+impresa+un%26%238217%3Bassicurazione+di+responsabilit%C3%A0+civile%3F';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aggiornato il 3 gennaio 2013 La stipulazione di un\u2019assicurazione di responsabilit\u00e0 civile per le imprese non \u00e8 obbligatoria, ma consigliabile. Essa persegue lo stesso scopo di un\u2019assicurazione di responsabilit\u00e0 civile: vengono coperti i danni causati a terzi dall\u2019imprenditore, da un suo rappresentante o da un suo dipendente. Normalmente vengono inclusi i danni materiali o alle [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24,3],"tags":[173,171,733,172,175,170,176,174],"class_list":["post-316","post","type-post","status-publish","format-standard","hentry","category-costituzione","category-domande-generali","tag-analisi-dei-rischi","tag-assicurazione","tag-costituzione","tag-danni","tag-impresa","tag-responsabilita-civile","tag-rischio-dellimprenditore","tag-stipulare-assicurazioni"],"jetpack_publicize_connections":[],"views":2598,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-56","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":11,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/316\/revisions"}],"predecessor-version":[{"id":3874,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/316\/revisions\/3874"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}