{"id":3032,"date":"2013-07-01T10:00:50","date_gmt":"2013-07-01T08:00:50","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=3032"},"modified":"2014-03-24T14:43:50","modified_gmt":"2014-03-24T13:43:50","slug":"i-conflitti-fiscali-penalizzano-gli-imprenditori-stranieri","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/i-conflitti-fiscali-penalizzano-gli-imprenditori-stranieri\/","title":{"rendered":"I conflitti fiscali penalizzano gli imprenditori stranieri"},"content":{"rendered":"<p><b>I giovani imprenditori svizzeri non si lasciano intimorire dal momentaneo periodo economico insicuro. Il numero di nuove iscrizioni al registro di commercio effettuate durante il primo semestre del 2013, rispetto allo stesso periodo del 2012, \u00e9 aumentato in modo concreto (+1.4%). Questo \u00e9 quanto ha riscontrato una recente analisi di <a href=\"http:\/\/www.startups.ch\/it\/\">STARTUPS.CH<\/a>, la piattaforma online specializzata in costituzioni di aziende. A seguito del conflitto fiscale con gli Stati Uniti e altre nazioni europee, i nuovi imprenditori stranieri influiscono solo in minima parte a quest\u2019aumento. Questo influisce negativamente sulla piazza economica Svizzera.<\/b><\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3038\" data-permalink=\"https:\/\/blog.startups.ch\/it\/i-conflitti-fiscali-penalizzano-gli-imprenditori-stranieri\/costituzioni_h1-2013\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png?fit=758%2C483&amp;ssl=1\" data-orig-size=\"758,483\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Costituzioni in Ticino\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png?fit=300%2C191&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png?fit=690%2C439&amp;ssl=1\" class=\"alignleft  wp-image-3038\" alt=\"Costituzioni in Ticino\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png?resize=682%2C435\" width=\"682\" height=\"435\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png?w=758&amp;ssl=1 758w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png?resize=300%2C191&amp;ssl=1 300w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni_H1-2013.png?resize=690%2C439&amp;ssl=1 690w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p>Il numero di nuove iscrizioni nel registro di commercio Svizzero durante il primo semestre 2013 \u00e9 cresciuto leggermente, facendo segnare un aumento dell\u20191.4 percento rispetto allo stesso periodo del 2012, e raggiungendo cos\u00ec quota 20\u2018303 unit\u00e0. In confronto al secondo semestre del 2012 il numero di nuove iscrizioni \u00e8 aumentato invece di quasi il 5 percento. I giovani imprenditori Svizzeri dimostrano cos\u00ec di essere meno influenzati dalla rallentata ripresa economica dell\u2019Eurozona e dalle insicurezze che ci\u00f2 comporta.<\/p>\n<p>Tuttavia, per i nuovi imprenditori esteri l\u2019apertura di una nuova attivit\u00e0 commerciale \u00e8 diventato pi\u00f9 difficile. Questo colpisce per lo pi\u00f9 quegli imprenditori che non provengono dalle nazioni confinanti alla Svizzera come ad esempio l\u2019Inghilterra, l\u2019Olanda e i paesi scandinavi. Se non si dispone di un domicilio in Svizzera e un\u2019attivit\u00e0 commerciale non pu\u00f2 essere comprovata \u2013 cosa che prima della costituzione dell\u2019azienda risulta difficile \u2013 il conto vincolato per il deposito del capitale sociale non pu\u00f2 venir aperto, non rispettando cos\u00ec una delle condizioni per la costituzione di un\u2019azienda.<\/p>\n<p>Questa \u00e9 la conseguenza del conflitto fiscale con gli Stati Uniti e altre nazioni, che tradotto, per le banche vuol dire un chiaro e secco \u201eNo!\u201c. Le banche non si assumono pi\u00f9 il rischio, e se lo fanno, impongono tariffe molto pi\u00f9 alte. Progetti di imprenditori stranieri, in particolare quelli che non provengono dalle nazioni confinanti, devono sottostare a rigide condizioni, altrimenti non possono venire realizzati.<\/p>\n<p><b>La reputazione della Svizzera viene danneggiata<\/b><\/p>\n<p>\u201eQuesto \u00e9 un grande problema. La Svizzera sta infatti chiudendo la porta ad importanti investitori. Questo rovina l\u2019immagine della nostra nazione e della nostra piazza finanziaria\u201c afferma Michele Blasucci, CEO di STARTUPS.CH. I dati delle aziende costituite tramite STARTUPS.CH confermano l\u2019immagine sopra esposta. La percentuale di aziende costituite da imprenditori stranieri per il periodo preso in considerazione, \u00e9 diminuita, passando dal 35,1 percento dello scorso anno al 33,7 di quest\u2019anno, il tutto in controtendenza al trend generale positivo riscontrato.<\/p>\n<p>Nei singoli cantoni, il numero di nuove iscrizioni si \u00e9 sviluppato in differenti modi. Zugo ha fatto segnare una diminuzione del 9,1 percento. Questo calo \u00e8 da attribuire in parte alla concorrenza del Canton Lucerna, il quale a partire dal 2012 offre il domicilio fiscale per le aziende pi\u00f9 a buon mercato di tutta la Svizzera. Dall\u2019altro lato \u00e8 da ricondurre alle maggiori difficolt\u00e0 per gli imprenditori stranieri. Essi vengono spesso visti come imprenditori che intendono aprire solo una societ\u00e0 buca lettere, ma che in realt\u00e0, anche se non dispongono ancora di personale, vogliono intraprendere un\u2019attivit\u00e0 imprenditoriale concreta. Un circolo vizioso: un contratto di lavoro valido con l\u2019azienda che si vuole costituire necessit\u00e0 di un permesso di soggiorno. L\u2019azienda per\u00f2 non pu\u00f2 essere costituita senza un domicilio in Svizzera.<\/p>\n<p><b>Turgovia sa quello che hanno bisogno i giovani imprenditori<\/b><\/p>\n<p>L\u2019indicatore di riferimento per le nuove costituzioni \u00e8, e rimane, il Canton Zurigo: ricco di popolazione, economicamente forte e attivo in tutti i settori. A Zurigo sono state costituite ben il 16,6 percento di tutte le nuove aziende in Svizzera. Nel corso del primo semestre 2013, le iscrizioni al registro di commercio sono state 3\u2018368 (+0,9%).<\/p>\n<p>Uno sviluppo particolarmente positivo \u00e9 stato registrato nuovamente nel Canton Turgovia (nuove iscrizioni: +16,3% a quota 607). L\u2019aumento non \u00e9 solo da ricondurre ai prezzi dei terreni particolarmente bassi. \u201eLe autorit\u00e0 offrono ottime condizioni alle aziende che creano nuovi posti di lavoro \u201c, ci spiega Blasucci. Inoltre la vicinanza alla Germania comporta un vantaggio. La regione di Kreuzlingen e dintorni ha vissuto un vero e proprio boom. La stessa cosa si osserva per il Canton San Gallo, che approfitta a sua volta della vicinanza dell\u2019Austria e dell\u2019est Europa. Il numero di nuove iscrizioni al registro di commercio \u00e9 rimasto pressoch\u00e9 invariato nel primo semestre 2013 in confronto alla prima met\u00e0 del 2012. Ha fatto invece registrare un aumento dell\u20199,5 percento rispetto al secondo semestre del 2012. Il Ticino continua ad approfittare della situazione politica giudicata insoddisfacente da molti cittadini italiani (nuove costituzioni: +10,6% a quota 1\u2018612).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3040\" data-permalink=\"https:\/\/blog.startups.ch\/it\/i-conflitti-fiscali-penalizzano-gli-imprenditori-stranieri\/costituzioni-mensili-svizzera_h1-2013\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-mensili-Svizzera_H1-2013.png?fit=752%2C432&amp;ssl=1\" data-orig-size=\"752,432\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Costituzioni mensili-Svizzera_H1 2013\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-mensili-Svizzera_H1-2013.png?fit=300%2C172&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-mensili-Svizzera_H1-2013.png?fit=690%2C396&amp;ssl=1\" class=\"alignleft  wp-image-3040\" alt=\"Costituzioni mensili-Svizzera_H1 2013\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-mensili-Svizzera_H1-2013.png?resize=677%2C389\" width=\"677\" height=\"389\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-mensili-Svizzera_H1-2013.png?w=752&amp;ssl=1 752w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-mensili-Svizzera_H1-2013.png?resize=300%2C172&amp;ssl=1 300w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-mensili-Svizzera_H1-2013.png?resize=690%2C396&amp;ssl=1 690w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" data-recalc-dims=\"1\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><b>I fallimenti rimangono nei limiti<\/b><\/p>\n<p>Il numero di nuove iscrizioni si contrappone a quello dei fallimenti. Il numero di cancellazioni dal registro di commercio \u00e9 diminuito a livello Svizzero del 5 percento. Secondo <a href=\"https:\/\/secure.creditreform.ch\/index.php?id=1&amp;L=3\">Creditreform<\/a>, unione Svizzera dei creditori, il numero dei fallimenti \u00e9 invece aumentato, in particolar modo quelli dovuti ad un sovra indebitamento dell\u2019azienda, di circa il 3 percento. Il dato non \u00e9 particolarmente drammatico.<\/p>\n<p>Per l\u2019anno 2013, Blasucci prevede un sviluppo piuttosto piatto delle nuove iscrizioni al registro di commercio, da ricondurre anche ai maggiori svantaggi per gli imprenditori esteri a seguito dello scontro fiscale con le altre nazioni.<\/p>\n<p><a href=\"http:\/\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-Svizzera_H1-2013.bmp\"><img decoding=\"async\" data-attachment-id=\"3039\" data-permalink=\"https:\/\/blog.startups.ch\/it\/i-conflitti-fiscali-penalizzano-gli-imprenditori-stranieri\/costituzioni-svizzera_h1-2013\/\" data-orig-file=\"https:\/\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-Svizzera_H1-2013.bmp\" data-orig-size=\"\" data-comments-opened=\"0\" data-image-meta=\"[]\" data-image-title=\"Costituzioni-Svizzera_H1 2013\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-Svizzera_H1-2013.bmp\" data-large-file=\"https:\/\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-Svizzera_H1-2013.bmp\" class=\"alignleft size-full wp-image-3039\" alt=\"Costituzioni-Svizzera_H1 2013\" src=\"http:\/\/blog.startups.ch\/it\/wp-content\/uploads\/2013\/07\/Costituzioni-Svizzera_H1-2013.bmp\" \/><\/a><br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n<b>\u00a0<\/b><\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fi-conflitti-fiscali-penalizzano-gli-imprenditori-stranieri%2F';\n  addthis_title  = 'I+conflitti+fiscali+penalizzano+gli+imprenditori+stranieri';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>I giovani imprenditori svizzeri non si lasciano intimorire dal momentaneo periodo economico insicuro. Il numero di nuove iscrizioni al registro di commercio effettuate durante il primo semestre del 2013, rispetto allo stesso periodo del 2012, \u00e9 aumentato in modo concreto (+1.4%). Questo \u00e9 quanto ha riscontrato una recente analisi di STARTUPS.CH, la piattaforma online specializzata [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"class_list":["post-3032","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"views":1809,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-MU","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=3032"}],"version-history":[{"count":16,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3032\/revisions"}],"predecessor-version":[{"id":3660,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/3032\/revisions\/3660"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=3032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=3032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=3032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}