{"id":2263,"date":"2012-12-24T11:00:37","date_gmt":"2012-12-24T10:00:37","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=2263"},"modified":"2014-03-24T14:43:51","modified_gmt":"2014-03-24T13:43:51","slug":"il-beneficio-del-cloud-computing-per-le-pmi","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/il-beneficio-del-cloud-computing-per-le-pmi\/","title":{"rendered":"Il beneficio del Cloud Computing per le PMI."},"content":{"rendered":"<h2>Il tema Cloud Computing, ovvero il fatto di salvare i propri dati in un \u201cCloud\u201d (una \u201cnuvola\u201d), ha guadagnato d\u2019importanza negli ultimi anni. Secondo l\u2019azienda di ricerca di mercato Svizzera MSM Research SA, entro il 2015 il 70% delle aziende Svizzere adotter\u00e0 un sistema di Cloud Computing. Microsoft annuncia che il 71% delle PMI hanno bisogno di tecnologie che permettano ai propri dipendenti di lavorare in qualsiasi momento e ovunque. STARTUPS.CH ha approfondito il tema con Stephan Mahler, CEO di ProCloud SA.<\/h2>\n<p><!--more--><\/p>\n<div style=\"text-align: -webkit-left;\"><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2012\/12\/Cloud-Computing.gif\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2264\" data-permalink=\"https:\/\/blog.startups.ch\/it\/il-beneficio-del-cloud-computing-per-le-pmi\/cloud-computing\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2012\/12\/Cloud-Computing.gif?fit=690%2C342&amp;ssl=1\" data-orig-size=\"690,342\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Cloud Computing\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2012\/12\/Cloud-Computing.gif?fit=300%2C148&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2012\/12\/Cloud-Computing.gif?fit=690%2C342&amp;ssl=1\" class=\"aligncenter size-full wp-image-2264\" title=\"Cloud Computing\" alt=\"\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2012\/12\/Cloud-Computing.gif?resize=690%2C342\" width=\"690\" height=\"342\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2012\/12\/Cloud-Computing.gif?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2012\/12\/Cloud-Computing.gif?resize=300%2C148&amp;ssl=1 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><\/div>\n<p align=\"left\">Cloud Computing \u00e8 diventato un servizio ormai indispensabile ed \u00e8 definitivamente entrato a far parte del mondo delle aziende. Ma che cos\u2019\u00e8 un Cloud Computing esattamente? \u201cLa parola Cloud (in italiano nuvola) non rappresenta un termine preciso nel mondo dell\u2019IT. In modo semplice, si tratta dell\u2019esternalizzazione dell\u2019informatica in centri di calcolo pi\u00f9 sicuri. Il settore dell\u2019IT dell\u2019azienda non viene pi\u00f9 gestito in modo autonomo da ogni singola azienda, ma viene per cos\u00ec dire affittato e delegato a ditte specializzate\u201d ci spiega Stephan Mahler.<\/p>\n<p align=\"left\">L\u2019applicazione pratica del Cloud Computing si pu\u00f2 categorizzare in due forme. Si affittano dei <strong>Software <\/strong>oppure si <strong>esternalizza tutto il sistema IT in un Cloud<\/strong>. In questo modo per lavorare \u00e8 necessario solamente un collegamento ad internet. Il posto di lavoro \u00e8 dove ti trovi in quel momento. \u201cLa produttivit\u00e0 che si va a guadagnare compensa in molti casi i costi legati a tutto il settore IT. Immaginatevi di poter lavorare per un\u2019ora mentre siete in viaggio in treno oppure in un bar nel tempo tra due appuntamenti, e poter fatturare questo tempo direttamente al cliente. Moltiplicate allora l\u2019onorario per le ore che tutti i vostri collaboratori potrebbero lavorare in pi\u00f9. Il potenziale di risparmio per le aziende \u00e8 enorme\u201d, ci racconta entusiasta Stephan Mahler.<\/p>\n<p align=\"left\">Un\u2019altra importante caratteristica in merito all\u2019aumento di produttivit\u00e0 riguarda il fatto di potersi focalizzare sulle attivit\u00e0 aziendali principali, ovvero sul core business, liberando risorse impiegate alla gestione dell\u2019IT. Si pu\u00f2 partire dal presupposto che, gli standard all\u2019interno del Cloud sono pi\u00f9 alti, rispetto ad un\u2019analoga gestione dell\u2019IT individuale. \u201cI nostri servizi di Cloud Computing si avvengono attraverso centri di calcolo, i quali standard sono allo stesso livello di quelli delle banche. Prima dell\u2019era del Cloud solo le grandi aziende potevano permettersi un simile sistema. Oggi questo servizio \u00e8 possibile anche per aziende di piccole dimensioni\u201d ci spiega Stephan Mahler. \u201cNel settore del Cloud Computing \u00e8 molto importante scegliere dei Partner affidabili e che i dati vengano salvati in Svizzera. In questo modo si rimane soggetti al diritto Svizzero e i dati rimango a disposizione nelle immediate vicinanze\u201d.<\/p>\n<p align=\"left\">In fine bisogna tener conto anche dei costi. I costi per lo sviluppo dell\u2019informatica non sono per\u00f2 sempre calcolabili. \u201cLe offerte Cloud vengono calcolare con tariffe mensili sulla base degli utenti o alle risorse necessarie. In questo modo si possono prevedere i costi legati all\u2019IT e pu\u00f2 venir allestito un budget. L\u2019azienda garantisce una disponibilit\u00e0 del 99.99% durante tutto l\u2019anno\u201d conclude Stephan Mahler.<\/p>\n<p>L\u2019azienda ProCloud SA \u00e8 il nostro Co-Partner esclusivo nel settore del Cloud Computing ed ha a disposizione interessanti offerte e condizioni speciali anche per giovani start up. Cloud Backup a partire da CHF 15.-\/mese, delocalizzazione di tutto l\u2019IT a partire da CHF 179.-\/mese. Maggiori informazioni potete trovarle su <a href=\"http:\/\/www.procloud.ch\">www.procloud.ch<\/a> oppure al numero diretto 062 552 01 00.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fil-beneficio-del-cloud-computing-per-le-pmi%2F';\n  addthis_title  = 'Il+beneficio+del+Cloud+Computing+per+le+PMI.';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il tema Cloud Computing, ovvero il fatto di salvare i propri dati in un \u201cCloud\u201d (una \u201cnuvola\u201d), ha guadagnato d\u2019importanza negli ultimi anni. Secondo l\u2019azienda di ricerca di mercato Svizzera MSM Research SA, entro il 2015 il 70% delle aziende Svizzere adotter\u00e0 un sistema di Cloud Computing. Microsoft annuncia che il 71% delle PMI hanno [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"class_list":["post-2263","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"views":2203,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-Av","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/2263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=2263"}],"version-history":[{"count":11,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/2263\/revisions"}],"predecessor-version":[{"id":3676,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/2263\/revisions\/3676"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=2263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=2263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=2263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}