{"id":206,"date":"2009-12-10T07:30:00","date_gmt":"2009-12-10T05:30:00","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=206"},"modified":"2014-03-24T14:44:16","modified_gmt":"2014-03-24T13:44:16","slug":"lavoro-indipendente-e-costituzione-in-svizzera-per-cittadini-ue-e-efta-permesso-di-dimora-per-stranieri","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/lavoro-indipendente-e-costituzione-in-svizzera-per-cittadini-ue-e-efta-permesso-di-dimora-per-stranieri\/","title":{"rendered":"Lavoro indipendente e costituzione in Svizzera per cittadini UE e EFTA (Permesso di dimora per stranieri)"},"content":{"rendered":"<p><em>Aggiornato il 3 gennaio 2013<\/em><\/p>\n<h4>Per quanto riguarda la dimora a scopo di attivit\u00e0 lavorativa indipendente (inclusa la costituzione di un&#8217;impresa in Svizzera), i cittadini dei paesi UE e EFTA (inclusi Romania e Bulgaria) sono tutti equiparati.<\/h4>\n<h3>Occorre procedere nel modo seguente:<\/h3>\n<p><em>Entro 8 giorni dall&#8217;ingresso occorre inoltrare domanda per un permesso di dimora a scopo di lavoro indipendente presso il comune di domicilio. <\/em>Nell&#8217;ambito dell&#8217;evasione della domanda <em>bisogna dimostrare la propria indipendenza lavorativa in Svizzera<\/em>. Se ci\u00f2 riesce, si ottiene un permesso di dimora UE\/EFTA valido per 5 anni.<\/p>\n<p>Per dimostrare la propria indipendenza lavorativa in Svizzera occorre inoltrare i corrispettivi documenti. Se si costituisce un&#8217;impresa in Svizzera, sono rilevanti soprattutto l&#8217;estratto del registro di commercio, il riconoscimento dell&#8217;istituto delle assicurazioni sociali (IAS), e un&#8217;attestazione di capitale (ovvero o l&#8217;attestazione di capitale proprio sufficiente, oppure qualcuno che possa depositare questo capitale; l&#8217;importo varia da settore a settore). Inoltre possono fungere da prova anche il numero IVA e diversi documenti commerciali (p.es. la contabilit\u00e0, il business plan).<\/p>\n<p><em>La domanda pu\u00f2 anche essere inoltrata subito senza la documentazione richiesta. L&#8217;autorit\u00e0 poi fissa dei termini entro i quali questi possono essere inoltrati.<\/em> L&#8217;autorit\u00e0 pu\u00f2 controllare anche in un secondo tempo se l&#8217;attivit\u00e0 di lavoro indipendente sia effettiva e duratura, e che permetta di assicurare l&#8217;esistenza. Il permesso pu\u00f2 essere ritirato qualora questi requisiti vengano a mancare.<\/p>\n<p>La durata della procedura dipende dal riconoscimento dell&#8217;IAS, dall&#8217;ufficio del registro di commercio e dall&#8217;ufficio degli stranieri. Secondo la nostra esperienza, la durata dalla costituzione fino al riconoscimento da parte dell&#8217;ufficio degli stranieri \u00e8 di almeno due mesi.<\/p>\n<p>Informazioni sul tema vengono fornite dalle autorit\u00e0 cantonali di polizia degli stranieri (<a href=\"http:\/\/www.bfm.admin.ch\/bfm\/it\/home\/die_oe\/kontakt\/kantonale_behoerden\/adressen_kantone_und.html\" target=\"_blank\">una lista degli uffici cantonali \u00e8 consultabile a questo indirizzo<\/a>).<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Flavoro-indipendente-e-costituzione-in-svizzera-per-cittadini-ue-e-efta-permesso-di-dimora-per-stranieri%2F';\n  addthis_title  = 'Lavoro+indipendente+e+costituzione+in+Svizzera+per+cittadini+UE+e+EFTA+%28Permesso+di+dimora+per+stranieri%29';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aggiornato il 3 gennaio 2013 Per quanto riguarda la dimora a scopo di attivit\u00e0 lavorativa indipendente (inclusa la costituzione di un&#8217;impresa in Svizzera), i cittadini dei paesi UE e EFTA (inclusi Romania e Bulgaria) sono tutti equiparati. Occorre procedere nel modo seguente: Entro 8 giorni dall&#8217;ingresso occorre inoltrare domanda per un permesso di dimora a [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24,3],"tags":[73,733,69,32,71,72,70],"class_list":["post-206","post","type-post","status-publish","format-standard","hentry","category-costituzione","category-domande-generali","tag-cittadini-ueefta","tag-costituzione","tag-lavoro-indipendente","tag-mettersi-in-proprio","tag-permesso-di-dimora","tag-polizia-degli-stranieri","tag-stranieri"],"jetpack_publicize_connections":[],"views":3342,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-3k","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":10,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/206\/revisions"}],"predecessor-version":[{"id":3901,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/206\/revisions\/3901"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}