{"id":2035,"date":"2012-11-09T09:00:28","date_gmt":"2012-11-09T07:00:28","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=2035"},"modified":"2014-03-24T14:43:52","modified_gmt":"2014-03-24T13:43:52","slug":"costituzioni-di-nuove-aziende-nel-mese-di-ottobre-2012-a-confronto-con-il-mese-e-lanno-precedente","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/costituzioni-di-nuove-aziende-nel-mese-di-ottobre-2012-a-confronto-con-il-mese-e-lanno-precedente\/","title":{"rendered":"Costituzioni di nuove aziende nel mese di ottobre 2012 a confronto con il mese e l&#8217;anno precedente"},"content":{"rendered":"<p><strong>La tendenza positiva per quanto riguarda le costituzioni di nuove aziende nel mese di settembre, viene confermata anche nel mese di ottobre. Tendenza inaspettata se si confronta lo sviluppo dello stesso periodo dell&#8217;anno precedente. I dati dettagliati a riguardo nel seguente articolo.<\/strong><\/p>\n<p><!--more--><\/p>\n<h2><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/wp-content\/uploads\/2012\/11\/Handelsregisterneueintr%C3%A4ge-Oktober2.png\"><img loading=\"lazy\" decoding=\"async\" title=\"Handelsregisterneueintr\u00e4ge Oktober\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/wp-content\/uploads\/2012\/11\/Handelsregisterneueintr%C3%A4ge-Oktober2.png?resize=690%2C415\" alt=\"costituzioni\" width=\"690\" height=\"415\" data-recalc-dims=\"1\" \/><\/a><\/h2>\n<p align=\"left\">Nel mese di settembre di quest\u2019anno sono state annunciate al registro di commercio 2&#8217;728 nuove aziende, mentre in ottobre hanno raggiunto quota 3&#8217;253. Questo significa un aumento assoluto di 525 nuove registrazioni, ovvero un aumento relativo del 19.2%. Uno sguardo al confronto con il mese precedente fa vedere come la tendenza positiva osservata, non solo viene confermata, ma ha anche aumentato d\u2019intensit\u00e0. La crescita del numero di annunci di nuove aziende al registro di commercio da ottobre a settembre (+525) \u00e8 di quasi quattro volte superiore all\u2019aumento rispetto ai\u00a0 mesi da agosto a settembre (+138). Un ulteriore conferma viene data eseguendo il confronto con lo stesso periodo dell\u2019anno precedente. Le registrazioni del mese di ottobre 2012 (3&#8217;253) sorpassano di gran lunga quelle dell\u2019ottobre 2011 (2&#8217;934), con un aumento di ben 319 unit\u00e0, vale a dire il 10.9% in pi\u00f9.<\/p>\n<p align=\"left\">Responsabile di questo aumento osservato su scala nazionale in tutta la svizzera, sono gli sviluppi positivi delle singole regioni linguistiche e dei rispettivi cantoni. In tutte e tre le regioni linguistiche, nell\u2019ottobre del 2012 \u00e8 stato registrato un aumento del numero di annunci di nuove aziende al registro di commercio rispetto al mese precedente. La crescita pi\u00f9 significativa la fatta registrare il Ticino con un aumento del 38.3% (+67), seguito dalla Svizzera Romanda con un aumento del 27.8% (+206) e la Svizzera Tedesca con il 13.9% (+252). Nella Svizzera Tedesca l\u2019aumento \u00e8 stato influito principalmente dai cantoni di Zurigo (+149 risp. +31.6%), Argovia (+52 risp. +37.7%), Grigioni* (+41 risp. +87.2%) und Svitto* (+39 risp. +54.2%). Una diminuzione \u00e8 stata invece registrata nei cantoni Appenzello Esterno* (-19 risp. -51.4%) e Nidvaldo* (-18 risp. -56.3%), che hanno per\u00f2 esercitato un influenza minima sul risultato nazionale.<\/p>\n<p>* Questi cantoni registrano un numero mensile di nuove costituzioni poco elevato, per tanto anche un piccolo cambiamento assoluto, esercita una grande variazione percentuale.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fcostituzioni-di-nuove-aziende-nel-mese-di-ottobre-2012-a-confronto-con-il-mese-e-lanno-precedente%2F';\n  addthis_title  = 'Costituzioni+di+nuove+aziende+nel+mese+di+ottobre+2012+a+confronto+con+il+mese+e+l%26%238217%3Banno+precedente';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La tendenza positiva per quanto riguarda le costituzioni di nuove aziende nel mese di settembre, viene confermata anche nel mese di ottobre. Tendenza inaspettata se si confronta lo sviluppo dello stesso periodo dell&#8217;anno precedente. I dati dettagliati a riguardo nel seguente articolo.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[691,3],"tags":[],"class_list":["post-2035","post","type-post","status-publish","format-standard","hentry","category-curiosita","category-domande-generali"],"jetpack_publicize_connections":[],"views":1808,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-wP","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/2035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=2035"}],"version-history":[{"count":11,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/2035\/revisions"}],"predecessor-version":[{"id":3684,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/2035\/revisions\/3684"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=2035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=2035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=2035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}