{"id":1743,"date":"2012-01-17T09:14:41","date_gmt":"2012-01-17T07:14:41","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=1743"},"modified":"2014-03-24T14:43:57","modified_gmt":"2014-03-24T13:43:57","slug":"contabilita-delle-merci-i-conti-piu-importanti","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/contabilita-delle-merci-i-conti-piu-importanti\/","title":{"rendered":"Contabilit\u00e0 delle merci. I conti pi\u00f9 importanti per quanto riguarda acquisti e vendite."},"content":{"rendered":"<p><em>Aggiornato il 14 dicembre 2012<\/em><\/p>\n<p><strong>Per la contabilit\u00e0 legata agli acquisti e alla vendita di merce, vengono utilizzati in sostanza tre conti, secondo il metodo della tripartizione.<\/strong><\/p>\n<p><!--more--><\/p>\n<p><strong>Scorte merce<\/strong><br \/>\nIl conto scorte appartiene ai conti attivi del bilancio. Tramite gli acquisti aumenta il magazzino, tramite le vendite diminuisce. Il conto scorte viene registrato a prezzo di consegna. Nel prezzo di consegna viene tenuto conto, oltre al prezzo d\u2019acquisto della merce, anche dei costi d\u2019acquisizione aggiuntivi. Moltiplicando il prezzo di consegna con la quantit\u00e0 si ottiene il valore della merce acquisita.<br \/>\n<strong>Costo merce<\/strong><br \/>\n\u2028Il conto scorte diminuisce tramite la vendita di merce. Questa operazione si rispecchia nel conto con una registrazione in avere. La diminuzione di patrimonio viene poi registrata in dare come costo merce. L\u2019utilizzo di merce viene registrata a prezzo d\u2019acquisizione.<br \/>\n<strong>Ricavi da vendita merce<\/strong><br \/>\n<strong><\/strong>\u2028Il saldo della cassa diminuisce tramite acquisti a contanti, il conto debitori aumenta tramite vendite a credito, cosa che viene registrata in dare nel conto cassa e nel conto debitori. Gli aumenti di patrimonio vengono registrati in avere nel conto Ricavi merce. La registrazione non avviene in questo caso al prezzo d\u2019acquisto, ma al prezzo di vendita.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fcontabilita-delle-merci-i-conti-piu-importanti%2F';\n  addthis_title  = 'Contabilit%C3%A0+delle+merci.+I+conti+pi%C3%B9+importanti+per+quanto+riguarda+acquisti+e+vendite.';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aggiornato il 14 dicembre 2012 Per la contabilit\u00e0 legata agli acquisti e alla vendita di merce, vengono utilizzati in sostanza tre conti, secondo il metodo della tripartizione.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[7,3,5,4,84],"tags":[736,650,651,652,653,649],"class_list":["post-1743","post","type-post","status-publish","format-standard","hentry","category-ditta-individuale","category-domande-generali","category-sa","category-sagl","category-societa-in-nome-collettivo","tag-contabilita","tag-contabilita-delle-merci","tag-costi-merce","tag-ricavi-merce","tag-scorte-merce","tag-tripartizione"],"jetpack_publicize_connections":[],"views":4308,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-s7","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=1743"}],"version-history":[{"count":12,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1743\/revisions"}],"predecessor-version":[{"id":3726,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1743\/revisions\/3726"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=1743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=1743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=1743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}