{"id":1322,"date":"2011-06-06T09:00:37","date_gmt":"2011-06-06T07:00:37","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=1322"},"modified":"2014-03-24T14:44:02","modified_gmt":"2014-03-24T13:44:02","slug":"piu-costituzioni-e-meno-fallimenti-nel-gennaio-del-2011","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/piu-costituzioni-e-meno-fallimenti-nel-gennaio-del-2011\/","title":{"rendered":"Pi\u00f9 costituzioni e meno fallimenti nel gennaio 2011"},"content":{"rendered":"<p>In Svizzera nel gennaio 2011 sono state iscritte nel registro di commercio 3151 ditte. Ci\u00f2 equivale al 14% in pi\u00f9 rispetto al gennaio 2010. Soprattutto nei cantoni San Gallo e Appenzello esterno si registra un numero di ditte nuove superiore alla media. Un calo delle iscrizioni nel registro di commercio si \u00e8 per contro riscontrato nei cantoni Turgovia e Appenzello interno.<\/p>\n<p>A confronto con l&#8217;anno passato il numero di fallimenti di ditte \u00e8 sceso dell&#8217; 1% a 445. Di questi 312 fallimenti sono per insolvenza. Gli altri 133 fallimenti sono stati causati da lacune organizzative. Se si detraggono tutte le ditte cancellate a quelle appena costituite ed iscritte nel registro di commercio si ottiene nel gennaio 2011 una crescita netta di 883 ditte.<\/p>\n<p>Fonte: D&amp;B<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fpiu-costituzioni-e-meno-fallimenti-nel-gennaio-del-2011%2F';\n  addthis_title  = 'Pi%C3%B9+costituzioni+e+meno+fallimenti+nel+gennaio+2011';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>In Svizzera nel gennaio 2011 sono state iscritte nel registro di commercio 3151 ditte. Ci\u00f2 equivale al 14% in pi\u00f9 rispetto al gennaio 2010. Soprattutto nei cantoni San Gallo e Appenzello esterno si registra un numero di ditte nuove superiore alla media. Un calo delle iscrizioni nel registro di commercio si \u00e8 per contro riscontrato [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[3],"tags":[733,188,515],"class_list":["post-1322","post","type-post","status-publish","format-standard","hentry","category-domande-generali","tag-costituzione","tag-fallimento","tag-gennaio-2011"],"jetpack_publicize_connections":[],"views":1901,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-lk","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=1322"}],"version-history":[{"count":9,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1322\/revisions"}],"predecessor-version":[{"id":3776,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1322\/revisions\/3776"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=1322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=1322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=1322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}