{"id":1051,"date":"2011-02-07T18:59:11","date_gmt":"2011-02-07T16:59:11","guid":{"rendered":"http:\/\/blog.startups.ch\/it\/?p=1051"},"modified":"2014-03-24T14:44:05","modified_gmt":"2014-03-24T13:44:05","slug":"trasferimento-dellappartenenza-in-qualita-di-socio-nel-caso-di-una-sa","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/trasferimento-dellappartenenza-in-qualita-di-socio-nel-caso-di-una-sa\/","title":{"rendered":"Trasferimento della condizione di socio nel caso di una SA"},"content":{"rendered":"<p><em>Aggiornato il 3 gennaio 2013<\/em><\/p>\n<h4>L&#8217;appartenenza alla societ\u00e0 in qualit\u00e0 di socio di una societ\u00e0 anonima (SA) \u00e8 di regola trasferibile liberamente. Questo \u00e8 da ricondurre \u00a0al fatto che la SA \u00e8 una societ\u00e0 di capitali.<\/h4>\n<p>Il trasferimento della condizione di socio avviene essenzialmente attraverso il trasferimento delle azioni. Un&#8217;uscita dalla societ\u00e0 pu\u00f2 anche avvenire, quando le azione vengono cedute ad un nuovo o precedente azionista. \u00a0Unica eccezione rappresenta la riduzione del capitale.<\/p>\n<p>Il trasferimento delle azioni (e con esso anche il trasferimento della condizione di socio) pu\u00f2 in determinate circostanze essere limitato. La limitazione del trasferimento \u00e8 chiamata nel diritto azionario il vincolo. Date determinate premesse le azioni di una SA possono essere vincolate (limitazione secondo gli statuti). Per legge sussiste per le azioni nominali una trasferibilit\u00e0 limitata: azioni che non sono liberate interamente possono essere trasferite solo con il consenso della societ\u00e0. Le azioni al portatore posso solo essere cedute se liberate interamente.<\/p>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Ftrasferimento-dellappartenenza-in-qualita-di-socio-nel-caso-di-una-sa%2F';\n  addthis_title  = 'Trasferimento+della+condizione+di+socio+nel+caso+di+una+SA';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aggiornato il 3 gennaio 2013 L&#8217;appartenenza alla societ\u00e0 in qualit\u00e0 di socio di una societ\u00e0 anonima (SA) \u00e8 di regola trasferibile liberamente. Questo \u00e8 da ricondurre \u00a0al fatto che la SA \u00e8 una societ\u00e0 di capitali. Il trasferimento della condizione di socio avviene essenzialmente attraverso il trasferimento delle azioni. Un&#8217;uscita dalla societ\u00e0 pu\u00f2 anche avvenire, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[5],"tags":[428,293,297,427,429,731,79,431,430,298],"class_list":["post-1051","post","type-post","status-publish","format-standard","hentry","category-sa","tag-appartenenza-in-qualita-di-socio","tag-azioni-al-portatore","tag-azioni-nominali","tag-condizione-di-socio","tag-riduzione-del-capitale","tag-sa","tag-societa-di-capitali","tag-trasferibilita-limitata","tag-trasferimento-delle-azioni","tag-vincolo"],"jetpack_publicize_connections":[],"views":2518,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-gX","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=1051"}],"version-history":[{"count":12,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1051\/revisions"}],"predecessor-version":[{"id":3804,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/1051\/revisions\/3804"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=1051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=1051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}