{"id":10055,"date":"2023-03-01T07:15:31","date_gmt":"2023-03-01T06:15:31","guid":{"rendered":"https:\/\/blog.startups.ch\/it\/?p=10055"},"modified":"2023-02-26T17:16:43","modified_gmt":"2023-02-26T16:16:43","slug":"intervista-a-manuel-voigt-proprietario-e-fondatore-di-grow-grow-nut-svizzera","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/it\/intervista-a-manuel-voigt-proprietario-e-fondatore-di-grow-grow-nut-svizzera\/","title":{"rendered":"Intervista a Manuel Voigt, proprietario e fondatore di Grow-Grow Nut Svizzera"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Manuel Voigt ha fondato nel 2021\nGrow-Grow Nut Switzerland, un&#8217;azienda che permette ai suoi clienti di coltivare\na casa propria microgreens deliziosi e allo stesso tempo salutari in un vero\nguscio di noce di cocco. STARTUPS.CH lo ha incontrato per un&#8217;intervista.<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"803\" height=\"451\" data-attachment-id=\"10056\" data-permalink=\"https:\/\/blog.startups.ch\/it\/intervista-a-manuel-voigt-proprietario-e-fondatore-di-grow-grow-nut-svizzera\/immagine1-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2023\/02\/Immagine1.png?fit=803%2C451&amp;ssl=1\" data-orig-size=\"803,451\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Immagine1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2023\/02\/Immagine1.png?fit=803%2C451&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2023\/02\/Immagine1.png?fit=803%2C451&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/it\/wp-content\/uploads\/2023\/02\/Immagine1.png?resize=803%2C451&#038;ssl=1\" alt=\"Manuel Voigt\" class=\"wp-image-10056\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Quali sono state le motivazioni\nche l&#8217;hanno spinta a fondare la sua azienda?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il desiderio di creare qualcosa di mio e la semplice curiosit\u00e0. Molti miei\nconoscenti sono stati coinvolti in start-up e hanno lanciato idee davvero\ninteressanti. All&#8217;inizio era anche relativamente facile raggiungere nuovi\nclienti con il marketing online e presentare buone idee.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avviare un&#8217;attivit\u00e0 in proprio \u00e8\nmolto eccitante e spesso comporta molte domande senza risposta. Come ha vissuto\nquesta fase?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 2019 ho fondato con un buon amico in Germania l&#8217;azienda\n&#8220;Keimgr\u00fcn&#8221;, che si occupa di microgreens. Durante questo periodo, ho\navuto modo di imparare molto sull&#8217;avvio di un&#8217;impresa e sulle sfide ad essa\nassociate. Queste conoscenze mi hanno aiutato nell&#8217;avvio dell&#8217;attivit\u00e0 in\nSvizzera e hanno accelerato notevolmente molti processi. Tuttavia, \u00e8 sempre un\nperiodo stressante perch\u00e9 \u00e8 impossibile pianificare tutto alla perfezione in\nanticipo: alcune cose non vanno come desiderato e allora \u00e8 importante mantenere\nil sangue freddo e trarre il meglio dalla situazione!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come \u00e8 cambiata la sua vita da\nquando ha avviato la sua attivit\u00e0?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mio suocero diceva sempre che lavorare in proprio significa &#8220;me\nstesso&#8221; e &#8220;tutto il tempo&#8221;. In molti settori, posso ben\nimmaginare che sia ancora cos\u00ec. Nel mondo dell&#8217;e-commerce, beneficiamo del\nfatto che quasi tutto \u00e8 completamente digitale. Fin dall&#8217;inizio mi sono\naffidato a processi aziendali automatizzati, che mi fanno risparmiare un&#8217;enorme\nquantit\u00e0 di tempo o lo liberano per altre attivit\u00e0 (importanti).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuttavia, lavorare in proprio \u00e8 fondamentalmente diverso rispetto a un\nrapporto di lavoro dipendente. Ogni decisione viene presa in modo ancora pi\u00f9\ncoscienzioso e spesso ti segue fino a tarda notte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quali sfide potrebbe affrontare\nuna start-up nel vostro mercato?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A causa della pandemia, molte aziende hanno dovuto riorientarsi e ora hanno\nscoperto anche il mercato online. Da un lato, questo \u00e8 un grande sviluppo\nperch\u00e9 la digitalizzazione \u00e8 stata notevolmente ampliata. Dall&#8217;altro, comporta\nanche un aumento dei costi di marketing per le aziende.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soprattutto per le start-up con una piccola gamma di prodotti, questa \u00e8 una\ngrande sfida, perch\u00e9 il marketing online sta diventando sempre pi\u00f9 difficile e\ncostoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo \u00e8 chiaramente visibile nei &#8220;pacchetti di offerta&#8221;\nnell&#8217;e-commerce: in passato, c&#8217;erano spesso pacchetti di prodotti iniziali per\n20-30 CHF, oggi sono gi\u00e0 50 CHF e oltre. Ci\u00f2 \u00e8 dovuto al fatto che i costi di\nmarketing per utente sono significativamente pi\u00f9 alti e quindi anche le vendite\nper utente devono aumentare perch\u00e9 l&#8217;attivit\u00e0 sia redditizia. Tuttavia, ci\u00f2 \u00e8\nin contrasto con l&#8217;attuale tendenza del mercato, in quanto i potenziali clienti\nsono pi\u00f9 propensi a spendere meno.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cosa le piace in particolare\ndella sua vita di imprenditore\/manager di una start-up?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;indipendenza. Grazie all&#8217;automazione e alla collaborazione con il nostro\npartner per le consegne, in teoria posso servire il groove di Grow-Grow da\nqualsiasi parte del mondo. Trovo inoltre fantastico lavorare con laboratori per\npersone con esigenze speciali. L&#8217;inclusione \u00e8 un tema molto importante, che si\ntraduce in un vantaggio per l&#8217;azienda e per le persone.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prospettive future: Dove si vede\ntra cinque anni?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il mio desiderio \u00e8 quello di portare molto pi\u00f9 verde sui davanzali delle\nfinestre delle persone e di attirare l&#8217;attenzione su quanto sia facile e\naffascinante coltivare micro-ortaggi e germogli, anche senza un giardino\nproprio! Nei prossimi anni vorrei anche creare una piattaforma sul tema dei\nmicrogreen in Svizzera.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quali consigli darebbe alle\nstart-up in erba?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avete una buona idea? Allora investite un po&#8217; di tempo per realizzare un\nprototipo, fatelo provare ad amici e parenti e poi avviate la vostra attivit\u00e0!\nSe non ora, quando? Alla fine, gli unici rimpianti sono le cose che non si\nprovano. Assicuratevi di poter portare avanti il vostro progetto con cuore e\nconcentrazione e di poter affrontare per tempo le condizioni quadro,\nsoprattutto dal punto di vista finanziario. Collegatevi con le reti della\nvostra zona e imparate dai successi e dagli errori degli altri fondatori!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ultima domanda: per quali\nragioni ha deciso di avviare la sua attivit\u00e0 con STARTUPS.CH?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Penso che sia semplicemente geniale che startups.ch offra questo servizio.\nLa creazione di un&#8217;impresa \u00e8 molto complessa, a seconda dell&#8217;attivit\u00e0, e si\npossono fare molte cose sbagliate che in seguito costano molto denaro e\/o\nnervi. Grazie a startups.ch non ho avuto alcuna preoccupazione. \u00c8 un grande\nvantaggio potersi affidare alla loro esperienza e avere sempre a disposizione\nun interlocutore competente. Grazie ancora per questo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avete un\u2019idea innovativa che vorreste implementare? Gli esperti di\nSTARTUPS.CH saranno lieti di accompagnarvi verso l\u2019indipendenza professionale!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Mompreneur: <a href=\"http:\/\/www.mom-preneur.ch\">www.mom-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Dadpreneur: <a href=\"http:\/\/www.dad-preneur.ch\">www.dad-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Seniorpreneur: <a href=\"http:\/\/www.senior-preneur.ch\">www.senior-preneur.ch<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inizia come Youngpreneur: <a href=\"http:\/\/www.young-preneur.ch\">www.young-preneur.ch<\/a> <\/p>\n\n\n\n<a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/contatto\/appuntamento\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Contattaci per un colloquio personale<\/a><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/it\/servizi\/costituzione-impresa\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Calcola un&#8217;offerta e costituisci ora<\/a>\n<div class=\"addthis_div\"><script type=\"text\/javascript\">\n  addthis_url    = 'https%3A%2F%2Fblog.startups.ch%2Fit%2Fintervista-a-manuel-voigt-proprietario-e-fondatore-di-grow-grow-nut-svizzera%2F';\n  addthis_title  = 'Intervista+a+Manuel+Voigt%2C+proprietario+e+fondatore+di+Grow-Grow+Nut+Svizzera';\n  addthis_pub    = 'fabware';\n<\/script><script type=\"text\/javascript\" src=\"http:\/\/s7.addthis.com\/js\/addthis_widget.php?v=12\" ><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Manuel Voigt ha fondato nel 2021 Grow-Grow Nut Switzerland, un&#8217;azienda che permette ai suoi clienti di coltivare a casa propria microgreens deliziosi e allo stesso tempo salutari in un vero guscio di noce di cocco. STARTUPS.CH lo ha incontrato per un&#8217;intervista. Quali sono state le motivazioni che l&#8217;hanno spinta a fondare la sua azienda? Il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24],"tags":[1042],"class_list":["post-10055","post","type-post","status-publish","format-standard","hentry","category-costituzione","tag-storie-di-successo"],"jetpack_publicize_connections":[],"views":621,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ydF5-2Cb","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/10055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/comments?post=10055"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/10055\/revisions"}],"predecessor-version":[{"id":10057,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/posts\/10055\/revisions\/10057"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/media?parent=10055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/categories?post=10055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/it\/wp-json\/wp\/v2\/tags?post=10055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}