{"id":7544,"date":"2019-04-30T10:00:22","date_gmt":"2019-04-30T08:00:22","guid":{"rendered":"https:\/\/www.startups.ch\/fr\/blog\/?p=7544"},"modified":"2020-04-22T12:30:22","modified_gmt":"2020-04-22T10:30:22","slug":"imposition-des-monnaies-cryptographiques-commerce-de-monnaies-cryptographiques","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/fr\/2019\/04\/30\/imposition-des-monnaies-cryptographiques-commerce-de-monnaies-cryptographiques\/","title":{"rendered":"Imposition des monnaies cryptographiques : Commerce de monnaies cryptographiques"},"content":{"rendered":"<h2>Bitcoin, Ethereum, Ripple ou EOS : les monnaies cryptographiques sont de plus en plus populaires et le choix entre les diff\u00e9rentes monnaies cryptographiques est \u00e9norme. Mais quelle est leur incidence sur votre d\u00e9claration fiscale ? Nous vous expliquons la distinction entre la gestion priv\u00e9e et le n\u00e9goce commercial de monnaies cryptographiques.<\/h2>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7539\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/fr\/blog\/wp-content\/uploads\/2019\/02\/thought-catalog-674419-unsplash-1200x899.jpg?resize=1200%2C899&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"899\" data-recalc-dims=\"1\" \/><\/strong><\/p>\n<p>Les gains en capital provenant de monnaies cryptographiques provenant de capitaux priv\u00e9s sont g\u00e9n\u00e9ralement non imposables et les pertes \u00e9ventuelles ne sont pas d\u00e9ductibles d&#8217;imp\u00f4t. Toutefois, si les monnaies cryptographiques sont consid\u00e9r\u00e9es comme des actifs commerciaux, les gains sont imposables et les pertes peuvent \u00eatre d\u00e9duites. La distinction entre le n\u00e9goce commercial de monnaies cryptographiques (et donc le travail ind\u00e9pendant) et la gestion de fortune priv\u00e9e est par cons\u00e9quent ici d\u00e9terminante. Si sa propre gestion de fortune prend une telle ampleur qu&#8217;il est n\u00e9cessaire de parler d&#8217;une activit\u00e9 commerciale, les b\u00e9n\u00e9fices qu&#8217;elle g\u00e9n\u00e8re sont impos\u00e9s comme des revenus provenant d&#8217;activit\u00e9s commerciales. Outre l&#8217;imp\u00f4t sur le revenu, les cotisations sociales telles que l&#8217;AVS, l&#8217;AI ou les APG sont \u00e9galement dues.<\/p>\n<p>Dans le cas des monnaies cryptographiques, il est tr\u00e8s difficile de faire une distinction entre gestion priv\u00e9e ou n\u00e9goce professionnel, c&#8217;est pourquoi l&#8217;AFC \u00e9num\u00e8re les crit\u00e8res sur la base desquels le n\u00e9goce professionnel de titres peut au moins \u00eatre exclu Les autorit\u00e9s fiscales concluent dans tous les cas \u00e0 l\u2019existence d\u2019une gestion de la fortune priv\u00e9e et, par cons\u00e9quent, \u00e0 la qualification de gains en capital priv\u00e9s lorsque les crit\u00e8res suivants sont remplis cumulativement.<\/p>\n<p><em>1.Les titres vendus ont \u00e9t\u00e9 d\u00e9tenus durant 6 mois au moins.<\/em><\/p>\n<p><em>2. Le volume total des transactions (somme de tous les achats et de toutes les ventes) ne repr\u00e9sente pas, par ann\u00e9e civile, plus du quintuple du montant des titres et des avoirs au d\u00e9but de la p\u00e9riode fiscale.<\/em><\/p>\n<p><em>3. La r\u00e9alisation de gains en capital provenant d\u2019op\u00e9rations sur titres n\u2019est pas n\u00e9cessaire en vue de remplacer des revenus manquants ou ayant cess\u00e9 dans le but d\u2019assurer le train de vie du contribuable. C\u2019est normalement le cas lorsque les gains en capital r\u00e9alis\u00e9s repr\u00e9sentent moins de 50 % du revenu net de la p\u00e9riode fiscale consid\u00e9r\u00e9e.<\/em><\/p>\n<p><em>4. Les placements ne sont pas financ\u00e9s par des fonds \u00e9trangers ou les rendements de fortune imposables provenant des titres (par ex. les int\u00e9r\u00eats, les dividendes, etc.) sont plus \u00e9lev\u00e9s que la part proportionnelle des int\u00e9r\u00eats passifs.<\/em><\/p>\n<p><em>5. L\u2019achat et la vente de produits d\u00e9riv\u00e9s (en particulier d\u2019options) se limitent \u00e0 la couverture des positions-titres du contribuable.<\/em><\/p>\n<p>Si ces crit\u00e8res sont remplis cumulativement, il s&#8217;agit d&#8217;une gestion de fortune priv\u00e9e dont les b\u00e9n\u00e9fices sont exon\u00e9r\u00e9s d&#8217;imp\u00f4t. Si tous ne sont pas cumulativement remplis, la d\u00e9limitation s&#8217;effectue en examinant l&#8217;ensemble des circonstances du cas en question. Il existe diverses indications selon lesquelles le n\u00e9goce professionnel de titres est possible, l&#8217;existence d&#8217;un indice pouvant suffire :<\/p>\n<p><em>1. Le volume des transactions (fr\u00e9quence des transactions et courte p\u00e9riode de d\u00e9tention)<\/em><\/p>\n<p><em>2. Recours \u00e0 d&#8217;importants fonds externes pour financer les transactions commerciales<\/em><\/p>\n<p><em>3. Utilisation de d\u00e9riv\u00e9s<\/em><\/p>\n<p><em>4. La mani\u00e8re syst\u00e9matique ou planifi\u00e9e de proc\u00e9der<\/em><\/p>\n<p><em>5. Le lien \u00e9troit entre les op\u00e9rations et l&#8217;activit\u00e9 professionnelle du contribuable et le recours \u00e0 une expertise particuli\u00e8re<\/em><\/p>\n<p><strong>D\u00e9claration d\u2019imp\u00f4ts priv\u00e9e \u2013 un jeu d\u2019enfant gr\u00e2ce \u00e0 taxea !<\/strong><\/p>\n<p>Gr\u00e2ce \u00e0 notre application <a href=\"https:\/\/www.taxea.ch\/fr\/home\">taxea<\/a>, vous pouvez pr\u00e9parer votre d\u00e9claration d\u2019imp\u00f4ts en toute facilit\u00e9.<\/p>\n<p>Rendez-vous sur <a href=\"https:\/\/www.taxea.ch\/fr\/home\">taxea<\/a> et laissez-vous convaincre par notre service fiscal innovant ! Nous vous garantissons un maximum de d\u00e9ductions et un minimum de charges fiscales.<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/fr\/services\/creation-entreprise\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Se lancer, cr\u00e9er son entreprise<\/a>\u00a0<a class=\"postButton\" href=\"https:\/\/www.taxea.ch\/fr\/home\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb taxea<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bitcoin, Ethereum, Ripple ou EOS : les monnaies cryptographiques sont de plus en plus populaires et le choix entre les diff\u00e9rentes monnaies cryptographiques est \u00e9norme. Mais quelle est leur incidence sur votre d\u00e9claration fiscale ? Nous vous expliquons la distinction entre la gestion priv\u00e9e et le n\u00e9goce commercial de monnaies cryptographiques.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1,12],"tags":[],"jetpack_publicize_connections":[],"aioseo_notices":[],"views":1749,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7y0qY-1XG","_links":{"self":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/7544"}],"collection":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/comments?post=7544"}],"version-history":[{"count":6,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/7544\/revisions"}],"predecessor-version":[{"id":8855,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/7544\/revisions\/8855"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/media?parent=7544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/categories?post=7544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/tags?post=7544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}