{"id":4789,"date":"2017-01-24T11:50:57","date_gmt":"2017-01-24T10:50:57","guid":{"rendered":"https:\/\/www.startups.ch\/fr\/blog\/?p=4789"},"modified":"2020-04-22T13:47:17","modified_gmt":"2020-04-22T11:47:17","slug":"reforme-de-limposition-societes-iii-y-aura-referendum","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/fr\/2017\/01\/24\/reforme-de-limposition-societes-iii-y-aura-referendum\/","title":{"rendered":"R\u00e9forme de l&#8217;imposition des soci\u00e9t\u00e9s III : Il y aura un r\u00e9f\u00e9rendum"},"content":{"rendered":"<h2>Apr\u00e8s de longs d\u00e9bats, la r\u00e9forme de l&#8217;imposition des soci\u00e9t\u00e9s III entre dans la phase d\u00e9licate: le 12 F\u00e9vrier 2017 le peuple suisse serra amen\u00e9 \u00e0 voter sur cette r\u00e9forme fiscale. D\u00e9couvrez ce que cette r\u00e9forme peut changer et les cons\u00e9quences que cela pourrait avoir au niveau cantonal.<\/h2>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4790\" src=\"https:\/\/i0.wp.com\/www.startups.ch\/fr\/blog\/wp-content\/uploads\/2017\/01\/unternehmenssteuerreform-iii-1200x800.jpg?resize=674%2C450&#038;ssl=1\" alt=\"\" width=\"674\" height=\"450\" data-recalc-dims=\"1\" \/>(Source image: https:\/\/www.pixabay.com)<\/p>\n<h3>Qu&#8217;est-ce veut la r\u00e9forme?<\/h3>\n<p>La Suisse n&#8217;a, jusqu&#8217;\u00e0 pr\u00e9sent, pas tax\u00e9 les profits g\u00e9n\u00e9r\u00e9s \u00e0 l&#8217;\u00e9tranger de certaines entreprises de la m\u00eame mani\u00e8re que ceux g\u00e9n\u00e9r\u00e9s sur le territoire suisse. Cette pratique a rendu la Suisse attrayante comme lieu d&#8217;affaires pour les entreprises \u00e9trang\u00e8res. L&#8217;UE et l&#8217;OCDE ne sont cependant plus d&#8217;accord d&#8217;accepter cela. Par cons\u00e9quent, les privil\u00e8ges accord\u00e9s aux holdings doivent \u00eatre abolis. \u00c0 l&#8217;avenir, toutes les entreprises seront impos\u00e9es de la m\u00eame mani\u00e8re.<\/p>\n<p>Afin d&#8217;\u00e9viter un exode des entreprises, cette r\u00e9forme souhaite am\u00e9liorer les conditions fiscales pour toutes les entreprises. La hauteur et la conception de ces imp\u00f4ts d\u00e9pendent par contre principalement des lois fiscales cantonales.<\/p>\n<p>Afin de ne pas sanctionner tr\u00e8s s\u00e9v\u00e8rement les entreprises, les cantons ont les possibilit\u00e9s suivantes:<\/p>\n<ul>\n<li>Abaissement de l&#8217;imp\u00f4t sur le revenu: 16 cantons y pensent;<\/li>\n<li>Une taxation plus basse des droits de propri\u00e9t\u00e9 immat\u00e9rielle (brevets, marques, designs,&#8230;): 9 cantons;<\/li>\n<li>Subvention pour les co\u00fbts de recherche: 8 cantons;<\/li>\n<li>\n<div class=\"translation\">Introduction d&#8217;un imp\u00f4t sur le revenu \u00e0 int\u00e9r\u00eat ajust\u00e9, qui pr\u00e9voit la d\u00e9duction d&#8217;un taux d&#8217;int\u00e9r\u00eat th\u00e9orique \u00e0 l&#8217;\u00e9quit\u00e9 sup\u00e9rieure \u00e0 la moyenne: 5 cantons.<\/div>\n<\/li>\n<\/ul>\n<div class=\"text-wrap\">\n<h3 class=\"translation\">O\u00f9 en est la r\u00e9forme?<\/h3>\n<div class=\"translation\">La r\u00e9forme de l&#8217;imposition des soci\u00e9t\u00e9s III a \u00e9t\u00e9 adopt\u00e9e par le Parlement. Les partis de gauche (SP, Vert, syndicats) ont lanc\u00e9 un referendum pour l&#8217;emp\u00eacher. Maintenant, c&#8217;est au peuple suisse de d\u00e9cider du sort de cette r\u00e9forme le 12 f\u00e9vrier 2017.<\/div>\n<div class=\"translation\">Les opposants se plaignent que les entreprises seraient trop favoris\u00e9es et que les co\u00fbts seraient r\u00e9percut\u00e9s par cons\u00e9quent sur les consommateurs et les salari\u00e9s.<\/div>\n<\/div>\n<div class=\"translation\"><\/div>\n<div>\n<p><strong>D\u00e9clarer ses imp\u00f4ts en tant qu\u2019entreprise \u2013 un jeu d\u2019enfant gr\u00e2ce \u00e0 taxea !<\/strong><\/p>\n<p>Gr\u00e2ce \u00e0 notre application <a href=\"https:\/\/www.taxea.ch\/fr\/home\">taxea<\/a>, vous pouvez pr\u00e9parer la d\u00e9claration d\u2019imp\u00f4ts de votre entreprise en toute facilit\u00e9.<\/p>\n<p>Rendez-vous sur <a href=\"https:\/\/www.taxea.ch\/fr\/home\">taxea<\/a> et laissez-vous convaincre par notre service fiscal innovant ! Nous vous garantissons un maximum de d\u00e9ductions et un minimum de charges fiscales.<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/fr\/services\/creation-entreprise\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb Se lancer, cr\u00e9er son entreprise<\/a>\u00a0<a class=\"postButton\" href=\"https:\/\/www.taxea.ch\/fr\/home\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bb taxea<\/a><\/p>\n<\/div>\n<div class=\"text-wrap\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s de longs d\u00e9bats, la r\u00e9forme de l&#8217;imposition des soci\u00e9t\u00e9s III entre dans la phase d\u00e9licate: le 12 F\u00e9vrier 2017 le peuple suisse serra amen\u00e9 \u00e0 voter sur cette r\u00e9forme fiscale. D\u00e9couvrez ce que cette r\u00e9forme peut changer et les cons\u00e9quences que cela pourrait avoir au niveau cantonal.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"R\u00e9forme fiscale III : ce qu'il faut savoir! \r\n#startups #tax #entrepreneurship #CestMonDroit","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[9],"tags":[],"jetpack_publicize_connections":[],"aioseo_notices":[],"views":1450,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7y0qY-1ff","_links":{"self":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/4789"}],"collection":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/comments?post=4789"}],"version-history":[{"count":11,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/4789\/revisions"}],"predecessor-version":[{"id":8912,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/4789\/revisions\/8912"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/media?parent=4789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/categories?post=4789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/tags?post=4789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}