{"id":4522,"date":"2016-10-25T11:43:27","date_gmt":"2016-10-25T09:43:27","guid":{"rendered":"https:\/\/www.startups.ch\/fr\/blog\/?p=4522"},"modified":"2016-10-25T11:43:27","modified_gmt":"2016-10-25T09:43:27","slug":"creation-dune-succursale-expliquee-simplement-video-informative","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/fr\/2016\/10\/25\/creation-dune-succursale-expliquee-simplement-video-informative\/","title":{"rendered":"Cr\u00e9ation d\u2019une succursale expliqu\u00e9e simplement \u2013 Nouvelle vid\u00e9o informative"},"content":{"rendered":"<h2><strong>Vous souhaitez agrandir votre entreprise et cr\u00e9er de nouvelles agences ou de nouveaux bureaux en Suisse\u00a0? La cr\u00e9ation d\u2019une succursale semble \u00eatre la meilleure solution qui s\u2019offre \u00e0 vous. Les \u00e9tapes de la cr\u00e9ation d&#8217;une succursale sont expliqu\u00e9es de mani\u00e8re simple dans notre nouvelle vid\u00e9o.\u00a0 <\/strong><!--more--><\/h2>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/L60twvm5gKU?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-US&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<h3><strong>Les \u00e9tapes de la cr\u00e9ation d&#8217;une succursale expliqu\u00e9es simplement<\/strong><\/h3>\n<p>Une succursale est une exploitation qui d\u00e9pend juridiquement d\u2019une maison m\u00e8re. Elle exerce dans ses propres locaux une activit\u00e9 similaire que cette derni\u00e8re. La fiduciaire Findea a son si\u00e8ge social \u00e0 Winterthur. Cependant elle a des succursales \u00e0 Zurich, St.Gall, Berne, Lucerne, Zug, B\u00e2le, Lugano et Gen\u00e8ve.<\/p>\n<h3><strong>Avantage d\u2019une succursale <\/strong><\/h3>\n<p>Pour la cr\u00e9ation d\u2019une succursale, aucun apport de capital suppl\u00e9mentaire n\u2019est n\u00e9cessaire, comme c\u2019est le cas pour une SA par exemple. Les soci\u00e9t\u00e9s suisses peuvent \u00e9galement cr\u00e9er des succursales \u00e0 l\u2019\u00e9tranger, ce qui permet souvent de gagner une nouvelle client\u00e8le et de s\u2019ouvrir les portes de nouveaux march\u00e9s.<\/p>\n<p>Les soci\u00e9t\u00e9s \u00e9trang\u00e8res peuvent par ailleurs aussi fonder une succursale en Suisse. Pour ce faire, au moins un soci\u00e9taire doit avoir son domicile en Suisse et \u00eatre inscrit au registre du commerce. La succursale doit porter le m\u00eame nom que la soci\u00e9t\u00e9 m\u00e8re. Cependant des ajouts sont n\u00e9anmoins possibles.<\/p>\n<h3><strong>D\u00e9savantages d\u2019une succursale <\/strong><\/h3>\n<p>La responsabilit\u00e9 d\u2019une succursale est illimit\u00e9e. La soci\u00e9t\u00e9 m\u00e8re doit r\u00e9pondre de la totalit\u00e9 des dettes contract\u00e9es par la succursale.<\/p>\n<p>La succursale est li\u00e9e de mani\u00e8re juridique \u00e0 la soci\u00e9t\u00e9 m\u00e8re. Si cette derni\u00e8re venait \u00e0 faire faillite, la succursale serait, faute d\u2019ind\u00e9pendance juridique, \u00e9galement dissoute.<\/p>\n<p>&nbsp;<\/p>\n<p><a class=\"postButton\" href=\"https:\/\/www.startups.ch\/fr\/blog\/category\/questions-juridiques\/\" target=\"_blank\">\u00bb Autres articles juridiques<\/a> <a class=\"postButton\" href=\" https:\/\/startups.ch\/fr\/preparer\/business-plan\/qui-besoin\/\" target=\"_blank\">\u00bb R\u00e9diger son Business plan<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous souhaitez agrandir votre entreprise et cr\u00e9er de nouvelles agences ou de nouveaux bureaux en Suisse\u00a0? La cr\u00e9ation d\u2019une succursale semble \u00eatre la meilleure solution qui s\u2019offre \u00e0 vous. Les \u00e9tapes de la cr\u00e9ation d&#8217;une succursale sont expliqu\u00e9es de mani\u00e8re simple dans notre nouvelle vid\u00e9o.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"D\u00e9couvrez gr\u00e2ce \u00e0 notre nouvelle vid\u00e9o \u00e0 quel point il est facile de cr\u00e9er une succursale. \r\n#startups #goodtoknow #entrepreneurship","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"aioseo_notices":[],"views":3115,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7y0qY-1aW","_links":{"self":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/4522"}],"collection":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/comments?post=4522"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/4522\/revisions"}],"predecessor-version":[{"id":4525,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/4522\/revisions\/4525"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/media?parent=4522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/categories?post=4522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/tags?post=4522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}