{"id":3685,"date":"2015-07-01T12:17:44","date_gmt":"2015-07-01T10:17:44","guid":{"rendered":"http:\/\/blog.startups.ch\/fr\/?p=3685"},"modified":"2015-07-14T12:20:00","modified_gmt":"2015-07-14T10:20:00","slug":"inscriptions-au-registre-du-commerce-au-premier-semestre-2015-le-boom-des-createurs-dentreprises-est-il-passe","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/fr\/2015\/07\/01\/inscriptions-au-registre-du-commerce-au-premier-semestre-2015-le-boom-des-createurs-dentreprises-est-il-passe\/","title":{"rendered":"Inscriptions au registre du commerce au premier semestre 2015 : le boom des cr\u00e9ateurs d\u2019entreprises est-il pass\u00e9 ?"},"content":{"rendered":"<p>Un recul cons\u00e9quent du nombre d\u2019inscriptions au registre du commerce au premier semestre 2015.<\/p>\n<p>En p\u00e9riode \u00e9conomique incertaine, les cr\u00e9ateurs d\u2019entreprises en Suisse en ressentent aussi les effets. Le nombre de nouvelles inscriptions au registre du commerce Suisse du premier semestre 2015 a montr\u00e9 un recul par rapport \u00e0 la m\u00eame p\u00e9riode l\u2019an pass\u00e9. C\u2019est ce que montre le relev\u00e9 de chiffres le plus r\u00e9cent par les sp\u00e9cialistes de STARTUPS.CH, entreprise de cr\u00e9ations d\u2019entreprises en ligne.<br \/>\nLe nombre de nouvelles inscriptions au registre du commerce suisse a recul\u00e9 de 2.4 pour cent sur 20\u2018737 par rapport \u00e0 la m\u00eame p\u00e9riode l\u2019an pass\u00e9. La suppression du taux plancher EUR-CHF le 15 janvier 2015 et la situation \u00e9conomique incertaine de l\u2019UE ont fortement d\u00e9stabilis\u00e9 les cr\u00e9ateurs d\u2019entreprises suisses.\u00a0Depuis 2012, une hausse annuelle en terme de cr\u00e9ations d\u2019entreprises pouvait \u00eatre observ\u00e9e. En 2014, le paroxysme a \u00e9t\u00e9 atteint, avec 41&#8217;239 entreprises cr\u00e9\u00e9es. Le premier semestre 2015, au contraire de cette m\u00eame p\u00e9riode en 2014, a montr\u00e9 un recul mois apr\u00e8s mois en termes de nouvelles cr\u00e9ations. Seul le mois de mars a pr\u00e9sent\u00e9 4.6 pour cent de plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/07\/Grafik_DE_Entwicklung_Handelsregistereintragungen_Halbjahreszahlen_2015.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3686\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/07\/Grafik_DE_Entwicklung_Handelsregistereintragungen_Halbjahreszahlen_2015.png?resize=690%2C586\" alt=\"Grafik_DE_Entwicklung_Handelsregistereintragungen_Halbjahreszahlen_2015\" width=\"690\" height=\"586\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/07\/Grafik_DE_Entwicklung_Handelsregistereintragungen_Halbjahreszahlen_2015.png?w=690&amp;ssl=1 690w, https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/07\/Grafik_DE_Entwicklung_Handelsregistereintragungen_Halbjahreszahlen_2015.png?resize=300%2C254&amp;ssl=1 300w\" sizes=\"(max-width: 690px) 100vw, 690px\" data-recalc-dims=\"1\" \/><\/a><br \/>\n<strong>Beaucoup de nouvelles cr\u00e9ations de la Suisse romande<\/strong><\/p>\n<p>Chaque canton a montr\u00e9 un d\u00e9veloppement diff\u00e9rent de nombre de nouvelles inscriptions. La tendance pour les cr\u00e9ations d\u2019entreprises revient au canton de Zurich qui poss\u00e8de une population concentr\u00e9e, une forte \u00e9conomie et un m\u00e9lange de branches. 17.9 pour cent des nouvelles cr\u00e9ations viennent de ce canton. Les 3\u2019716 nouvelles inscriptions du premier semestre repr\u00e9sentent 0.5 pour cent de moins que l\u2019an dernier. Viennent ensuite les cantons de Vaud avec 9.1 pour cent et Gen\u00e8ve avec 8.93 pour cent de la totalit\u00e9 des nouvelles cr\u00e9ations. 7.4 pour cent de toutes les nouvelles entreprises viennent du canton du Tessin, le pla\u00e7ant \u00e0 la quatri\u00e8me place sur le ranking des cantons. Une hausse r\u00e9jouissante a \u00e9t\u00e9 enregistr\u00e9e en Nidwald (+ 19.2 pour cent) et Valais (+ 12.4 pour cent).<br \/>\nEn tant que si\u00e8ge d\u2019entreprise fiscalement avantageux en Suisse, le canton de Lucerne reste le pr\u00e9f\u00e9r\u00e9 pour les nouvelles cr\u00e9ations et voit une hausse de 4.6 pour cent (cela repr\u00e9sente une augmentation de +0.73 pour cent par rapport \u00e0 2014).<br \/>\n<strong>La forme juridique pr\u00e9f\u00e9r\u00e9e est la S\u00e0rl<\/strong><br \/>\nLa forme juridique pr\u00e9f\u00e9r\u00e9e pour les nouvelles cr\u00e9ations d\u2019entreprises est, comme avant, la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e (S\u00e0rl). Plus d\u2019un tiers des cr\u00e9ations se font avec cette forme juridique. Cette derni\u00e8re est suivie de pr\u00e8s par la raison individuelle. Cette pr\u00e9f\u00e9rence pour la S\u00e0rl s\u2019explique d\u2019une part car la responsabilit\u00e9 est limit\u00e9e, rendant ainsi le risque calculable pour un jeune entrepreneur, et d\u2019autre part car le capital initial est de CHF 20&#8217;000.-. Une raison individuelle montre ici un avantage, car il n\u2019y a pas de capital initial requis pour la cr\u00e9ation d\u2019une entreprise et tr\u00e8s peu de r\u00e9glementation l\u00e9gale.<br \/>\n<strong>Rapport de fondation<\/strong><br \/>\nChaque mois, le nouveau rapport de fondation de STARTUPS.CH est disponible sur www.startups.ch. A l\u2019aide d\u2019un index de fondation et un barom\u00e8tre de fondation, le rapport fournit une vue d\u2019ensemble sur le monde des cr\u00e9ations d\u2019entreprises en Suisse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un recul cons\u00e9quent du nombre d\u2019inscriptions au registre du commerce au premier semestre 2015. En p\u00e9riode \u00e9conomique incertaine, les cr\u00e9ateurs d\u2019entreprises en Suisse en ressentent aussi les effets. Le nombre de nouvelles inscriptions au registre du commerce Suisse du premier semestre 2015 a montr\u00e9 un recul par rapport \u00e0 la m\u00eame p\u00e9riode l\u2019an pass\u00e9. C\u2019est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[276,275,71],"jetpack_publicize_connections":[],"aioseo_notices":[],"views":1495,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7y0qY-Xr","_links":{"self":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/3685"}],"collection":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/comments?post=3685"}],"version-history":[{"count":1,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/3685\/revisions"}],"predecessor-version":[{"id":3687,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/3685\/revisions\/3687"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/media?parent=3685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/categories?post=3685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/tags?post=3685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}