{"id":3636,"date":"2015-05-02T13:19:47","date_gmt":"2015-05-02T11:19:47","guid":{"rendered":"http:\/\/blog.startups.ch\/fr\/?p=3636"},"modified":"2015-05-04T11:35:21","modified_gmt":"2015-05-04T09:35:21","slug":"la-startup-vaudoise-esmart-remporte-le-prix-strategis","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/fr\/2015\/05\/02\/la-startup-vaudoise-esmart-remporte-le-prix-strategis\/","title":{"rendered":"La startup vaudoise eSMART remporte le prix Strategis"},"content":{"rendered":"<p><strong>Le 28 avril dernier, le jury du Prix Strategis a d\u00e9cern\u00e9 un prix de CHF 50&#8217;000 \u00e0 la startup eSMART pour f\u00e9liciter son ing\u00e9nieux syst\u00e8me de domotique.<\/strong><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/05\/Capture-de\u0301cran-2015-05-02-13.16.13.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3637\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/05\/Capture-de\u0301cran-2015-05-02-13.16.13.png?resize=662%2C419\" alt=\"eSMART Strategis\" width=\"662\" height=\"419\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/05\/Capture-de\u0301cran-2015-05-02-13.16.13.png?w=662&amp;ssl=1 662w, https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2015\/05\/Capture-de\u0301cran-2015-05-02-13.16.13.png?resize=300%2C189&amp;ssl=1 300w\" sizes=\"(max-width: 662px) 100vw, 662px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><a href=\"http:\/\/myesmart.ch\/\" target=\"_blank\">eSMART<\/a> s\u2019est vue couronn\u00e9e de l\u2019\u00e9dition 2015 du Prix Strategis, organis\u00e9 chaque ann\u00e9e par l\u2019espace <a href=\"http:\/\/www.hec-espace-entreprise.ch\/\" target=\"_blank\">HEC Espace Entreprise<\/a>, ainsi devan\u00e7ant <a href=\"http:\/\/www.bcomp.ch\/\" target=\"_blank\">Bcomp<\/a> et <a href=\"http:\/\/www.insphero.com\/\" target=\"_blank\">Insphero<\/a> qui occupent les 2<sup>\u00e8me<\/sup> et 3<sup>\u00e8me<\/sup> places du concours.<\/p>\n<p><strong>Des modules sans c\u00e2ble<\/strong><\/p>\n<p>Le concept est simple, facile \u00e0 utiliser et innovant \u00e0 la fois. Il suffit d\u2019implanter des modules \u00e0 l\u2019arri\u00e8re des prises de courants ou des interrupteurs, sans installer de c\u00e2bles dans les murs, qui utilisent les r\u00e9seaux existants. Et ce n\u2019est pas tout. C\u2019est un syst\u00e8me qui combine \u00e9galement interphone, surveillance des consommations \u00e9nerg\u00e9tiques, r\u00e9glage domotique et diverses informations, le tout r\u00e9glable \u00e0 distance par une app pour smartphone et tablette.<\/p>\n<p>C\u2019est une solution peu co\u00fbteuse, facile \u00e0 utiliser et qui a d\u00e9j\u00e0 convaincu de nombreux utilisateurs. Ce syst\u00e8me est n\u00e9 en 2009, mais les premiers boitiers n\u2019ont \u00e9t\u00e9 disponibles qu\u2019en 2012. Plus de 400 logements, pour la plupart situ\u00e9s en r\u00e9gion l\u00e9manique, sont d\u00e9j\u00e0 s\u00e9duits par ce produit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 28 avril dernier, le jury du Prix Strategis a d\u00e9cern\u00e9 un prix de CHF 50&#8217;000 \u00e0 la startup eSMART pour f\u00e9liciter son ing\u00e9nieux syst\u00e8me de domotique.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"aioseo_notices":[],"views":1685,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7y0qY-WE","_links":{"self":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/3636"}],"collection":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/comments?post=3636"}],"version-history":[{"count":3,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/3636\/revisions"}],"predecessor-version":[{"id":3644,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/3636\/revisions\/3644"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/media?parent=3636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/categories?post=3636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/tags?post=3636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}