{"id":10900,"date":"2022-11-07T07:15:00","date_gmt":"2022-11-07T06:15:00","guid":{"rendered":"https:\/\/blog.startups.ch\/fr\/?p=10900"},"modified":"2022-11-05T13:33:04","modified_gmt":"2022-11-05T12:33:04","slug":"fondation-avec-apport-en-nature","status":"publish","type":"post","link":"https:\/\/blog.startups.ch\/fr\/2022\/11\/07\/fondation-avec-apport-en-nature\/","title":{"rendered":"Quels sont les apports les plus fr\u00e9quents lors d&#8217;une fondation avec apport en nature ?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Pour une fondation par apport en nature, il est en principe possible d&#8217;utiliser tous les biens qui peuvent \u00eatre inscrits \u00e0 l&#8217;actif selon les principes de la comptabilit\u00e9 r\u00e9guli\u00e8re. D\u00e9couvrez ici quelles conditions concr\u00e8tes doivent \u00eatre remplies et quels sont les exemples typiques d&#8217;un apport en nature.<\/h2>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"666\" src=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2022\/11\/Bildschirmfoto-2022-11-05-um-13.32.22.png?resize=1200%2C666&#038;ssl=1\" alt=\"\" class=\"wp-image-10905\" srcset=\"https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2022\/11\/Bildschirmfoto-2022-11-05-um-13.32.22.png?resize=1200%2C666&amp;ssl=1 1200w, https:\/\/i0.wp.com\/blog.startups.ch\/fr\/wp-content\/uploads\/2022\/11\/Bildschirmfoto-2022-11-05-um-13.32.22.png?w=1344&amp;ssl=1 1344w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-recalc-dims=\"1\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conditions pour un apport en nature<\/strong><\/h3>\n\n\n\n<p>En principe, tout ce qui a une valeur marchande peut \u00eatre \u00eatre consid\u00e9r\u00e9 comme apport en nature. Les choses apport\u00e9es doivent donc apporter une utilit\u00e9 \u00e9conomique effective \u00e0 la soci\u00e9t\u00e9. Concr\u00e8tement, quatre conditions peuvent \u00eatre d\u00e9finies :<\/p>\n\n\n\n<p><strong>Possibilit\u00e9 d&#8217;\u00e9valuation ou de comptabilisation<\/strong> : Seuls entrent en ligne de compte les biens qui ont une certaine valeur et qui peuvent \u00eatre inscrits \u00e0 l&#8217;actif du bilan.<\/p>\n\n\n\n<p><strong>La possibilit\u00e9 d&#8217;acquisition de droits par la soci\u00e9t\u00e9 doit exister (transf\u00e9rabilit\u00e9) :<\/strong> Pour que la soci\u00e9t\u00e9 puisse acqu\u00e9rir un apport en nature, l&#8217;objet correspondant doit pouvoir \u00eatre transf\u00e9r\u00e9 dans le patrimoine de la soci\u00e9t\u00e9 lors de la constitution ou de l&#8217;augmentation de capital. Par cons\u00e9quent, aucun obstacle juridique ne doit s&#8217;opposer au transfert (comme par exemple une interdiction contractuelle de cession).<\/p>\n\n\n\n<p><strong>Disponibilit\u00e9 (ou droit d&#8217;inscription inconditionnel, par exemple au registre foncier)<\/strong> : La soci\u00e9t\u00e9 doit pouvoir disposer imm\u00e9diatement et sans condition du bien en question apr\u00e8s son inscription au registre du commerce.<\/p>\n\n\n\n<p><strong>Possibilit\u00e9 de r\u00e9alisation<\/strong> : le bien doit pouvoir \u00eatre transf\u00e9r\u00e9 par la soci\u00e9t\u00e9 \u00e0 des tiers. Ce point est particuli\u00e8rement important en cas de dissolution de la soci\u00e9t\u00e9. Le bien apport\u00e9 doit \u00eatre r\u00e9alisable afin de pouvoir servir de substrat de responsabilit\u00e9 aux cr\u00e9anciers de la soci\u00e9t\u00e9. La possibilit\u00e9 de r\u00e9alisation pr\u00e9suppose l&#8217;existence d&#8217;un march\u00e9 au moins limit\u00e9. En outre, le transfert de la valeur patrimoniale doit \u00eatre juridiquement admissible et juridiquement stable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Exemples typiques d&#8217;apports en nature<\/strong><\/h3>\n\n\n\n<p>Bien que les exemples \u00ab&nbsp;typiques&nbsp;\u00bb varient d\u2019un secteur \u00e0 l\u2019autre,&nbsp; les actifs suivants font souvent partie d&#8217;un apport en nature :<\/p>\n\n\n\n<ul><li>Mobilier (tables de bureau, chaises, papeterie, etc.)<\/li><li>Informatique (ordinateurs, \u00e9crans, etc.)<\/li><li>V\u00e9hicules (voitures, camionnettes, camions, etc.)<\/li><li>Stocks de marchandises ou de mat\u00e9riel (p. ex. mati\u00e8res premi\u00e8res, pi\u00e8ces de rechange, etc.)<\/li><li>Outils (p. ex. cl\u00e9s \u00e0 vis, pinces, etc. mais aussi outils \u00e9lectriques tels que marteaux perforateurs, ponceuses, etc. ou appareils de mesure)<\/li><li>Licences de logiciels<\/li><\/ul>\n\n\n\n<p>Se lancer en tant que <a href=\"https:\/\/bit.ly\/3fccZuN\">Mompreneur<\/a> <br>Se lancer en tant que <a href=\"https:\/\/bit.ly\/2UFV71N\">Dadpreneur<\/a> <br>Se lancer en tant <a href=\"https:\/\/bit.ly\/35JYyLi\">Seniorpreneur<\/a> <br>Se lancer en tant que <a href=\"https:\/\/bit.ly\/2UEHhwy\">Youngpreneur<\/a><br><a href=\"https:\/\/www.startups.ch\/fr\/home\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bb STARTUPS.CH<\/a>&nbsp;<a href=\"https:\/\/www.startups.ch\/fr\/services\/creation-entreprise\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bb Cr\u00e9er une entreprise<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour une fondation par apport en nature, il est en principe possible d&#8217;utiliser tous les biens qui peuvent \u00eatre inscrits \u00e0 l&#8217;actif selon les principes de la comptabilit\u00e9 r\u00e9guli\u00e8re. D\u00e9couvrez ici quelles conditions concr\u00e8tes doivent \u00eatre remplies et quels sont les exemples typiques d&#8217;un apport en nature.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"aioseo_notices":[],"views":463,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7y0qY-2PO","_links":{"self":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/10900"}],"collection":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/comments?post=10900"}],"version-history":[{"count":2,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/10900\/revisions"}],"predecessor-version":[{"id":10906,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/posts\/10900\/revisions\/10906"}],"wp:attachment":[{"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/media?parent=10900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/categories?post=10900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.startups.ch\/fr\/wp-json\/wp\/v2\/tags?post=10900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}